{"id":12325,"date":"2017-02-17T18:52:00","date_gmt":"2017-02-17T18:52:00","guid":{"rendered":"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/"},"modified":"2017-02-17T18:52:00","modified_gmt":"2017-02-17T18:52:00","slug":"9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr","status":"publish","type":"post","link":"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/","title":{"rendered":"Fire Emblem Heroes Update: Vier neue Helden und mehr"},"content":{"rendered":"<p>Das neueste Mobile-Game aus dem Hause Nintendo, welches <a href=\"http:\/\/www.lightsteelblue-llama-768814.hostingersite.comn\/n\/9138-fire-emblem-heroes-startet-fuer-android-und-ios\" target=\"_blank\">Anfang Februar auf den Markt<\/a> kam, erhielt ein Update mit dem Event Familienbande. Das Event, in dem zahlreiche Nebenquests in drei Missionen erledigt werden k\u00c3\u00b6nnen, beinhaltet auch vier neue Helden. Ephraim und Erika aus The Sacred Storm und Seliph und Julia aus Genealogy of the Holy War sind alle vier 5-Sterne-Helden. Das Beschw\u00c3\u00b6rungsevent endet am 27. Februar, die Helden allerdings bleiben dauerhaft im Spiel. W\u00c3\u00a4hrend des Events bestehen allerdings erh\u00c3\u00b6hte Chancen, diese Helden zu bekommen. Weitere Bestandteile des Familienbande-Beschw\u00c3\u00b6rungsevents sind die Halbierung der Energiekosten im \u00c3\u0153bungsturm und das kostenlose Ausr\u00c3\u00bcsten von Fertigkeiten. Auch diese sollen angeblich auch nach dem Eventende vorerst so in Fire Emblem Heroes erhalten bleiben. Zudem wurde angek\u00c3\u00bcndigt, dass die vier Helden ab Anfang M\u00c3\u00a4rz auch Erfahrungspunkte geben sollen. In einem Trailer zum Event und den neuen Charakteren werden die F\u00c3\u00a4higkeiten der vier etwas vorgestellt. <iframe loading=\"lazy\" allowfullscreen=\"\" frameborder=\"0\" height=\"438\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/F7e1ZscCUSg\" width=\"100%\"><\/iframe> Fire Emblem Heroes startete nicht ganz so erfolgreich wie Super Mario Run oder Pok\u00c3\u00a9mon GO, aber generierte laut Nintendo doch auch schon Ums\u00c3\u00a4tze von \u00c3\u00bcber f\u00c3\u00bcnf Millionen US-Dollar. Es wurde in den ersten 48 Stunden ca. 48 Millionen mal heruntergeladen. Fire Emblems Heroes basiert auf dem Free-2-Play-Prinzip und kann kostenlos in den Stores geladen werden. Geld soll durch In-App-K\u00c3\u00a4ufe in Nintendos Kassen gesp\u00c3\u00bclt werden. Bis zum 14. M\u00c3\u00a4rz l\u00c3\u00a4uft noch der App-Ver\u00c3\u00b6ffentlichungsbonus, durch den es zum Beispiel ab dem 20. Februar ab 8 Uhr f\u00c3\u00bcr 24 Stunden Belohnungen im \u00c3\u0153bungsturm geben wird. In Fire Emblem Heroes k\u00c3\u00a4mpft ihr mit euren Helden gegen die Invasoren den Emblanischen Imperiums und baut euren Charakter auf. Wir haben f\u00c3\u00bcr Fire Emblems Heroes auch einen kleinen <a href=\"http:\/\/www.lightsteelblue-llama-768814.hostingersite.comn\/n\/9173-fire-emblem-heroes-tipps-und-tricks-zum-neuen-nintendo-spiel\" target=\"_blank\">Guide mit den wichtigsten Tipps zum Charakteraufbau, der Heldenbeschw\u00c3\u00b6rung und nat\u00c3\u00bcrlich dem Kampf<\/a> f\u00c3\u00bcr euch geschrieben.<\/p><div class=\"newss-content\" id=\"newss-411839396\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-7733425960004873\" \ndata-ad-slot=\"2582020599\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div class=\"newss-article-1\" id=\"newss-1994638929\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Homepage2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7733425960004873\"\r\n     data-ad-slot=\"2582020599\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mit dem neuesten Update zum Beschw\u00c3\u00b6rungsevent gibt es neben den Familenbande-Event-bezogenen Nebenquests auch vier neue Helden, die&#8230; Mehr auf Newsslash.com!<\/p>\n","protected":false},"author":7,"featured_media":21974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-12325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fire Emblem Heroes Update: Vier neue Helden und mehr - Newsslash<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fire Emblem Heroes Update: Vier neue Helden und mehr - Newsslash\" \/>\n<meta property=\"og:description\" content=\"Mit dem neuesten Update zum Beschw\u00c3\u00b6rungsevent gibt es neben den Familenbande-Event-bezogenen Nebenquests auch vier neue Helden, die... Mehr auf Newsslash.com!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/\" \/>\n<meta property=\"og:site_name\" content=\"Newsslash\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-17T18:52:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniela H\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniela H\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/\"},\"author\":{\"name\":\"Daniela H\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11\"},\"headline\":\"Fire Emblem Heroes Update: Vier neue Helden und mehr\",\"datePublished\":\"2017-02-17T18:52:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/\"},\"wordCount\":309,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/\",\"url\":\"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/\",\"name\":\"Fire Emblem Heroes Update: Vier neue Helden und mehr - Newsslash\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"datePublished\":\"2017-02-17T18:52:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/#primaryimage\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"width\":1280,\"height\":854},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsslash.com\/n\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fire Emblem Heroes Update: Vier neue Helden und mehr\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsslash.com\/n\/#website\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"name\":\"Newsslash\",\"description\":\"Trending News on Movies, Series, OTT, Gaming\",\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsslash.com\/n\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsslash.com\/n\/#organization\",\"name\":\"Newsslash\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"width\":512,\"height\":512,\"caption\":\"Newsslash\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11\",\"name\":\"Daniela H\",\"sameAs\":[\"https:\/\/newsslash.com\"],\"url\":\"https:\/\/newsslash.com\/n\/author\/daniela_h\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fire Emblem Heroes Update: Vier neue Helden und mehr - Newsslash","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Fire Emblem Heroes Update: Vier neue Helden und mehr - Newsslash","og_description":"Mit dem neuesten Update zum Beschw\u00c3\u00b6rungsevent gibt es neben den Familenbande-Event-bezogenen Nebenquests auch vier neue Helden, die... Mehr auf Newsslash.com!","og_url":"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/","og_site_name":"Newsslash","article_published_time":"2017-02-17T18:52:00+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","type":"image\/jpeg"}],"author":"Daniela H","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Daniela H","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/#article","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/"},"author":{"name":"Daniela H","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11"},"headline":"Fire Emblem Heroes Update: Vier neue Helden und mehr","datePublished":"2017-02-17T18:52:00+00:00","mainEntityOfPage":{"@id":"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/"},"wordCount":309,"commentCount":0,"publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"image":{"@id":"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/","url":"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/","name":"Fire Emblem Heroes Update: Vier neue Helden und mehr - Newsslash","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/#primaryimage"},"image":{"@id":"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","datePublished":"2017-02-17T18:52:00+00:00","breadcrumb":{"@id":"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/#primaryimage","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","width":1280,"height":854},{"@type":"BreadcrumbList","@id":"https:\/\/newsslash.com\/n\/9236-fire-emblem-heroes-update-vier-neue-helden-und-mehr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsslash.com\/n\/"},{"@type":"ListItem","position":2,"name":"Fire Emblem Heroes Update: Vier neue Helden und mehr"}]},{"@type":"WebSite","@id":"https:\/\/newsslash.com\/n\/#website","url":"https:\/\/newsslash.com\/n\/","name":"Newsslash","description":"Trending News on Movies, Series, OTT, Gaming","publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsslash.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/newsslash.com\/n\/#organization","name":"Newsslash","url":"https:\/\/newsslash.com\/n\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","width":512,"height":512,"caption":"Newsslash"},"image":{"@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11","name":"Daniela H","sameAs":["https:\/\/newsslash.com"],"url":"https:\/\/newsslash.com\/n\/author\/daniela_h\/"}]}},"_links":{"self":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/12325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/comments?post=12325"}],"version-history":[{"count":0,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/12325\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media\/21974"}],"wp:attachment":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media?parent=12325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}