{"id":12753,"date":"2017-04-10T11:15:00","date_gmt":"2017-04-10T11:15:00","guid":{"rendered":"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/"},"modified":"2017-04-10T11:15:00","modified_gmt":"2017-04-10T11:15:00","slug":"9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video","status":"publish","type":"post","link":"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/","title":{"rendered":"Wann kommt Greys Anatomy Staffel 13 auf Amazon Prime Video?"},"content":{"rendered":"<p>Man kann sich kaum vorstellen, dass vor mehr als zehn Jahren Meredith und ihre Kollegen noch gemeinsam ihre Ausbildung am Seattle Grey Hospital gemacht haben. Am 27. M\u00c3\u00a4rz 2005 startete Greys Anatomy auf ABC. Die deutschsprachige Version wurde seit dem 9. M\u00c3\u00a4rz 2006 auf ORF eins und sp\u00c3\u00a4ter auf Sixx und ProSieben ausgestrahlt. Mittlerweile sind mehr als 250 Episoden von den ABC Studios produziert worden und ein Ende der Serie ist noch nicht in Sicht. Aber wann kommt Staffel 13 von Grey\u00e2\u20ac\u2122s Anatomy auf Amazon Prime Video? Auf ProSieben startete Staffel 13 bereits am 29. M\u00c3\u00a4rz dieses Jahres. Wann Grey\u00e2\u20ac\u2122s Anatomy Staffel 13 auf Amazon Prime Video zum Streamen bereit steht ist noch nicht bekannt. Jedoch k\u00c3\u00b6nnte es sein, dass die Serie Ende des Jahres oder Anfang n\u00c3\u00a4chsten Jahres auf der VoD-Plattform landet. Bis dahin k\u00c3\u00b6nnt ihr euch entweder die ersten 12 Staffeln nochmal anschauen oder euch die ersten Folgen von Staffel 13 \u00c3\u00bcber <a href=\"https:\/\/www.amazon.de\/gp\/video\/detail\/B06XR2MGBR?ref_=UTF8&amp;tag=newsslash-21\" target=\"_blank\">Amazon<\/a> holen. <ins data-ad-client=\"ca-pub-3647021458695789\" data-ad-format=\"link\" data-ad-slot=\"7996975644\" style=\"display:block\"><\/ins> Im Mittelpunkt der Serie steht Meredith Grey (Ellen Pompeo), die zu Beginn der Serie noch gemeinsam mit vier weiteren Assistenz\u00c3\u00a4rzten &#8211; Christina Yang (Sandra Oh), Isobel \u00e2\u20ac\u0153Izzy\u00e2\u20ac\u009d Stevens (Katherine Heigl), Sch\u00c3\u00b6nling George O\u00e2\u20ac\u2122Malley (T. R. Knight) und Alexander Karev (Justin Chambers) &#8211; ihre Ausbildung in Chirurgie am Seattle Grace Hospital absolviert. Seitdem hat sie sich in den gutaussehenden und charmanten Oberarzt Dr. Derek Shepherd (Patrick Dempsey) verliebt mit dem sie sp\u00c3\u00a4ter eine Beziehung eingeht und zusammenzieht. Eigentlich dreht sich alles in Grey\u00e2\u20ac\u2122s Anatomy um die Beziehungen der Assistenz\u00c3\u00a4rzte untereinander und zu ihren Stationsober\u00c3\u00a4rzten. Schlie\u00c3\u0178lich sind Meredith und Derek nicht die einzigen, die eine Beziehung versuchen, die jedoch schon bald scheitert. Auch Dr. Miranda Bailey (Chandra Wilson) und die taffe Calliope Torres (Sara Ramirez) haben immer wieder mit Liebeskummer und Konkurrenten zu k\u00c3\u00a4mpfen. Auch die Freundschaft zwischen Christina und Meredith scheint unter keinem guten Stern zu stehen. Die Ideen zur Serie stammen allesamt von Shonda Rhimes, die sich bereits \u00c3\u00bcber zahlreiche Auszeichnungen freuen durfte. Unter anderem wurde die Serie mit dem Emmy und dem Golden Globe ausgezeichnet. Bleibt zu hoffen, dass noch viele weitere Staffeln von Grey\u00e2\u20ac\u2122s Anatomy produziert werden.<\/p><div class=\"newss-content\" id=\"newss-456322346\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-7733425960004873\" \ndata-ad-slot=\"2582020599\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div class=\"newss-article-1\" id=\"newss-3815576365\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Homepage2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7733425960004873\"\r\n     data-ad-slot=\"2582020599\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Endlich geht die Krankenhaus-Odyssee weiter. Auf ProSieben startete am 29. M\u00c3\u00a4rz die 13. Staffel von Greys Anatomy und es ist noch&#8230; Mehr auf Newsslash.com!<\/p>\n","protected":false},"author":5,"featured_media":21974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-12753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Wann kommt Greys Anatomy Staffel 13 auf Amazon Prime Video? - Newsslash<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wann kommt Greys Anatomy Staffel 13 auf Amazon Prime Video? - Newsslash\" \/>\n<meta property=\"og:description\" content=\"Endlich geht die Krankenhaus-Odyssee weiter. Auf ProSieben startete am 29. M\u00c3\u00a4rz die 13. Staffel von Greys Anatomy und es ist noch... Mehr auf Newsslash.com!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/\" \/>\n<meta property=\"og:site_name\" content=\"Newsslash\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-10T11:15:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ramona R\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ramona R\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/\"},\"author\":{\"name\":\"Ramona R\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/709185a45f398d6a15210745a10251e2\"},\"headline\":\"Wann kommt Greys Anatomy Staffel 13 auf Amazon Prime Video?\",\"datePublished\":\"2017-04-10T11:15:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/\"},\"wordCount\":362,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/\",\"url\":\"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/\",\"name\":\"Wann kommt Greys Anatomy Staffel 13 auf Amazon Prime Video? - Newsslash\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"datePublished\":\"2017-04-10T11:15:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/#primaryimage\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"width\":1280,\"height\":854},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsslash.com\/n\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wann kommt Greys Anatomy Staffel 13 auf Amazon Prime Video?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsslash.com\/n\/#website\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"name\":\"Newsslash\",\"description\":\"Trending News on Movies, Series, OTT, Gaming\",\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsslash.com\/n\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsslash.com\/n\/#organization\",\"name\":\"Newsslash\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"width\":512,\"height\":512,\"caption\":\"Newsslash\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/709185a45f398d6a15210745a10251e2\",\"name\":\"Ramona R\",\"sameAs\":[\"https:\/\/newsslash.com\"],\"url\":\"https:\/\/newsslash.com\/n\/author\/ramona_r\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wann kommt Greys Anatomy Staffel 13 auf Amazon Prime Video? - Newsslash","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Wann kommt Greys Anatomy Staffel 13 auf Amazon Prime Video? - Newsslash","og_description":"Endlich geht die Krankenhaus-Odyssee weiter. Auf ProSieben startete am 29. M\u00c3\u00a4rz die 13. Staffel von Greys Anatomy und es ist noch... Mehr auf Newsslash.com!","og_url":"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/","og_site_name":"Newsslash","article_published_time":"2017-04-10T11:15:00+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","type":"image\/jpeg"}],"author":"Ramona R","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ramona R","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/#article","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/"},"author":{"name":"Ramona R","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/709185a45f398d6a15210745a10251e2"},"headline":"Wann kommt Greys Anatomy Staffel 13 auf Amazon Prime Video?","datePublished":"2017-04-10T11:15:00+00:00","mainEntityOfPage":{"@id":"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/"},"wordCount":362,"commentCount":0,"publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"image":{"@id":"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/","url":"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/","name":"Wann kommt Greys Anatomy Staffel 13 auf Amazon Prime Video? - Newsslash","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/#primaryimage"},"image":{"@id":"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","datePublished":"2017-04-10T11:15:00+00:00","breadcrumb":{"@id":"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/#primaryimage","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","width":1280,"height":854},{"@type":"BreadcrumbList","@id":"https:\/\/newsslash.com\/n\/9575-wann-kommt-greys-anatomy-staffel-13-auf-amazon-prime-video\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsslash.com\/n\/"},{"@type":"ListItem","position":2,"name":"Wann kommt Greys Anatomy Staffel 13 auf Amazon Prime Video?"}]},{"@type":"WebSite","@id":"https:\/\/newsslash.com\/n\/#website","url":"https:\/\/newsslash.com\/n\/","name":"Newsslash","description":"Trending News on Movies, Series, OTT, Gaming","publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsslash.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/newsslash.com\/n\/#organization","name":"Newsslash","url":"https:\/\/newsslash.com\/n\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","width":512,"height":512,"caption":"Newsslash"},"image":{"@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/709185a45f398d6a15210745a10251e2","name":"Ramona R","sameAs":["https:\/\/newsslash.com"],"url":"https:\/\/newsslash.com\/n\/author\/ramona_r\/"}]}},"_links":{"self":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/12753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/comments?post=12753"}],"version-history":[{"count":0,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/12753\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media\/21974"}],"wp:attachment":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media?parent=12753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}