{"id":12919,"date":"2017-04-20T21:20:00","date_gmt":"2017-04-20T21:20:00","guid":{"rendered":"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/"},"modified":"2017-04-20T21:20:00","modified_gmt":"2017-04-20T21:20:00","slug":"9695-facebook-messenger-so-sieht-die-zukunft-aus","status":"publish","type":"post","link":"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/","title":{"rendered":"Facebook Messenger: So sieht die Zukunft aus!"},"content":{"rendered":"<p>Der Messenger von Facebook soll viel mehr sein als nur die M\u00c3\u00b6glichkeit, mit anderen zu chatten. Vice President David Marcus von Facebook sieht den Messenger mehr als \u00e2\u20ac\u0153soziales Wohnzimmer, in dem die Nutzer herumh\u00c3\u00a4ngen, chatten, spielen, Dinge kaufen oder sich helfen lassen k\u00c3\u00b6nnen\u00e2\u20ac\u009d. Au\u00c3\u0178erdem soll er zwei Altbekannte wieder verbinden: Das Telefonbuch und die Gelben Seiten. Zus\u00c3\u00a4tzlich zu den schon vorhanden Funktionen, mit denen man zum Beispiel via Chat mit Unternehmen in Kontakt treten kann, sollen User nun Bots leichter finden k\u00c3\u00b6nnen und diese auch in Gruppen-Chats einbinden, um zum Beispiel gemeinsam Spotify zu h\u00c3\u00b6ren. Auf der Entwicklerkonferenz F8 hat Facebook nun Version 2 der Messenger Platform f\u00c3\u00bcr alle Messenger-Entwickler freigegeben und neue Funktionen vorgestellt, die den Namen soziale Plattform weiter best\u00c3\u00a4tigen. So gibt es den neuen Discover-Tab, mit dem man Bots direkt im Homescreen des Messengers finden kann. Dieser ist derzeit nur f\u00c3\u00bcr ausgew\u00c3\u00a4hlte Nutzer in den USA verf\u00c3\u00bcgbar. Desweiteren gibt es Neuigkeiten zum Assistenten M, Bots in Gruppen und eine Alternative zum QR-Code scannen. <b>Bots in Gruppen-Chats<\/b> Durch die \u00e2\u20ac\u0153Chat-Extensions\u00e2\u20ac\u009d wird es nun m\u00c3\u00b6glich, dass mehrere Nutzer gleichzeitig mit einem Bot chatten k\u00c3\u00b6nnen. Es ist auch m\u00c3\u00b6glich, \u00c3\u00bcber diese Funktion einen Bot einem Gruppenchat hinzuzuf\u00c3\u00bcgen. Zum Start der Funktion soll auf jeden Fall Spotify verf\u00c3\u00bcgbar sein, so dass man als Beispiel derzeit auch nur anf\u00c3\u00bchren kann, dass es dann m\u00c3\u00b6glich wird, gemeinsam Songs zu h\u00c3\u00b6ren. Welche M\u00c3\u00b6glichkeiten dadurch noch hinzukommen werden, bleibt abzuwarten. <b>Messenger und Scannen<\/b> Das Scannen von QR-Codes ist anscheinend nicht ganz so der Hype geworden wie mal anfangs gedacht hat. David Marcus meint, es w\u00c3\u00a4re \u00e2\u20ac\u0153not a thing\u00e2\u20ac\u009d. K\u00c3\u00bcnftig soll der Facebook Messenger hier eine Alternative bieten. Wenn man die QR-Codes direkt mit der Messenger-App scannt, soll man sofort zu einem passenden Bot weitergeleitet werden. <b>Assistent M macht noch mehr Vorschl\u00c3\u00a4ge<\/b> Der virtuelle Assistent des Facebook Messengers M macht schon so einige Vorschl\u00c3\u00a4ge in Unterhaltungen oder erinnert an Termine wie Treffen mit Freunden. Nun soll er noch mehr k\u00c3\u00b6nnen und zum Beispiel einen Lieferdienst vorschlagen, wenn, wie wohl so oft, sich das Thema in der Konversation ums Essen dreht. Wieviel mehr die k\u00c3\u00bcnstliche Intelligenz noch aus den Konversationen interpretieren und in Vorschl\u00c3\u00a4ge f\u00c3\u00bcr Reallife-Aktionen umwandeln kann, ist noch nicht bekannt. Die erweiterten intelligenten Funktionen des Assistenten sind derzeit nur in den USA nutzbar. Facebook ist also weiter auf dem Weg, seine klassische Finanzierung durch personalisierte Werbung auf den Messenger, die Gruppen-Konversationen auszuweiten und bietet mehr und mehr Funktionen f\u00c3\u00bcr Unternehmen, an dieser Stelle mit (potentiellen) Kunden in Verbindung zu treten, Hilfe anzubieten, seine Produkte zu verkaufen oder die M\u00c3\u00b6glichkeit zu geben, diese Produkte im Messenger zu nutzen wie im Falle von Spotify. Wir sind gespannt wie diese Funktionen dann auch in Good Old Europe angenommen werden.<\/p><div class=\"newss-content\" id=\"newss-1626917748\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-7733425960004873\" \ndata-ad-slot=\"2582020599\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div class=\"newss-article-1\" id=\"newss-3380164837\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Homepage2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7733425960004873\"\r\n     data-ad-slot=\"2582020599\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Schon im vergangenen Jahr erweiterte Facebook seinen Messenger zu einer richtigen Anwendungsplattform. Nun geht gibt es weitere&#8230; Mehr auf Newsslash.com!<\/p>\n","protected":false},"author":7,"featured_media":21974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-12919","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Facebook Messenger: So sieht die Zukunft aus! - Newsslash<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Facebook Messenger: So sieht die Zukunft aus! - Newsslash\" \/>\n<meta property=\"og:description\" content=\"Schon im vergangenen Jahr erweiterte Facebook seinen Messenger zu einer richtigen Anwendungsplattform. Nun geht gibt es weitere... Mehr auf Newsslash.com!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/\" \/>\n<meta property=\"og:site_name\" content=\"Newsslash\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-20T21:20:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniela H\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniela H\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/\"},\"author\":{\"name\":\"Daniela H\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11\"},\"headline\":\"Facebook Messenger: So sieht die Zukunft aus!\",\"datePublished\":\"2017-04-20T21:20:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/\"},\"wordCount\":488,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/\",\"url\":\"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/\",\"name\":\"Facebook Messenger: So sieht die Zukunft aus! - Newsslash\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"datePublished\":\"2017-04-20T21:20:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/#primaryimage\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"width\":1280,\"height\":854},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsslash.com\/n\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Facebook Messenger: So sieht die Zukunft aus!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsslash.com\/n\/#website\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"name\":\"Newsslash\",\"description\":\"Trending News on Movies, Series, OTT, Gaming\",\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsslash.com\/n\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsslash.com\/n\/#organization\",\"name\":\"Newsslash\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"width\":512,\"height\":512,\"caption\":\"Newsslash\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11\",\"name\":\"Daniela H\",\"sameAs\":[\"https:\/\/newsslash.com\"],\"url\":\"https:\/\/newsslash.com\/n\/author\/daniela_h\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Facebook Messenger: So sieht die Zukunft aus! - Newsslash","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Facebook Messenger: So sieht die Zukunft aus! - Newsslash","og_description":"Schon im vergangenen Jahr erweiterte Facebook seinen Messenger zu einer richtigen Anwendungsplattform. Nun geht gibt es weitere... Mehr auf Newsslash.com!","og_url":"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/","og_site_name":"Newsslash","article_published_time":"2017-04-20T21:20:00+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","type":"image\/jpeg"}],"author":"Daniela H","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Daniela H","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/#article","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/"},"author":{"name":"Daniela H","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11"},"headline":"Facebook Messenger: So sieht die Zukunft aus!","datePublished":"2017-04-20T21:20:00+00:00","mainEntityOfPage":{"@id":"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/"},"wordCount":488,"commentCount":0,"publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"image":{"@id":"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/","url":"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/","name":"Facebook Messenger: So sieht die Zukunft aus! - Newsslash","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/#primaryimage"},"image":{"@id":"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","datePublished":"2017-04-20T21:20:00+00:00","breadcrumb":{"@id":"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/#primaryimage","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","width":1280,"height":854},{"@type":"BreadcrumbList","@id":"https:\/\/newsslash.com\/n\/9695-facebook-messenger-so-sieht-die-zukunft-aus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsslash.com\/n\/"},{"@type":"ListItem","position":2,"name":"Facebook Messenger: So sieht die Zukunft aus!"}]},{"@type":"WebSite","@id":"https:\/\/newsslash.com\/n\/#website","url":"https:\/\/newsslash.com\/n\/","name":"Newsslash","description":"Trending News on Movies, Series, OTT, Gaming","publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsslash.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/newsslash.com\/n\/#organization","name":"Newsslash","url":"https:\/\/newsslash.com\/n\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","width":512,"height":512,"caption":"Newsslash"},"image":{"@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11","name":"Daniela H","sameAs":["https:\/\/newsslash.com"],"url":"https:\/\/newsslash.com\/n\/author\/daniela_h\/"}]}},"_links":{"self":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/12919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/comments?post=12919"}],"version-history":[{"count":0,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/12919\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media\/21974"}],"wp:attachment":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media?parent=12919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}