{"id":13023,"date":"2017-05-05T16:24:00","date_gmt":"2017-05-05T16:24:00","guid":{"rendered":"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/"},"modified":"2017-05-05T16:24:00","modified_gmt":"2017-05-05T16:24:00","slug":"9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene","status":"publish","type":"post","link":"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/","title":{"rendered":"Bates Motel ist geschlossen &#8211; AandE verl\u00c3\u00a4sst die Seriens&#8230;"},"content":{"rendered":"<p>Das Bates Motel hat seine T\u00c3\u00bcren geschlossen und l\u00c3\u00a4utet damit auch eine Neuausrichtung des Kabelsenders A&amp;E ein. \u00c3\u0153ber zehn Jahre lang hat der Sender drehbuchbasierte Eigenproduktionen in Serie auf die Bildschirme gebracht. Nun ist damit Schluss. Der Sender m\u00c3\u00b6chte sich nun mehr auf unscripted reality konzentrieren. Verschiedenste Serienformate hat A&amp;E ausprobiert. Keines lief wirklich richtig gut. Der richtige Kracher war bei allen Versuchen nicht dabei. Longmine und The Glades brachten es auf nur drei Staffeln direkt beim TV-Sender. Longmine, eine Serie rund um das wilde Cowboyleben erfuhr dank Netflix noch ein verl\u00c3\u00a4ngertes Leben. Sehr kurzlebige Serien, die fast den Namen nicht verdient haben, wie Those Who Kill, Damien oder Les Revenants waren weitere Versuche, in der Produktion von Serien Fu\u00c3\u0178 zu fassen. Bates Motel war nun die letzte Serie, die das Unternehmen noch an den Start geschickt hat. Andere Formate wie Aftermath, 60 Days In, Leah Remini: Scientology oder die Polizeidokumentation Live PD bringen aktuell wesentlich bessere Einschaltquoten. Der amerikanische Sender will sich daher laut Deadline in der n\u00c3\u00a4chsten Zeit auf Reality-Formate konzentrieren.<\/p><div class=\"newss-content\" id=\"newss-3119718812\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-7733425960004873\" \ndata-ad-slot=\"2582020599\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div class=\"newss-article-1\" id=\"newss-2535977633\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Homepage2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7733425960004873\"\r\n     data-ad-slot=\"2582020599\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die Serie Bates Motel hat die letzte Folge hinter sich und auch der produzierende Sender AandE schliesst eine T\u00c3\u00bcr. Mit dem Ende von&#8230; Mehr auf Newsslash.com!<\/p>\n","protected":false},"author":7,"featured_media":21974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-13023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bates Motel ist geschlossen - AandE verl\u00c3\u00a4sst die Seriens... - Newsslash<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bates Motel ist geschlossen - AandE verl\u00c3\u00a4sst die Seriens... - Newsslash\" \/>\n<meta property=\"og:description\" content=\"Die Serie Bates Motel hat die letzte Folge hinter sich und auch der produzierende Sender AandE schliesst eine T\u00c3\u00bcr. Mit dem Ende von... Mehr auf Newsslash.com!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/\" \/>\n<meta property=\"og:site_name\" content=\"Newsslash\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-05T16:24:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniela H\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniela H\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/\"},\"author\":{\"name\":\"Daniela H\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11\"},\"headline\":\"Bates Motel ist geschlossen &#8211; AandE verl\u00c3\u00a4sst die Seriens&#8230;\",\"datePublished\":\"2017-05-05T16:24:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/\"},\"wordCount\":191,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/\",\"url\":\"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/\",\"name\":\"Bates Motel ist geschlossen - AandE verl\u00c3\u00a4sst die Seriens... - Newsslash\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"datePublished\":\"2017-05-05T16:24:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/#primaryimage\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"width\":1280,\"height\":854},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsslash.com\/n\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bates Motel ist geschlossen &#8211; AandE verl\u00c3\u00a4sst die Seriens&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsslash.com\/n\/#website\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"name\":\"Newsslash\",\"description\":\"Trending News on Movies, Series, OTT, Gaming\",\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsslash.com\/n\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsslash.com\/n\/#organization\",\"name\":\"Newsslash\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"width\":512,\"height\":512,\"caption\":\"Newsslash\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11\",\"name\":\"Daniela H\",\"sameAs\":[\"https:\/\/newsslash.com\"],\"url\":\"https:\/\/newsslash.com\/n\/author\/daniela_h\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bates Motel ist geschlossen - AandE verl\u00c3\u00a4sst die Seriens... - Newsslash","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Bates Motel ist geschlossen - AandE verl\u00c3\u00a4sst die Seriens... - Newsslash","og_description":"Die Serie Bates Motel hat die letzte Folge hinter sich und auch der produzierende Sender AandE schliesst eine T\u00c3\u00bcr. Mit dem Ende von... Mehr auf Newsslash.com!","og_url":"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/","og_site_name":"Newsslash","article_published_time":"2017-05-05T16:24:00+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","type":"image\/jpeg"}],"author":"Daniela H","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Daniela H","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/#article","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/"},"author":{"name":"Daniela H","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11"},"headline":"Bates Motel ist geschlossen &#8211; AandE verl\u00c3\u00a4sst die Seriens&#8230;","datePublished":"2017-05-05T16:24:00+00:00","mainEntityOfPage":{"@id":"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/"},"wordCount":191,"commentCount":0,"publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"image":{"@id":"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/","url":"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/","name":"Bates Motel ist geschlossen - AandE verl\u00c3\u00a4sst die Seriens... - Newsslash","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/#primaryimage"},"image":{"@id":"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","datePublished":"2017-05-05T16:24:00+00:00","breadcrumb":{"@id":"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/#primaryimage","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","width":1280,"height":854},{"@type":"BreadcrumbList","@id":"https:\/\/newsslash.com\/n\/9787-bates-motel-ist-geschlossen-a-und-e-verlaesst-die-serienschiene\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsslash.com\/n\/"},{"@type":"ListItem","position":2,"name":"Bates Motel ist geschlossen &#8211; AandE verl\u00c3\u00a4sst die Seriens&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/newsslash.com\/n\/#website","url":"https:\/\/newsslash.com\/n\/","name":"Newsslash","description":"Trending News on Movies, Series, OTT, Gaming","publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsslash.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/newsslash.com\/n\/#organization","name":"Newsslash","url":"https:\/\/newsslash.com\/n\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","width":512,"height":512,"caption":"Newsslash"},"image":{"@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11","name":"Daniela H","sameAs":["https:\/\/newsslash.com"],"url":"https:\/\/newsslash.com\/n\/author\/daniela_h\/"}]}},"_links":{"self":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/13023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/comments?post=13023"}],"version-history":[{"count":0,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/13023\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media\/21974"}],"wp:attachment":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media?parent=13023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}