{"id":13225,"date":"2017-05-30T11:42:00","date_gmt":"2017-05-30T11:42:00","guid":{"rendered":"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/"},"modified":"2017-05-30T11:42:00","modified_gmt":"2017-05-30T11:42:00","slug":"9941-netflix-juni-2017-neuerscheinungen-im-ueberbick","status":"publish","type":"post","link":"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/","title":{"rendered":"Netflix Juni 2017 Neuerscheinungen im \u00c3\u0153berblick"},"content":{"rendered":"<p>Ein neuer Monat steht vor der T\u00c3\u00bcr und nat\u00c3\u00bcrlich hat der Streaming-Anbieter Netflix auch im Juni jede Menge neue Filme und Serien in petto. Unten findet ihr eine ausf\u00c3\u00bchrliche Liste mit den Netflix Juni 2017 Neuerscheinungen. Wollt ihr zudem t\u00c3\u00a4glich \u00c3\u00bcber die neuesten Netflix Serien und Filme informiert bleiben, dann schaut in unseren <a href=\"http:\/\/www.lightsteelblue-llama-768814.hostingersite.comn\/netflix-neuerscheinungen\" target=\"_blank\">Netflix Neuerscheinungen<\/a> vorbei. Dort findet ihr einen t\u00c3\u00a4glich aktualisierten \u00c3\u0153berblick zu den neusten Inhalten auf Netflix. Euch erwarten im neuen Monat nicht nur neue Folgen zu Orange Is The New Black und Flaked sondern Netflix wird auch den neuen Originalfim OKJA ver\u00c3\u00b6ffentlichen. Dabei k\u00c3\u00b6nnt ihr einer besonderen Freundschaft zwischen Mensch und Tier folgen. Doch der Streaming-Dienst l\u00c3\u00a4sst auch altbekannte Filme wie die Indiana Jones-Reihe mit allen vier Kinofilmen ab dem 01.06.2017 wieder aufleben. <b>Tipp:<\/b> Like unsere Facebook-Seite um die neuesten Netflix-News zu erhalten! <\/p><div class=\"newss-content\" id=\"newss-3887619543\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-7733425960004873\" \ndata-ad-slot=\"2582020599\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div class=\"newss-article-1\" id=\"newss-2054717912\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Homepage2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7733425960004873\"\r\n     data-ad-slot=\"2582020599\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div>\n<div data-action=\"like\" data-href=\"http:\/\/www.facebook.com\/Newsslash\" data-layout=\"button_count\" data-send=\"false\" data-width=\"90\"><\/div>\n<p> <b>Netflix Serien im Juni 2017<\/b> 02.06.2017 \u00e2\u20ac\u201c Flaked Staffel 2 06.06.2017 \u00e2\u20ac\u201c Shadowhunters Staffel 2B (w\u00c3\u00b6chentlich) 07.06.2017 \u00e2\u20ac\u201c Reigen Staffel 3 09.06.2017 \u00e2\u20ac\u201c Orange Is The New Black Staffel 5 09.06.2017 \u00e2\u20ac\u201c My Only Love Song Staffel 1 15.06.2017 \u00e2\u20ac\u201c You Me Her Staffel 2 16.06.2017 \u00e2\u20ac\u201c The Ranch Teil 3 16.06.2017 \u00e2\u20ac\u201c El Chapo Staffel 1 23.06.2017 \u00e2\u20ac\u201c Glow Staffel 1 30.06.2017 \u00e2\u20ac\u201c Gypsy Staffel 1 <b>Netflix Filme im Juni 2017<\/b> 01.06.2017 \u00e2\u20ac\u201c Gringo: The Dangerous Life Of John Mcafee 01.06.2017 \u00e2\u20ac\u201c Burlesque 01.06.2017 \u00e2\u20ac\u201c Der letzte K\u00c3\u00b6nig von Schottland \u00e2\u20ac\u201c In den F\u00c3\u00a4ngen der macht 01.06.2017 \u00e2\u20ac\u201c Searching For Sugar Man 01.06.2017 \u00e2\u20ac\u201c Prestige: Die Meister der Magie 01.06.2017 \u00e2\u20ac\u201c Barbershop 2 \u00e2\u20ac\u201c Krass Frisiert 01.06.2017 \u00e2\u20ac\u201c Old Dogs 01.06.2017 \u00e2\u20ac\u201c The Birdcage: Ein Paradies f\u00c3\u00bcr schrille V\u00c3\u00b6gel 01.06.2017 \u00e2\u20ac\u201c The Last Samurai 01.06.2017 \u00e2\u20ac\u201c Indiana Jones und das K\u00c3\u00b6nigreich des Kristallsch\u00c3\u00a4dels 01.06.2017 \u00e2\u20ac\u201c Indiana Jones und der J\u00c3\u00a4ger des Verlorenen Schatzes 01.06.2017 \u00e2\u20ac\u201c Indiana Jones und der Tempel des Todes 01.06.2017 \u00e2\u20ac\u201c Indiana Jones und der letzte Kreuzzug 02.06.2017 \u00e2\u20ac\u201c Lucid Dream 02.06.2017 \u00e2\u20ac\u201c Saving Banksy 03.06.2017 \u00e2\u20ac\u201c Headshot 05.06.2017 \u00e2\u20ac\u201c Das Schwergewicht 07.06.2017 \u00e2\u20ac\u201c Disturbing The Peace 07.06.2017 \u00e2\u20ac\u201c Top Gun 09.06.2017 \u00e2\u20ac\u201c Shimmer Lake 13.06.2017 \u00e2\u20ac\u201c Oh, Hello On Broadway (Comedy) 15.06.2017 \u00e2\u20ac\u201c Date Night: Gangster f\u00c3\u00bcr eine Nacht 16.06.2017 \u00e2\u20ac\u201c Counterpunch (Doku) 16.06.2017 \u00e2\u20ac\u201c What The Health (Doku) 20.06.2017 \u00e2\u20ac\u201c Rory Scovel Tries Stand-Up For The First Time (Comedy) 23.06.2017 \u00e2\u20ac\u201c Nobody Speak: Die Fallstricke der Pressefreiheit (Doku) 27.06.2017 \u00e2\u20ac\u201c Chris D\u00e2\u20ac\u2122Elia: Man on Fire (Comedy) 28.06.2017 \u00e2\u20ac\u201c OKJA 28.06.2017 \u00e2\u20ac\u201c Jackass 3.5 der Film <b>Netflix Kinderserien im Juni 2017<\/b> 01.06.2017 \u00e2\u20ac\u201c Die Eisk\u00c3\u00b6nigin 01.06.2017 \u00e2\u20ac\u201c Der K\u00c3\u00b6nig der L\u00c3\u00b6wen 01.06.2017 \u00e2\u20ac\u201c Der Gl\u00c3\u00b6ckner von Notre Dame 16.06.2017 \u00e2\u20ac\u201c World of Winx 23.06.2017 \u00e2\u20ac\u201c Free Rein 30.06.2017 \u00e2\u20ac\u201c Little Witch Academia Und hier gibt es noch mehr Neuerscheinungen, welche Netflix in den vergangenen Tagen ver\u00c3\u00b6ffentlichte: <a href=\"http:\/\/www.lightsteelblue-llama-768814.hostingersite.comn\/netflix-neuerscheinungen\" target=\"_blank\">Die Netflix Neuerscheinungen im \u00c3\u0153berblick<\/a>. Wir berichten \u00c3\u00bcbrigens t\u00c3\u00a4glich \u00c3\u00bcber die neuesten Filme, Serien und News rund um Netflix!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Netflix hat die ersten Informationen zu den Mai 2017 Neuerscheinungen ver\u00c3\u00b6ffentlicht. Wir pr\u00c3\u00a4sentieren die komplette Liste. Mit&#8230; Mehr auf Newsslash.com!<\/p>\n","protected":false},"author":4,"featured_media":13211,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-13225","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Netflix Juni 2017 Neuerscheinungen im \u00c3\u0153berblick - Newsslash<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Netflix Juni 2017 Neuerscheinungen im \u00c3\u0153berblick - Newsslash\" \/>\n<meta property=\"og:description\" content=\"Netflix hat die ersten Informationen zu den Mai 2017 Neuerscheinungen ver\u00c3\u00b6ffentlicht. Wir pr\u00c3\u00a4sentieren die komplette Liste. Mit... Mehr auf Newsslash.com!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/\" \/>\n<meta property=\"og:site_name\" content=\"Newsslash\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-30T11:42:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_9941.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"617\" \/>\n\t<meta property=\"og:image:height\" content=\"349\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christina B\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christina B\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/\"},\"author\":{\"name\":\"Christina B\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/d091f5c44e30328c391ba075ee1b88d3\"},\"headline\":\"Netflix Juni 2017 Neuerscheinungen im \u00c3\u0153berblick\",\"datePublished\":\"2017-05-30T11:42:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/\"},\"wordCount\":387,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_9941.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/\",\"url\":\"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/\",\"name\":\"Netflix Juni 2017 Neuerscheinungen im \u00c3\u0153berblick - Newsslash\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_9941.jpg\",\"datePublished\":\"2017-05-30T11:42:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/#primaryimage\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_9941.jpg\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_9941.jpg\",\"width\":617,\"height\":349},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsslash.com\/n\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Netflix Juni 2017 Neuerscheinungen im \u00c3\u0153berblick\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsslash.com\/n\/#website\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"name\":\"Newsslash\",\"description\":\"Trending News on Movies, Series, OTT, Gaming\",\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsslash.com\/n\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsslash.com\/n\/#organization\",\"name\":\"Newsslash\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"width\":512,\"height\":512,\"caption\":\"Newsslash\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/d091f5c44e30328c391ba075ee1b88d3\",\"name\":\"Christina B\",\"sameAs\":[\"https:\/\/newsslash.com\"],\"url\":\"https:\/\/newsslash.com\/n\/author\/christina_b\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Netflix Juni 2017 Neuerscheinungen im \u00c3\u0153berblick - Newsslash","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Netflix Juni 2017 Neuerscheinungen im \u00c3\u0153berblick - Newsslash","og_description":"Netflix hat die ersten Informationen zu den Mai 2017 Neuerscheinungen ver\u00c3\u00b6ffentlicht. Wir pr\u00c3\u00a4sentieren die komplette Liste. Mit... Mehr auf Newsslash.com!","og_url":"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/","og_site_name":"Newsslash","article_published_time":"2017-05-30T11:42:00+00:00","og_image":[{"width":617,"height":349,"url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_9941.jpg","type":"image\/jpeg"}],"author":"Christina B","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Christina B","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/#article","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/"},"author":{"name":"Christina B","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/d091f5c44e30328c391ba075ee1b88d3"},"headline":"Netflix Juni 2017 Neuerscheinungen im \u00c3\u0153berblick","datePublished":"2017-05-30T11:42:00+00:00","mainEntityOfPage":{"@id":"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/"},"wordCount":387,"commentCount":0,"publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"image":{"@id":"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_9941.jpg","articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/","url":"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/","name":"Netflix Juni 2017 Neuerscheinungen im \u00c3\u0153berblick - Newsslash","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/#primaryimage"},"image":{"@id":"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_9941.jpg","datePublished":"2017-05-30T11:42:00+00:00","breadcrumb":{"@id":"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/#primaryimage","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_9941.jpg","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_9941.jpg","width":617,"height":349},{"@type":"BreadcrumbList","@id":"https:\/\/newsslash.com\/n\/9941-netflix-juni-2017-neuerscheinungen-im-ueberbick\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsslash.com\/n\/"},{"@type":"ListItem","position":2,"name":"Netflix Juni 2017 Neuerscheinungen im \u00c3\u0153berblick"}]},{"@type":"WebSite","@id":"https:\/\/newsslash.com\/n\/#website","url":"https:\/\/newsslash.com\/n\/","name":"Newsslash","description":"Trending News on Movies, Series, OTT, Gaming","publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsslash.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/newsslash.com\/n\/#organization","name":"Newsslash","url":"https:\/\/newsslash.com\/n\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","width":512,"height":512,"caption":"Newsslash"},"image":{"@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/d091f5c44e30328c391ba075ee1b88d3","name":"Christina B","sameAs":["https:\/\/newsslash.com"],"url":"https:\/\/newsslash.com\/n\/author\/christina_b\/"}]}},"_links":{"self":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/13225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/comments?post=13225"}],"version-history":[{"count":0,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/13225\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media\/13211"}],"wp:attachment":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media?parent=13225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}