{"id":13294,"date":"2017-06-07T14:48:18","date_gmt":"2017-06-07T14:48:18","guid":{"rendered":"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/"},"modified":"2017-06-07T14:48:18","modified_gmt":"2017-06-07T14:48:18","slug":"9994-apple-stellt-voellig-neuen-app-store-vor","status":"publish","type":"post","link":"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/","title":{"rendered":"Apple stellt v\u00c3\u00b6llig neuen App Store vor"},"content":{"rendered":"<p>Apple hat den v\u00c3\u00b6llig neuen App Store vorgestellt, von Grund auf gestaltet, um das Entdecken von Apps und Spielen einfacher zu machen als jemals zuvor. Der wundersch\u00c3\u00b6n \u00c3\u00bcberarbeitete App Store ist vollgepackt mit originellen Geschichten und redaktionellen Beitr\u00c3\u00a4gen, die t\u00c3\u00a4glich in einem neuen Heute-Tab sowie in neuen Spiele- und Apps-Tabs aktualisiert werden. Spannende Geschichten, ausf\u00c3\u00bchrliche Interviews, hilfreiche Tipps und Sammlungen mit unverzichtbaren Apps und Spielen werden die besondere Perspektive von Apple veranschaulichen und zielen darauf ab Kunden t\u00c3\u00a4glich zu informieren, ihnen zu helfen und sie zu inspirieren. App Store-Kunden haben bis dato mehr als 180 Milliarden Apps heruntergeladen und Apple hat seit Start des App Store im Jahr 2008 \u00c3\u00bcber 70 Milliarden US-Dollar an Entwickler ausbezahlt, was ihn zum weltweit dynamischsten Marktplatz f\u00c3\u00bcr Software macht. &#8220;Gemeinsam mit unserer unglaublichen Entwicklergemeinschaft haben wir den App Store zur besten App-Plattform der Welt gemacht, die von mehr als 500 Millionen einzelner Kunden jede Woche besucht wird&#8221;, sagt Philip Schiller, Senior Vice President Worldwide Marketing von Apple. &#8220;Wir ber\u00c3\u00bccksichtigen nun alles, was wir in den vergangenen neun Jahren App Store gelernt haben und setzen es in einem atemberaubenden neuen Design um. Jedes Element des neuen App Store ist reichhaltiger, sch\u00c3\u00b6ner und ansprechender.&#8221; Der v\u00c3\u00b6llig neue App Store wird Teil von iOS 11 sein. Die Developer Preview von iOS 11 ist ab heute f\u00c3\u00bcr Mitglieder des iOS Developer Program auf developer.apple.com verf\u00c3\u00bcgbar und ein \u00c3\u00b6ffentliches Beta-Programm wird f\u00c3\u00bcr iOS-Nutzer im Laufe dieses Monats auf beta.apple.com verf\u00c3\u00bcgbar sein.<\/p><div class=\"newss-content\" id=\"newss-3086566735\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-7733425960004873\" \ndata-ad-slot=\"2582020599\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div class=\"newss-article-1\" id=\"newss-602576266\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Homepage2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7733425960004873\"\r\n     data-ad-slot=\"2582020599\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Als Teil vom neuen Betriebssystem iOS 11 hat Apple den neuen Apple App Store pr\u00c3\u00a4sentiert. Dieser neue App Store wurde komplett&#8230; Mehr auf Newsslash.com!<\/p>\n","protected":false},"author":2,"featured_media":13278,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-13294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Apple stellt v\u00c3\u00b6llig neuen App Store vor - Newsslash<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apple stellt v\u00c3\u00b6llig neuen App Store vor - Newsslash\" \/>\n<meta property=\"og:description\" content=\"Als Teil vom neuen Betriebssystem iOS 11 hat Apple den neuen Apple App Store pr\u00c3\u00a4sentiert. Dieser neue App Store wurde komplett... Mehr auf Newsslash.com!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/\" \/>\n<meta property=\"og:site_name\" content=\"Newsslash\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-07T14:48:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_9994.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"617\" \/>\n\t<meta property=\"og:image:height\" content=\"349\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viktor Pulz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viktor Pulz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/\"},\"author\":{\"name\":\"Viktor Pulz\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/9710bfacfd5579c2b307825ddaad6c46\"},\"headline\":\"Apple stellt v\u00c3\u00b6llig neuen App Store vor\",\"datePublished\":\"2017-06-07T14:48:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/\"},\"wordCount\":262,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_9994.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/\",\"url\":\"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/\",\"name\":\"Apple stellt v\u00c3\u00b6llig neuen App Store vor - Newsslash\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_9994.jpg\",\"datePublished\":\"2017-06-07T14:48:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/#primaryimage\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_9994.jpg\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_9994.jpg\",\"width\":617,\"height\":349},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsslash.com\/n\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apple stellt v\u00c3\u00b6llig neuen App Store vor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsslash.com\/n\/#website\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"name\":\"Newsslash\",\"description\":\"Trending News on Movies, Series, OTT, Gaming\",\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsslash.com\/n\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsslash.com\/n\/#organization\",\"name\":\"Newsslash\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"width\":512,\"height\":512,\"caption\":\"Newsslash\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/9710bfacfd5579c2b307825ddaad6c46\",\"name\":\"Viktor Pulz\",\"sameAs\":[\"https:\/\/newsslash.com\"],\"url\":\"https:\/\/newsslash.com\/n\/author\/viktor_pulz\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apple stellt v\u00c3\u00b6llig neuen App Store vor - Newsslash","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Apple stellt v\u00c3\u00b6llig neuen App Store vor - Newsslash","og_description":"Als Teil vom neuen Betriebssystem iOS 11 hat Apple den neuen Apple App Store pr\u00c3\u00a4sentiert. Dieser neue App Store wurde komplett... Mehr auf Newsslash.com!","og_url":"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/","og_site_name":"Newsslash","article_published_time":"2017-06-07T14:48:18+00:00","og_image":[{"width":617,"height":349,"url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_9994.jpg","type":"image\/jpeg"}],"author":"Viktor Pulz","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Viktor Pulz","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/#article","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/"},"author":{"name":"Viktor Pulz","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/9710bfacfd5579c2b307825ddaad6c46"},"headline":"Apple stellt v\u00c3\u00b6llig neuen App Store vor","datePublished":"2017-06-07T14:48:18+00:00","mainEntityOfPage":{"@id":"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/"},"wordCount":262,"commentCount":0,"publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"image":{"@id":"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_9994.jpg","articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/","url":"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/","name":"Apple stellt v\u00c3\u00b6llig neuen App Store vor - Newsslash","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/#primaryimage"},"image":{"@id":"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_9994.jpg","datePublished":"2017-06-07T14:48:18+00:00","breadcrumb":{"@id":"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/#primaryimage","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_9994.jpg","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_9994.jpg","width":617,"height":349},{"@type":"BreadcrumbList","@id":"https:\/\/newsslash.com\/n\/9994-apple-stellt-voellig-neuen-app-store-vor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsslash.com\/n\/"},{"@type":"ListItem","position":2,"name":"Apple stellt v\u00c3\u00b6llig neuen App Store vor"}]},{"@type":"WebSite","@id":"https:\/\/newsslash.com\/n\/#website","url":"https:\/\/newsslash.com\/n\/","name":"Newsslash","description":"Trending News on Movies, Series, OTT, Gaming","publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsslash.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/newsslash.com\/n\/#organization","name":"Newsslash","url":"https:\/\/newsslash.com\/n\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","width":512,"height":512,"caption":"Newsslash"},"image":{"@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/9710bfacfd5579c2b307825ddaad6c46","name":"Viktor Pulz","sameAs":["https:\/\/newsslash.com"],"url":"https:\/\/newsslash.com\/n\/author\/viktor_pulz\/"}]}},"_links":{"self":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/13294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/comments?post=13294"}],"version-history":[{"count":0,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/13294\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media\/13278"}],"wp:attachment":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media?parent=13294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}