{"id":13426,"date":"2017-06-27T11:52:00","date_gmt":"2017-06-27T11:52:00","guid":{"rendered":"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/"},"modified":"2017-06-27T11:52:00","modified_gmt":"2017-06-27T11:52:00","slug":"10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag","status":"publish","type":"post","link":"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/","title":{"rendered":"Amazon gibt Dokuserie hinter den Kulissen der Tour de Fra&#8230;"},"content":{"rendered":"<p>Amazon gibt einem neuen Amazon Original gr\u00c3\u00bcnes Licht: Die noch unbetitelte Abenteuer-Dokuserie setzt die Athleten der 104. Tour de France in den Fokus, und das Essen, das sie am Leben h\u00c3\u00a4lt. Die Serie schaut Hannah Grant, bei Profi-Radfahrern bekannt als K\u00c3\u00b6nigin des \u00e2\u20ac\u017ePerformance Cooking\u00e2\u20ac\u0153, und ihrer Crew \u00c3\u00bcber die Schultern, wie sie gesunde und nahrhafte Mahlzeiten f\u00c3\u00bcr die neun Fahrer des Teams Orica-Scott zubereiten \u00e2\u20ac\u201c w\u00c3\u00a4hrend des ganzen Rennens, das 23 Tage dauert und 21 Etappen \u00c3\u00bcber 3540 Kilometer umfasst. Die Serie wurde inspiriert von Hannah Grants Buch The Grand Tour Cookbook und er\u00c3\u00b6ffnet einen Blick hinter die Kulissen des Rennens im Rennen. Sie zeigt, was es bedeutet, die Standards der Sterne-K\u00c3\u00bcche auf einen Nenner mit den Bed\u00c3\u00bcrfnissen professioneller Athleten zu bringen. W\u00c3\u00a4hrend der Tour de France wechseln das Rennteam und Hannah Grants gesamte Crew t\u00c3\u00a4glich den Standort \u00e2\u20ac\u201c angefangen in D\u00c3\u00bcsseldorf bis hin zur Zielgeraden auf der Champs-\u00c3\u2030lys\u00c3\u00a9es in Paris. Das Amazon Original gibt einen noch nie dagewesenen Einblick in eines der anspruchsvollsten Sportevents der Welt, das j\u00c3\u00a4hrlich von Millionen von Zuschauern verfolgt wird, und stellt eine Seite des Rennens und der Teams vor, die noch kaum einer kennt. \u00e2\u20ac\u017eHannah Grant ist eine Weltklasse-K\u00c3\u00b6chin, die ihre Karriere der Ern\u00c3\u00a4hrung von einigen der fantastischsten Sportlern der Welt gewidmet hat. Unter unm\u00c3\u00b6glichen Bedingungen kreiert sie Gourmet-Mahlzeiten, die gleichzeitig nahrhaft und leistungssteigernd sind\u00e2\u20ac\u0153, so Conrad Riggs, Head of Unscripted, Amazon Originals. \u00e2\u20ac\u017eWir freuen uns sehr, Amazon Prime-Mitgliedern das organisierte Chaos hinter einer der renommiertesten und intensivsten Sportveranstaltungen der Welt zu zeigen, bei der sich Hannah Grant und ihr Team voll entfalten k\u00c3\u00b6nnen.\u00e2\u20ac\u0153 \u00e2\u20ac\u017eEs ist ein seltenes Geschenk, einen starken, neuen Blickwinkel auf ein Event zu finden, das so gro\u00c3\u0178 ist wie die Tour de France. Die beispiellose Kombination aus Sport, Reisen und Essen ist so ein Blickwinkel\u00e2\u20ac\u0153, so Executive Producer Christof Bove. \u00e2\u20ac\u017eUnser Ziel ist es, dem Publikum von Amazon weltweit einen ungehinderten Zugang zu den Mechanismen und der Leidenschaft dieses Sportevents zu geben. Hannah Grant ist Teil einer neuen Generation von K\u00c3\u00b6chen. Mit ihrer Einstellung und ihrem K\u00c3\u00b6nnen ist sie dieser Welt voller Spitzenleistungen gewachsen. Um die Tour de France zu \u00c3\u00bcberleben, musst du einfach der Beste der Besten sein.\u00e2\u20ac\u009d<\/p><div class=\"newss-content\" id=\"newss-132061818\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-7733425960004873\" \ndata-ad-slot=\"2582020599\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div class=\"newss-article-1\" id=\"newss-2153557357\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Homepage2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7733425960004873\"\r\n     data-ad-slot=\"2582020599\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Amazon hat eine neue Abenteuer-Dokuserie in Auftrag gegeben. Konkret wird bei dieser die 104. Tour de France im Fokus stehen. Neue&#8230; Mehr auf Newsslash.com!<\/p>\n","protected":false},"author":2,"featured_media":21974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-13426","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Amazon gibt Dokuserie hinter den Kulissen der Tour de Fra... - Newsslash<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amazon gibt Dokuserie hinter den Kulissen der Tour de Fra... - Newsslash\" \/>\n<meta property=\"og:description\" content=\"Amazon hat eine neue Abenteuer-Dokuserie in Auftrag gegeben. Konkret wird bei dieser die 104. Tour de France im Fokus stehen. Neue... Mehr auf Newsslash.com!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/\" \/>\n<meta property=\"og:site_name\" content=\"Newsslash\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-27T11:52:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viktor Pulz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viktor Pulz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/\"},\"author\":{\"name\":\"Viktor Pulz\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/9710bfacfd5579c2b307825ddaad6c46\"},\"headline\":\"Amazon gibt Dokuserie hinter den Kulissen der Tour de Fra&#8230;\",\"datePublished\":\"2017-06-27T11:52:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/\"},\"wordCount\":383,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/\",\"url\":\"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/\",\"name\":\"Amazon gibt Dokuserie hinter den Kulissen der Tour de Fra... - Newsslash\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"datePublished\":\"2017-06-27T11:52:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/#primaryimage\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"width\":1280,\"height\":854},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsslash.com\/n\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Amazon gibt Dokuserie hinter den Kulissen der Tour de Fra&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsslash.com\/n\/#website\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"name\":\"Newsslash\",\"description\":\"Trending News on Movies, Series, OTT, Gaming\",\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsslash.com\/n\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsslash.com\/n\/#organization\",\"name\":\"Newsslash\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"width\":512,\"height\":512,\"caption\":\"Newsslash\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/9710bfacfd5579c2b307825ddaad6c46\",\"name\":\"Viktor Pulz\",\"sameAs\":[\"https:\/\/newsslash.com\"],\"url\":\"https:\/\/newsslash.com\/n\/author\/viktor_pulz\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Amazon gibt Dokuserie hinter den Kulissen der Tour de Fra... - Newsslash","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Amazon gibt Dokuserie hinter den Kulissen der Tour de Fra... - Newsslash","og_description":"Amazon hat eine neue Abenteuer-Dokuserie in Auftrag gegeben. Konkret wird bei dieser die 104. Tour de France im Fokus stehen. Neue... Mehr auf Newsslash.com!","og_url":"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/","og_site_name":"Newsslash","article_published_time":"2017-06-27T11:52:00+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","type":"image\/jpeg"}],"author":"Viktor Pulz","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Viktor Pulz","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/#article","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/"},"author":{"name":"Viktor Pulz","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/9710bfacfd5579c2b307825ddaad6c46"},"headline":"Amazon gibt Dokuserie hinter den Kulissen der Tour de Fra&#8230;","datePublished":"2017-06-27T11:52:00+00:00","mainEntityOfPage":{"@id":"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/"},"wordCount":383,"commentCount":0,"publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"image":{"@id":"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/","url":"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/","name":"Amazon gibt Dokuserie hinter den Kulissen der Tour de Fra... - Newsslash","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/#primaryimage"},"image":{"@id":"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","datePublished":"2017-06-27T11:52:00+00:00","breadcrumb":{"@id":"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/#primaryimage","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","width":1280,"height":854},{"@type":"BreadcrumbList","@id":"https:\/\/newsslash.com\/n\/10108-amazon-gibt-dokuserie-hinter-den-kulissen-der-rour-de-france-in-auftrag\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsslash.com\/n\/"},{"@type":"ListItem","position":2,"name":"Amazon gibt Dokuserie hinter den Kulissen der Tour de Fra&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/newsslash.com\/n\/#website","url":"https:\/\/newsslash.com\/n\/","name":"Newsslash","description":"Trending News on Movies, Series, OTT, Gaming","publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsslash.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/newsslash.com\/n\/#organization","name":"Newsslash","url":"https:\/\/newsslash.com\/n\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","width":512,"height":512,"caption":"Newsslash"},"image":{"@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/9710bfacfd5579c2b307825ddaad6c46","name":"Viktor Pulz","sameAs":["https:\/\/newsslash.com"],"url":"https:\/\/newsslash.com\/n\/author\/viktor_pulz\/"}]}},"_links":{"self":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/13426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/comments?post=13426"}],"version-history":[{"count":0,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/13426\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media\/21974"}],"wp:attachment":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media?parent=13426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}