{"id":13657,"date":"2017-07-26T16:11:10","date_gmt":"2017-07-26T16:11:10","guid":{"rendered":"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/"},"modified":"2017-07-26T16:11:10","modified_gmt":"2017-07-26T16:11:10","slug":"10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress","status":"publish","type":"post","link":"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/","title":{"rendered":"Vom MoMA New York bis Artenschutz: \u00c3\u00bcber 70 Speaker beim &#8230;"},"content":{"rendered":"<p>Mit hochkar\u00c3\u00a4tigen Referenten und einem vielf\u00c3\u00a4ltigen Themenmix lockt der diesj\u00c3\u00a4hrige gamescom congress am 23. August 2017 nach K\u00c3\u00b6ln. Die Veranstaltung wird erstmalig mit einer Wahlkampf-Arena er\u00c3\u00b6ffnet. Es treten an: Dr. Peter Tauber (CDU), Hubertus Heil (SPD), Matthias H\u00c3\u00b6hn (Die Linke), Michael Kellner (B\u00c3\u00bcndnis 90\/Die Gr\u00c3\u00bcnen) und Nicola Beer (FDP). Die Top-Wahlk\u00c3\u00a4mpfer nehmen Stellung zur Relevanz von Spielen und den Herausforderungen in der Digitalpolitik des Landes. Anschlie\u00c3\u0178end referieren \u00c3\u00bcber 70 Speaker aus dem In- und Ausland in Keynotes, Talks und Panels zu den f\u00c3\u00bcnf Dachthemen Wissen, Business, Gamification, Recht und Leben. Der gamescom congress ist Europas f\u00c3\u00bchrende Konferenz f\u00c3\u00bcr Trends und die Potenziale von Computerspielen weit \u00c3\u00bcber die Games-Branche hinaus und die erste Adresse f\u00c3\u00bcr Wirtschaftsvertreter aller Branchen, Kulturschaffende, P\u00c3\u00a4dagogen, Politiker und Wissenschaftler. Henriette Reker, Oberb\u00c3\u00bcrgermeisterin der Stadt K\u00c3\u00b6ln: \u00e2\u20ac\u017eIn den vergangenen Jahren hat die Branche der Computer- und Videospiele eine eindrucksvolle Entwicklung erlebt \u00e2\u20ac\u201c vor allem als Antriebsmotor f\u00c3\u00bcr Innovationen in allen Bereichen. Der Medienstandort K\u00c3\u00b6ln f\u00c3\u00b6rdert die kreativen Impulse von Games, allen voran die Zukunftsthemen Gamification sowie Virtual und Augmented Reality. Ein besonderer Schwerpunkt liegt auf der F\u00c3\u00b6rderung von Start-ups, so zum Beispiel im neu gegr\u00c3\u00bcndeten Games Inkubator des Cologne Game Lab. Die gamescom und neue Branchentreffs machen K\u00c3\u00b6ln ganzj\u00c3\u00a4hrig zu einem Netzwerk von internationaler Bedeutung.\u00e2\u20ac\u0153 Unter dem diesj\u00c3\u00a4hrigen Kongress-Motto \u00e2\u20ac\u017eMehr als Spiele\u00e2\u20ac\u0153 referieren unter anderem Cornelia Holsten von der Kommission f\u00c3\u00bcr Jugendmedienschutz (KJM), Henriette L\u00c3\u00b6wisch von der Deutschen Journalistenschule (DJS), der russische Schriftsteller Dmitry Glukhovsky (Metro-Reihe), Dr. Torsten Wingenter (Lufthansa), Gustav K\u00c3\u00a4ll (Universal Music), Gregor Gr\u00c3\u00bcndgens (Vodafone), Alexander Knetig (ARTE), Dr. Tobias Schmid von der Landesanstalt f\u00c3\u00bcr Medien Nordrhein-Westfalen (LfM), Thomas Jarzombek MdB (CDU\/CSU Fraktion), Heike Raab (Landesvertretung Rheinland-Pfalz) und Rachelle Vallon von der New Yorker Schule Quest to Learn. So vielf\u00c3\u00a4ltig die Referenten sind, so spannend und aktuell ist auch das Themenspektrum, das sich auf die f\u00c3\u00bcnf Dachthemen \u00e2\u20ac\u017eMehr als Wissen: Games bilden\u00e2\u20ac\u0153, \u00e2\u20ac\u017eMehr als Business: Games lohnen\u00e2\u20ac\u0153, \u00e2\u20ac\u017eMehr als Gamification: Games verwandeln\u00e2\u20ac\u0153, \u00e2\u20ac\u017eMehr als Recht: Games fundieren\u00e2\u20ac\u0153 und \u00e2\u20ac\u017eMehr als Leben: Games faszinieren\u00e2\u20ac\u0153 verteilt. So bieten die Panels, Talks und Diskussionsrunden \u00c3\u00bcber die Integration von Games in Schulen bis hin zum Artenschutz, wie Edward Partridge vom WWF berichtet, ausreichend Impulse, die weit \u00c3\u00bcber die Computerspiel-Branche hinausgehen. Auf einer zus\u00c3\u00a4tzlichen \u00e2\u20ac\u017eOpen Stage\u00e2\u20ac\u0153 erwarten die Teilnehmer weitere spannende Vortr\u00c3\u00a4ge \u00e2\u20ac\u201c von Games und Infotainment beim TV-Sender Arte bis zu Entwicklungen der Gamesbranche in Kanada.<\/p><div class=\"newss-content\" id=\"newss-1098998\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-7733425960004873\" \ndata-ad-slot=\"2582020599\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div class=\"newss-article-1\" id=\"newss-914943724\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Homepage2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7733425960004873\"\r\n     data-ad-slot=\"2582020599\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Der Gamescom Congress 2017 bietet ein breites Themen-Spektrum in f\u00c3\u00bcnf Dachthemen \u00e2\u20ac\u201c von Games-P\u00c3\u00a4dagogik in New York bis Recht bei&#8230; Mehr auf Newsslash.com!<\/p>\n","protected":false},"author":2,"featured_media":21974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-13657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vom MoMA New York bis Artenschutz: \u00c3\u00bcber 70 Speaker beim ... - Newsslash<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vom MoMA New York bis Artenschutz: \u00c3\u00bcber 70 Speaker beim ... - Newsslash\" \/>\n<meta property=\"og:description\" content=\"Der Gamescom Congress 2017 bietet ein breites Themen-Spektrum in f\u00c3\u00bcnf Dachthemen \u00e2\u20ac\u201c von Games-P\u00c3\u00a4dagogik in New York bis Recht bei... Mehr auf Newsslash.com!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/\" \/>\n<meta property=\"og:site_name\" content=\"Newsslash\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-26T16:11:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viktor Pulz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viktor Pulz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/\"},\"author\":{\"name\":\"Viktor Pulz\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/9710bfacfd5579c2b307825ddaad6c46\"},\"headline\":\"Vom MoMA New York bis Artenschutz: \u00c3\u00bcber 70 Speaker beim &#8230;\",\"datePublished\":\"2017-07-26T16:11:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/\"},\"wordCount\":425,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/\",\"url\":\"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/\",\"name\":\"Vom MoMA New York bis Artenschutz: \u00c3\u00bcber 70 Speaker beim ... - Newsslash\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"datePublished\":\"2017-07-26T16:11:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/#primaryimage\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"width\":1280,\"height\":854},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsslash.com\/n\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vom MoMA New York bis Artenschutz: \u00c3\u00bcber 70 Speaker beim &#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsslash.com\/n\/#website\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"name\":\"Newsslash\",\"description\":\"Trending News on Movies, Series, OTT, Gaming\",\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsslash.com\/n\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsslash.com\/n\/#organization\",\"name\":\"Newsslash\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"width\":512,\"height\":512,\"caption\":\"Newsslash\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/9710bfacfd5579c2b307825ddaad6c46\",\"name\":\"Viktor Pulz\",\"sameAs\":[\"https:\/\/newsslash.com\"],\"url\":\"https:\/\/newsslash.com\/n\/author\/viktor_pulz\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vom MoMA New York bis Artenschutz: \u00c3\u00bcber 70 Speaker beim ... - Newsslash","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Vom MoMA New York bis Artenschutz: \u00c3\u00bcber 70 Speaker beim ... - Newsslash","og_description":"Der Gamescom Congress 2017 bietet ein breites Themen-Spektrum in f\u00c3\u00bcnf Dachthemen \u00e2\u20ac\u201c von Games-P\u00c3\u00a4dagogik in New York bis Recht bei... Mehr auf Newsslash.com!","og_url":"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/","og_site_name":"Newsslash","article_published_time":"2017-07-26T16:11:10+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","type":"image\/jpeg"}],"author":"Viktor Pulz","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Viktor Pulz","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/#article","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/"},"author":{"name":"Viktor Pulz","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/9710bfacfd5579c2b307825ddaad6c46"},"headline":"Vom MoMA New York bis Artenschutz: \u00c3\u00bcber 70 Speaker beim &#8230;","datePublished":"2017-07-26T16:11:10+00:00","mainEntityOfPage":{"@id":"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/"},"wordCount":425,"commentCount":0,"publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"image":{"@id":"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/","url":"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/","name":"Vom MoMA New York bis Artenschutz: \u00c3\u00bcber 70 Speaker beim ... - Newsslash","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/#primaryimage"},"image":{"@id":"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","datePublished":"2017-07-26T16:11:10+00:00","breadcrumb":{"@id":"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/#primaryimage","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","width":1280,"height":854},{"@type":"BreadcrumbList","@id":"https:\/\/newsslash.com\/n\/10297-von-moma-new-york-bis-artenschutz-ueber-70-speaker-beim-gamescom-congress\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsslash.com\/n\/"},{"@type":"ListItem","position":2,"name":"Vom MoMA New York bis Artenschutz: \u00c3\u00bcber 70 Speaker beim &#8230;"}]},{"@type":"WebSite","@id":"https:\/\/newsslash.com\/n\/#website","url":"https:\/\/newsslash.com\/n\/","name":"Newsslash","description":"Trending News on Movies, Series, OTT, Gaming","publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsslash.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/newsslash.com\/n\/#organization","name":"Newsslash","url":"https:\/\/newsslash.com\/n\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","width":512,"height":512,"caption":"Newsslash"},"image":{"@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/9710bfacfd5579c2b307825ddaad6c46","name":"Viktor Pulz","sameAs":["https:\/\/newsslash.com"],"url":"https:\/\/newsslash.com\/n\/author\/viktor_pulz\/"}]}},"_links":{"self":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/13657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/comments?post=13657"}],"version-history":[{"count":0,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/13657\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media\/21974"}],"wp:attachment":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media?parent=13657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}