{"id":17096,"date":"2018-11-13T15:20:00","date_gmt":"2018-11-13T15:20:00","guid":{"rendered":"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/"},"modified":"2018-11-13T15:20:00","modified_gmt":"2018-11-13T15:20:00","slug":"13350-netflix-guenstigere-version-in-der-planung","status":"publish","type":"post","link":"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/","title":{"rendered":"Netflix: G\u00c3\u00bcnstigere Version in der Planung?"},"content":{"rendered":"<p>Wie das Handelsblatt unter der Berufung auf Bloomberg berichtet, m\u00c3\u00b6chte der VoD-Anbieter Netflix zuk\u00c3\u00bcnftig eine g\u00c3\u00bcnstigere Version des Streamingdienstes auf den Markt bringen, um auch Kunden mit einem geringeren Einkommen als Kunden zu gewinnen. Dabei soll es nicht um eine Senkung des aktuellen Preises gehen, sondern um eine neue Version, die lediglich \u00c3\u00bcber ein reduziertes Angebot verf\u00c3\u00bcgt. Bislang hat Netflix seinen Fokus eher auf ein qualitativ m\u00c3\u00b6glichst hochwertiges Angebot gesetzt und die Preise daf\u00c3\u00bcr regelm\u00c3\u00a4\u00c3\u0178ig erh\u00c3\u00b6ht. Die geplante g\u00c3\u00bcnstigere Version des VoD-Anbieters ist somit laut dem Handelsblatt als eine Strategiewende zu deuten. Die g\u00c3\u00bcnstigeren Abos w\u00c3\u00a4ren dann aber auch vor allem f\u00c3\u00bcr L\u00c3\u00a4nder gedacht, in welchen das Pro-Kopf-Einkommen geringer ist. Im vergangenen Quartal konnte Netflix erneut einen Zuwachs der Nutzer verzeichnen. So z\u00c3\u00a4hlte der Streamingdienst 130,4 Millionen zahlende Abonnenten, von denen sich rund sieben Millionen noch im Probemonat befanden. Auf <a href=\"https:\/\/www.lightsteelblue-llama-768814.hostingersite.comn\/n\/13258-netflix-november-2018-neuerscheinungen-im-ueberblick\" target=\"_blank\">Newsslash<\/a> findet ihr eine Liste mit allen Neuerscheinungen, die im November auf Netflix ver\u00c3\u00b6ffentlicht werden.<\/p><div class=\"newss-content\" id=\"newss-1307006862\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-7733425960004873\" \ndata-ad-slot=\"2582020599\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div class=\"newss-article-1\" id=\"newss-4208142685\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Homepage2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7733425960004873\"\r\n     data-ad-slot=\"2582020599\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Um auch Personen mit einem geringen Einkommen anzusprechen, m\u00c3\u00b6chte Netflix in Zukunft eine g\u00c3\u00bcnstigere Version des&#8230; Mehr auf Newsslash.com!<\/p>\n","protected":false},"author":8,"featured_media":21974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-17096","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Netflix: G\u00c3\u00bcnstigere Version in der Planung? - Newsslash<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Netflix: G\u00c3\u00bcnstigere Version in der Planung? - Newsslash\" \/>\n<meta property=\"og:description\" content=\"Um auch Personen mit einem geringen Einkommen anzusprechen, m\u00c3\u00b6chte Netflix in Zukunft eine g\u00c3\u00bcnstigere Version des... Mehr auf Newsslash.com!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/\" \/>\n<meta property=\"og:site_name\" content=\"Newsslash\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-13T15:20:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cindy D\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cindy D\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/\"},\"author\":{\"name\":\"Cindy D\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/522101af9b37501b768c7dfa5cf1edad\"},\"headline\":\"Netflix: G\u00c3\u00bcnstigere Version in der Planung?\",\"datePublished\":\"2018-11-13T15:20:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/\"},\"wordCount\":176,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/\",\"url\":\"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/\",\"name\":\"Netflix: G\u00c3\u00bcnstigere Version in der Planung? - Newsslash\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"datePublished\":\"2018-11-13T15:20:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/#primaryimage\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"width\":1280,\"height\":854},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsslash.com\/n\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Netflix: G\u00c3\u00bcnstigere Version in der Planung?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsslash.com\/n\/#website\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"name\":\"Newsslash\",\"description\":\"Trending News on Movies, Series, OTT, Gaming\",\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsslash.com\/n\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsslash.com\/n\/#organization\",\"name\":\"Newsslash\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"width\":512,\"height\":512,\"caption\":\"Newsslash\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/522101af9b37501b768c7dfa5cf1edad\",\"name\":\"Cindy D\",\"sameAs\":[\"http:\/\/newsslash.com\"],\"url\":\"https:\/\/newsslash.com\/n\/author\/cindy_d\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Netflix: G\u00c3\u00bcnstigere Version in der Planung? - Newsslash","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Netflix: G\u00c3\u00bcnstigere Version in der Planung? - Newsslash","og_description":"Um auch Personen mit einem geringen Einkommen anzusprechen, m\u00c3\u00b6chte Netflix in Zukunft eine g\u00c3\u00bcnstigere Version des... Mehr auf Newsslash.com!","og_url":"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/","og_site_name":"Newsslash","article_published_time":"2018-11-13T15:20:00+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","type":"image\/jpeg"}],"author":"Cindy D","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Cindy D","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/#article","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/"},"author":{"name":"Cindy D","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/522101af9b37501b768c7dfa5cf1edad"},"headline":"Netflix: G\u00c3\u00bcnstigere Version in der Planung?","datePublished":"2018-11-13T15:20:00+00:00","mainEntityOfPage":{"@id":"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/"},"wordCount":176,"commentCount":0,"publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"image":{"@id":"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/","url":"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/","name":"Netflix: G\u00c3\u00bcnstigere Version in der Planung? - Newsslash","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/#primaryimage"},"image":{"@id":"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","datePublished":"2018-11-13T15:20:00+00:00","breadcrumb":{"@id":"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/#primaryimage","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","width":1280,"height":854},{"@type":"BreadcrumbList","@id":"https:\/\/newsslash.com\/n\/13350-netflix-guenstigere-version-in-der-planung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsslash.com\/n\/"},{"@type":"ListItem","position":2,"name":"Netflix: G\u00c3\u00bcnstigere Version in der Planung?"}]},{"@type":"WebSite","@id":"https:\/\/newsslash.com\/n\/#website","url":"https:\/\/newsslash.com\/n\/","name":"Newsslash","description":"Trending News on Movies, Series, OTT, Gaming","publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsslash.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/newsslash.com\/n\/#organization","name":"Newsslash","url":"https:\/\/newsslash.com\/n\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","width":512,"height":512,"caption":"Newsslash"},"image":{"@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/522101af9b37501b768c7dfa5cf1edad","name":"Cindy D","sameAs":["http:\/\/newsslash.com"],"url":"https:\/\/newsslash.com\/n\/author\/cindy_d\/"}]}},"_links":{"self":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/17096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/comments?post=17096"}],"version-history":[{"count":0,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/17096\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media\/21974"}],"wp:attachment":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media?parent=17096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}