{"id":17257,"date":"2018-12-10T20:38:00","date_gmt":"2018-12-10T20:38:00","guid":{"rendered":"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/"},"modified":"2018-12-10T20:38:00","modified_gmt":"2018-12-10T20:38:00","slug":"13501-netflix-kuendigt-neue-cyberpunk-animeserie-an","status":"publish","type":"post","link":"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/","title":{"rendered":"Netflix k\u00c3\u00bcndigt neue Cyberpunk-Animeserie an"},"content":{"rendered":"<p>Via <a href=\" https:\/\/twitter.com\/NXOnNetflix\/status\/1071192665008484352\" target=\"_blank\">Twitter<\/a> hat Netflix eine neue Cyberpunk-Animeserie aus dem Ghost-in-the-Shell-Franchise angek\u00c3\u00bcndigt. Das Projekt wird den Titel Ghost in the Shell: SAC_2045 tragen und, wie der Titel bereits erahnen l\u00c3\u00a4sst, im Jahr 2045 spielen. Die Regie werden Kenji Kamiyama (Ghost in the Shell: Stand Alone Complex) und Shinji Aramaki (Appleseed) f\u00c3\u00bchren. Die Serie wird unter den D\u00c3\u00a4chern von SOLA Digital Arts, Production I.G und CGI-Animation produziert. Die Handlung von Ghost in the Shell: SAC_2045 dreht sich um die Cyber-Crime-Sondereinheit Section 9. Zu der Einheit geh\u00c3\u00b6rt auch die Cyborg-Polizistin Motoko Kusanagi, die ein Maschinenmensch ist. Der Start des neuen Netflix Originals ist f\u00c3\u00bcr das Jahr 2020 angesetzt. Bei Ghost in the Shell: SAC_2045 handelt es sich nicht um die erste Animationsserie, die Netflix in diesem Monat ank\u00c3\u00bcndigt. Erst vor wenigen Tagen hat der Streamingdienst eine neue Animeserie aus dem \u00e2\u20ac\u017eBlade Runner\u00e2\u20ac\u0153-Universum best\u00c3\u00a4tigt, einen ausf\u00c3\u00bchrlichen Bericht hierzu findet ihr auf <a href=\"https:\/\/www.lightsteelblue-llama-768814.hostingersite.comn\/n\/13456-animeserie-aus-dem-blade-runner-universum-angekuendigt\" target=\"_blank\">Newsslash<\/a>.<\/p><div class=\"newss-content\" id=\"newss-1269631797\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-7733425960004873\" \ndata-ad-slot=\"2582020599\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div class=\"newss-article-1\" id=\"newss-244484528\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Homepage2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7733425960004873\"\r\n     data-ad-slot=\"2582020599\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mit Ghost in the Shell: SAC_2045 hat Netflix eine neue Animeserie angek\u00c3\u00bcndigt, die in der Zukunft spielen wird. Mit dem Start ist&#8230; Mehr auf Newsslash.com!<\/p>\n","protected":false},"author":8,"featured_media":21974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-17257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Netflix k\u00c3\u00bcndigt neue Cyberpunk-Animeserie an - Newsslash<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Netflix k\u00c3\u00bcndigt neue Cyberpunk-Animeserie an - Newsslash\" \/>\n<meta property=\"og:description\" content=\"Mit Ghost in the Shell: SAC_2045 hat Netflix eine neue Animeserie angek\u00c3\u00bcndigt, die in der Zukunft spielen wird. Mit dem Start ist... Mehr auf Newsslash.com!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/\" \/>\n<meta property=\"og:site_name\" content=\"Newsslash\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-10T20:38:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cindy D\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cindy D\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/\"},\"author\":{\"name\":\"Cindy D\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/522101af9b37501b768c7dfa5cf1edad\"},\"headline\":\"Netflix k\u00c3\u00bcndigt neue Cyberpunk-Animeserie an\",\"datePublished\":\"2018-12-10T20:38:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/\"},\"wordCount\":162,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/\",\"url\":\"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/\",\"name\":\"Netflix k\u00c3\u00bcndigt neue Cyberpunk-Animeserie an - Newsslash\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"datePublished\":\"2018-12-10T20:38:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/#primaryimage\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"width\":1280,\"height\":854},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsslash.com\/n\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Netflix k\u00c3\u00bcndigt neue Cyberpunk-Animeserie an\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsslash.com\/n\/#website\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"name\":\"Newsslash\",\"description\":\"Trending News on Movies, Series, OTT, Gaming\",\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsslash.com\/n\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsslash.com\/n\/#organization\",\"name\":\"Newsslash\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"width\":512,\"height\":512,\"caption\":\"Newsslash\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/522101af9b37501b768c7dfa5cf1edad\",\"name\":\"Cindy D\",\"sameAs\":[\"http:\/\/newsslash.com\"],\"url\":\"https:\/\/newsslash.com\/n\/author\/cindy_d\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Netflix k\u00c3\u00bcndigt neue Cyberpunk-Animeserie an - Newsslash","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Netflix k\u00c3\u00bcndigt neue Cyberpunk-Animeserie an - Newsslash","og_description":"Mit Ghost in the Shell: SAC_2045 hat Netflix eine neue Animeserie angek\u00c3\u00bcndigt, die in der Zukunft spielen wird. Mit dem Start ist... Mehr auf Newsslash.com!","og_url":"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/","og_site_name":"Newsslash","article_published_time":"2018-12-10T20:38:00+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","type":"image\/jpeg"}],"author":"Cindy D","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Cindy D","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/#article","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/"},"author":{"name":"Cindy D","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/522101af9b37501b768c7dfa5cf1edad"},"headline":"Netflix k\u00c3\u00bcndigt neue Cyberpunk-Animeserie an","datePublished":"2018-12-10T20:38:00+00:00","mainEntityOfPage":{"@id":"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/"},"wordCount":162,"commentCount":0,"publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"image":{"@id":"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/","url":"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/","name":"Netflix k\u00c3\u00bcndigt neue Cyberpunk-Animeserie an - Newsslash","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/#primaryimage"},"image":{"@id":"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","datePublished":"2018-12-10T20:38:00+00:00","breadcrumb":{"@id":"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/#primaryimage","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","width":1280,"height":854},{"@type":"BreadcrumbList","@id":"https:\/\/newsslash.com\/n\/13501-netflix-kuendigt-neue-cyberpunk-animeserie-an\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsslash.com\/n\/"},{"@type":"ListItem","position":2,"name":"Netflix k\u00c3\u00bcndigt neue Cyberpunk-Animeserie an"}]},{"@type":"WebSite","@id":"https:\/\/newsslash.com\/n\/#website","url":"https:\/\/newsslash.com\/n\/","name":"Newsslash","description":"Trending News on Movies, Series, OTT, Gaming","publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsslash.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/newsslash.com\/n\/#organization","name":"Newsslash","url":"https:\/\/newsslash.com\/n\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","width":512,"height":512,"caption":"Newsslash"},"image":{"@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/522101af9b37501b768c7dfa5cf1edad","name":"Cindy D","sameAs":["http:\/\/newsslash.com"],"url":"https:\/\/newsslash.com\/n\/author\/cindy_d\/"}]}},"_links":{"self":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/17257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/comments?post=17257"}],"version-history":[{"count":0,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/17257\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media\/21974"}],"wp:attachment":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media?parent=17257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}