{"id":17752,"date":"2019-05-16T11:30:00","date_gmt":"2019-05-16T11:30:00","guid":{"rendered":"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/"},"modified":"2019-05-16T11:30:00","modified_gmt":"2019-05-16T11:30:00","slug":"13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert","status":"publish","type":"post","link":"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/","title":{"rendered":"This Is Us bekommt gleich drei weitere Staffeln spendiert"},"content":{"rendered":"<p>Die Upfronts sind auch in diesem Jahr wieder eines der wichtigsten Ereignisse f\u00c3\u00bcr Serienfans, denn hier wird verk\u00c3\u00bcndet, wer verl\u00c3\u00a4ngert wird und wer den Serientod stirbt. Fans der Dramaserie This Is Us werden nun ganz besonders gl\u00c3\u00bccklich sein, denn die Serie wurde gleich um drei weitere Staffeln verl\u00c3\u00a4ngert. Damit hat NBC die Anzahl der Seasons so eben mal verdoppelt, denn bisher sind 3 Staffeln abgedreht. Die von Dan Fogelman, Charlie Gogolak, Glenn Ficanca, Jess Rosenthal und John Requa produzierte Serie ist aktuell die st\u00c3\u00a4rkste NBC-Serie, obwohl Staffel 3 harte Einbu\u00c3\u0178en der Zuschauerzahlen von 35 Prozent hinnehmen musste. Im Schnitt sehen aber noch immer rund 8,3 Millionen Menschen bei jeder Folge zu. Ob diese Mega-Verl\u00c3\u00a4ngerung dann auch gleich die letzte war und die Serie nach der sechsten Staffel auch ihr Ende findet, ist noch nicht bekanntgegeben worden. Dan Fogelman, der Sch\u00c3\u00b6pfer der Serie, allerdings sagte schon von Beginn an, dass es sechs Seasons geben wird. In This Is Us begleiten wir mehrere Protagonisten, die eines gemeinsam haben: ihren Geburtstag. Das Paar Paar Rebecca Mandy Moore und Jack Milo Ventimiglia mit ihren Drillingen, die \u00c3\u00bcbergewichtige Kate im st\u00c3\u00a4ndigen Kampf gegen die Kilos, die die gro\u00c3\u0178e Liebe findet oder Schauspieler Kevin, der ein ganz neues Leben anfangen will. Am\u00c3\u00bcsant und doch ein bisschen nachdenklich tauchen wir in den Alltag der Menschen ein und bleiben nicht in Klischees verhangen. <iframe loading=\"lazy\" allowfullscreen=\"\" frameborder=\"0\" height=\"315\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/xZFwPlqDURk\" width=\"100%\"><\/iframe><\/p><div class=\"newss-content\" id=\"newss-1170110252\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-7733425960004873\" \ndata-ad-slot=\"2582020599\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div class=\"newss-article-1\" id=\"newss-2302937632\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Homepage2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7733425960004873\"\r\n     data-ad-slot=\"2582020599\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>NBC hat auf den Upfronts bekannt gegeben, welche Serien verl\u00c3\u00a4ngert werden und von welchen man sich so langsam verabschieden darf&#8230;. Mehr auf Newsslash.com!<\/p>\n","protected":false},"author":7,"featured_media":21974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-17752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>This Is Us bekommt gleich drei weitere Staffeln spendiert - Newsslash<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"This Is Us bekommt gleich drei weitere Staffeln spendiert - Newsslash\" \/>\n<meta property=\"og:description\" content=\"NBC hat auf den Upfronts bekannt gegeben, welche Serien verl\u00c3\u00a4ngert werden und von welchen man sich so langsam verabschieden darf.... Mehr auf Newsslash.com!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/\" \/>\n<meta property=\"og:site_name\" content=\"Newsslash\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-16T11:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniela H\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniela H\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/\"},\"author\":{\"name\":\"Daniela H\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11\"},\"headline\":\"This Is Us bekommt gleich drei weitere Staffeln spendiert\",\"datePublished\":\"2019-05-16T11:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/\"},\"wordCount\":242,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/\",\"url\":\"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/\",\"name\":\"This Is Us bekommt gleich drei weitere Staffeln spendiert - Newsslash\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"datePublished\":\"2019-05-16T11:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/#primaryimage\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"width\":1280,\"height\":854},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsslash.com\/n\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"This Is Us bekommt gleich drei weitere Staffeln spendiert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsslash.com\/n\/#website\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"name\":\"Newsslash\",\"description\":\"Trending News on Movies, Series, OTT, Gaming\",\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsslash.com\/n\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsslash.com\/n\/#organization\",\"name\":\"Newsslash\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"width\":512,\"height\":512,\"caption\":\"Newsslash\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11\",\"name\":\"Daniela H\",\"sameAs\":[\"https:\/\/newsslash.com\"],\"url\":\"https:\/\/newsslash.com\/n\/author\/daniela_h\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"This Is Us bekommt gleich drei weitere Staffeln spendiert - Newsslash","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"This Is Us bekommt gleich drei weitere Staffeln spendiert - Newsslash","og_description":"NBC hat auf den Upfronts bekannt gegeben, welche Serien verl\u00c3\u00a4ngert werden und von welchen man sich so langsam verabschieden darf.... Mehr auf Newsslash.com!","og_url":"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/","og_site_name":"Newsslash","article_published_time":"2019-05-16T11:30:00+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","type":"image\/jpeg"}],"author":"Daniela H","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Daniela H","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/#article","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/"},"author":{"name":"Daniela H","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11"},"headline":"This Is Us bekommt gleich drei weitere Staffeln spendiert","datePublished":"2019-05-16T11:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/"},"wordCount":242,"commentCount":0,"publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"image":{"@id":"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/","url":"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/","name":"This Is Us bekommt gleich drei weitere Staffeln spendiert - Newsslash","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/#primaryimage"},"image":{"@id":"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","datePublished":"2019-05-16T11:30:00+00:00","breadcrumb":{"@id":"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/#primaryimage","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","width":1280,"height":854},{"@type":"BreadcrumbList","@id":"https:\/\/newsslash.com\/n\/13968-this-is-us-bekommt-gleich-drei-weitere-staffeln-spendiert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsslash.com\/n\/"},{"@type":"ListItem","position":2,"name":"This Is Us bekommt gleich drei weitere Staffeln spendiert"}]},{"@type":"WebSite","@id":"https:\/\/newsslash.com\/n\/#website","url":"https:\/\/newsslash.com\/n\/","name":"Newsslash","description":"Trending News on Movies, Series, OTT, Gaming","publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsslash.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/newsslash.com\/n\/#organization","name":"Newsslash","url":"https:\/\/newsslash.com\/n\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","width":512,"height":512,"caption":"Newsslash"},"image":{"@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11","name":"Daniela H","sameAs":["https:\/\/newsslash.com"],"url":"https:\/\/newsslash.com\/n\/author\/daniela_h\/"}]}},"_links":{"self":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/17752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/comments?post=17752"}],"version-history":[{"count":0,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/17752\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media\/21974"}],"wp:attachment":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media?parent=17752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}