{"id":17756,"date":"2019-05-20T11:30:00","date_gmt":"2019-05-20T11:30:00","guid":{"rendered":"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/"},"modified":"2019-05-20T11:30:00","modified_gmt":"2019-05-20T11:30:00","slug":"13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz","status":"publish","type":"post","link":"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/","title":{"rendered":"Trailer zur neuen Netflix-Serie What\/If &#8211; Zellweger bitte&#8230;"},"content":{"rendered":"<p>Endlich gibt es mehr als nur einen kleinen Teaser-trailer zur neuen Thriller-Anthologie von Netflix mit dem mysteri\u00c3\u00b6sen Namen What\/If, die Ende Mai beim Streamingdienst anl\u00c3\u00a4uft. Im nun ver\u00c3\u00b6ffentlichten Trailer l\u00c3\u00a4dt uns Ren\u00c3\u00a9e Zellweger aka Anne zu einem gef\u00c3\u00a4hrlichen Spiel ein. Sie macht den Eingeladenen ganz verlockende Angebote doch wie hoch ist der Preis, den sie f\u00c3\u00bcr ihre Tr\u00c3\u00a4ume zahlen m\u00c3\u00bcssen? What\/If zeigt, was geschieht, wenn sich ganz gew\u00c3\u00b6hnliche Menschen auf ein mysteri\u00c3\u00b6ses und gef\u00c3\u00a4hrliches Spiel einlassen, um ihre Tr\u00c3\u00a4ume zu erf\u00c3\u00bcllen. Sie werfen ihre moralischen Grundvorstellungen \u00c3\u00bcber Bord und merken oft nicht, wie Hauptfigur Anne sie wie Schachfiguren auf dem Spielbrett hin- und herschiebt. In der ersten Staffel, die am 24. Mai mit zehn Episoden startet, lernen wir zum Beispiel das Ehepaar Sean und Lisa kennen. Sie stecken in finanziellen Schwierigkeiten und bekommen von Anne, die eine sehr einflussreiche Risiko-Kapitalanlegerin ist, ein verlockendes Angebot. Der Geldregen, der \u00c3\u00bcber beide kommen soll, verursacht aber ein regelrechtes Chaos in ihrem bis dato so geordnetem Leben. War es die richtige Entscheidung, das Angebot anzunehmen? In der Hauptrolle sehen wir Ren\u00c3\u00a9e Zellweger als charismatische Anne. Neben ihr spielen in weiteren Rollen Dave Annable den Dr. Harris und Louis Herthum Annes Chauffeur Foster. Hinter der Serie steht Mike Kelley, der tonangebend die Schreibfeder schwang. Produziert wird von Page Fright, Atlas Entertainment und Compari Entertainment in Zusammenarbeit mit Warner Bros. Und hier nat\u00c3\u00bcrlich noch der Trailer f\u00c3\u00bcr euch: <iframe loading=\"lazy\" allowfullscreen=\"\" frameborder=\"0\" height=\"315\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/CdgQARm236Q\" width=\"100%\"><\/iframe><\/p><div class=\"newss-content\" id=\"newss-2371958651\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-7733425960004873\" \ndata-ad-slot=\"2582020599\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div class=\"newss-article-1\" id=\"newss-142467215\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Homepage2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7733425960004873\"\r\n     data-ad-slot=\"2582020599\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Thriller-Fans k\u00c3\u00b6nnen sich f\u00c3\u00bcr Ende Mai schon mal ein bisschen Zeit f\u00c3\u00bcr Netflix reservieren, denn dann kommt die neue&#8230; Mehr auf Newsslash.com!<\/p>\n","protected":false},"author":7,"featured_media":21974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-17756","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trailer zur neuen Netflix-Serie What\/If - Zellweger bitte... - Newsslash<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trailer zur neuen Netflix-Serie What\/If - Zellweger bitte... - Newsslash\" \/>\n<meta property=\"og:description\" content=\"Thriller-Fans k\u00c3\u00b6nnen sich f\u00c3\u00bcr Ende Mai schon mal ein bisschen Zeit f\u00c3\u00bcr Netflix reservieren, denn dann kommt die neue... Mehr auf Newsslash.com!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/\" \/>\n<meta property=\"og:site_name\" content=\"Newsslash\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-20T11:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniela H\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniela H\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/\"},\"author\":{\"name\":\"Daniela H\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11\"},\"headline\":\"Trailer zur neuen Netflix-Serie What\/If &#8211; Zellweger bitte&#8230;\",\"datePublished\":\"2019-05-20T11:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/\"},\"wordCount\":259,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/\",\"url\":\"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/\",\"name\":\"Trailer zur neuen Netflix-Serie What\/If - Zellweger bitte... - Newsslash\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"datePublished\":\"2019-05-20T11:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/#primaryimage\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"width\":1280,\"height\":854},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsslash.com\/n\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trailer zur neuen Netflix-Serie What\/If &#8211; Zellweger bitte&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsslash.com\/n\/#website\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"name\":\"Newsslash\",\"description\":\"Trending News on Movies, Series, OTT, Gaming\",\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsslash.com\/n\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsslash.com\/n\/#organization\",\"name\":\"Newsslash\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"width\":512,\"height\":512,\"caption\":\"Newsslash\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11\",\"name\":\"Daniela H\",\"sameAs\":[\"https:\/\/newsslash.com\"],\"url\":\"https:\/\/newsslash.com\/n\/author\/daniela_h\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trailer zur neuen Netflix-Serie What\/If - Zellweger bitte... - Newsslash","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Trailer zur neuen Netflix-Serie What\/If - Zellweger bitte... - Newsslash","og_description":"Thriller-Fans k\u00c3\u00b6nnen sich f\u00c3\u00bcr Ende Mai schon mal ein bisschen Zeit f\u00c3\u00bcr Netflix reservieren, denn dann kommt die neue... Mehr auf Newsslash.com!","og_url":"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/","og_site_name":"Newsslash","article_published_time":"2019-05-20T11:30:00+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","type":"image\/jpeg"}],"author":"Daniela H","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Daniela H","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/#article","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/"},"author":{"name":"Daniela H","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11"},"headline":"Trailer zur neuen Netflix-Serie What\/If &#8211; Zellweger bitte&#8230;","datePublished":"2019-05-20T11:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/"},"wordCount":259,"commentCount":0,"publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"image":{"@id":"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/","url":"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/","name":"Trailer zur neuen Netflix-Serie What\/If - Zellweger bitte... - Newsslash","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/#primaryimage"},"image":{"@id":"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","datePublished":"2019-05-20T11:30:00+00:00","breadcrumb":{"@id":"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/#primaryimage","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","width":1280,"height":854},{"@type":"BreadcrumbList","@id":"https:\/\/newsslash.com\/n\/13972-trailer-zur-neuen-netflix-serie-what-if-zellweger-bittet-zum-tanz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsslash.com\/n\/"},{"@type":"ListItem","position":2,"name":"Trailer zur neuen Netflix-Serie What\/If &#8211; Zellweger bitte&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/newsslash.com\/n\/#website","url":"https:\/\/newsslash.com\/n\/","name":"Newsslash","description":"Trending News on Movies, Series, OTT, Gaming","publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsslash.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/newsslash.com\/n\/#organization","name":"Newsslash","url":"https:\/\/newsslash.com\/n\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","width":512,"height":512,"caption":"Newsslash"},"image":{"@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11","name":"Daniela H","sameAs":["https:\/\/newsslash.com"],"url":"https:\/\/newsslash.com\/n\/author\/daniela_h\/"}]}},"_links":{"self":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/17756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/comments?post=17756"}],"version-history":[{"count":0,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/17756\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media\/21974"}],"wp:attachment":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media?parent=17756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}