{"id":17782,"date":"2019-06-03T11:30:00","date_gmt":"2019-06-03T11:30:00","guid":{"rendered":"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/"},"modified":"2019-06-03T11:30:00","modified_gmt":"2019-06-03T11:30:00","slug":"13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie","status":"publish","type":"post","link":"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/","title":{"rendered":"Der ber\u00c3\u00bchmte Golfer Tiger Woods bekommt eigene Serie"},"content":{"rendered":"<p>Er ist einer der erfolgreichsten Sportler aller Zeiten und reiht sich in die Riege von Michael Schumacher und Michael Jordan ein: Tiger Woods. Doch nicht nur durch sein besonderes Talent im Golf wurde der Sportler ber\u00c3\u00bchmt, sondern auch so einige Sex-Skandale sorgten f\u00c3\u00bcr ein eher nicht so positives Bild in der \u00c3\u2013ffentlichkeit. Nun soll der Ausnahme-Sportler in einer Miniserie verewigt werden. Mehr als eine Milliarde Dollar brachten Tiger Woods seine sportlichen Erfolge und die vielen Sponsoring-Deals ein. Dann bekam seine Karriere allerdings einen gewaltigen Knick, denn im Jahr 2009 kam es zum Tigergate, in dem es vor allem um die vielen Sex-Geschichten Beziehungen von Tiger Woods neben seiner Ehefrau ging. Das Ende vom Lied war die Scheidung und eine \u00c3\u00b6ffentliche Entschuldigung des Sportlers f\u00c3\u00bcr sein unr\u00c3\u00bchmliches Verhalten, denn um nichts auf der Welt wollte der Tiger seine sportliche Laufbahn aufgeben. Tat er auch nicht, denn erst vor Kurzem machte sich Tiger mit dem f\u00c3\u00bcnften Masters-Weltmeisterschaftstitel wieder zum Gott der Golfwelt. Um der spannenden Frage nachzugehen, ob Woods seine Karriere auf dem h\u00c3\u00b6chsten Level fortsetzen kann, kommt man nicht drumherum, die <a href=\"https:\/\/www.tvsportguide.de\/golf\/\">PGA Golftuniere<\/a> zu verfolgen. Jeff Benedict und Armen Keteyian waren es, die all dies in einer ausf\u00c3\u00bchrlichen Biographie niedergeschrieben haben. Und genau diese Ausf\u00c3\u00bchrungen sollen nun Grundlage f\u00c3\u00bcr die Miniserie \u00c3\u00bcber Tiger Woods werden. Realisiert wird das Projekt von Brent Montgommery mit seinem Studio Wheelhouse Entertainment. Angeblich sollen mit dem Deal \u00c3\u00bcber Tiger Woods auch noch weitere Biographie-Projekte von Jeff Benedict im Kasten sein. Welcher Sender \u00c3\u00bcbrigens die Ausstrahlungsrechte bekommen wird, ist noch nicht bekannt. Wir berichten euch nat\u00c3\u00bcrlich dar\u00c3\u00bcber, wenn es weitere Neuigkeiten gibt.<\/p><div class=\"newss-content\" id=\"newss-3281026468\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-7733425960004873\" \ndata-ad-slot=\"2582020599\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div class=\"newss-article-1\" id=\"newss-695751145\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Homepage2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7733425960004873\"\r\n     data-ad-slot=\"2582020599\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tiger Woods wurde nicht nur durch seine Erfolge im Golfen ber\u00c3\u00bchmt, sondern auch durch diverse Sex-Skandale. Nun plant Brent&#8230; Mehr auf Newsslash.com!<\/p>\n","protected":false},"author":7,"featured_media":21974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-17782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Der ber\u00c3\u00bchmte Golfer Tiger Woods bekommt eigene Serie - Newsslash<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der ber\u00c3\u00bchmte Golfer Tiger Woods bekommt eigene Serie - Newsslash\" \/>\n<meta property=\"og:description\" content=\"Tiger Woods wurde nicht nur durch seine Erfolge im Golfen ber\u00c3\u00bchmt, sondern auch durch diverse Sex-Skandale. Nun plant Brent... Mehr auf Newsslash.com!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/\" \/>\n<meta property=\"og:site_name\" content=\"Newsslash\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-03T11:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniela H\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniela H\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/\"},\"author\":{\"name\":\"Daniela H\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11\"},\"headline\":\"Der ber\u00c3\u00bchmte Golfer Tiger Woods bekommt eigene Serie\",\"datePublished\":\"2019-06-03T11:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/\"},\"wordCount\":284,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/\",\"url\":\"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/\",\"name\":\"Der ber\u00c3\u00bchmte Golfer Tiger Woods bekommt eigene Serie - Newsslash\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"datePublished\":\"2019-06-03T11:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/#primaryimage\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"width\":1280,\"height\":854},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsslash.com\/n\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der ber\u00c3\u00bchmte Golfer Tiger Woods bekommt eigene Serie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsslash.com\/n\/#website\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"name\":\"Newsslash\",\"description\":\"Trending News on Movies, Series, OTT, Gaming\",\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsslash.com\/n\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsslash.com\/n\/#organization\",\"name\":\"Newsslash\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"width\":512,\"height\":512,\"caption\":\"Newsslash\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11\",\"name\":\"Daniela H\",\"sameAs\":[\"https:\/\/newsslash.com\"],\"url\":\"https:\/\/newsslash.com\/n\/author\/daniela_h\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der ber\u00c3\u00bchmte Golfer Tiger Woods bekommt eigene Serie - Newsslash","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Der ber\u00c3\u00bchmte Golfer Tiger Woods bekommt eigene Serie - Newsslash","og_description":"Tiger Woods wurde nicht nur durch seine Erfolge im Golfen ber\u00c3\u00bchmt, sondern auch durch diverse Sex-Skandale. Nun plant Brent... Mehr auf Newsslash.com!","og_url":"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/","og_site_name":"Newsslash","article_published_time":"2019-06-03T11:30:00+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","type":"image\/jpeg"}],"author":"Daniela H","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Daniela H","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/#article","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/"},"author":{"name":"Daniela H","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11"},"headline":"Der ber\u00c3\u00bchmte Golfer Tiger Woods bekommt eigene Serie","datePublished":"2019-06-03T11:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/"},"wordCount":284,"commentCount":0,"publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"image":{"@id":"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/","url":"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/","name":"Der ber\u00c3\u00bchmte Golfer Tiger Woods bekommt eigene Serie - Newsslash","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/#primaryimage"},"image":{"@id":"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","datePublished":"2019-06-03T11:30:00+00:00","breadcrumb":{"@id":"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/#primaryimage","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","width":1280,"height":854},{"@type":"BreadcrumbList","@id":"https:\/\/newsslash.com\/n\/13994-der-beruehmte-golfer-tiger-woods-bekommt-eigene-serie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsslash.com\/n\/"},{"@type":"ListItem","position":2,"name":"Der ber\u00c3\u00bchmte Golfer Tiger Woods bekommt eigene Serie"}]},{"@type":"WebSite","@id":"https:\/\/newsslash.com\/n\/#website","url":"https:\/\/newsslash.com\/n\/","name":"Newsslash","description":"Trending News on Movies, Series, OTT, Gaming","publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsslash.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/newsslash.com\/n\/#organization","name":"Newsslash","url":"https:\/\/newsslash.com\/n\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","width":512,"height":512,"caption":"Newsslash"},"image":{"@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11","name":"Daniela H","sameAs":["https:\/\/newsslash.com"],"url":"https:\/\/newsslash.com\/n\/author\/daniela_h\/"}]}},"_links":{"self":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/17782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/comments?post=17782"}],"version-history":[{"count":0,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/17782\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media\/21974"}],"wp:attachment":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media?parent=17782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}