{"id":21030,"date":"2023-03-08T14:30:00","date_gmt":"2023-03-08T14:30:00","guid":{"rendered":"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/"},"modified":"2023-03-08T14:30:00","modified_gmt":"2023-03-08T14:30:00","slug":"16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley","status":"publish","type":"post","link":"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/","title":{"rendered":"Prime Video spendiert ersten Trailer zur Serie I\u00e2\u20ac\u2122m a Vi&#8230;"},"content":{"rendered":"<p>Der erste Blick auf I&#8217;m a Virgo von Amazons Prime Video, wurde am Montag zusammen mit einem Teaser-Trailer in Erwartung der Weltpremiere der Show auf dem SXSW Film &amp; TV Festival enth\u00c3\u00bcllt. In der Coming-of-Age-Kom\u00c3\u00b6die spielt Jharrel Jerome, der 2019 einen Emmy f\u00c3\u00bcr seine Hauptrolle in der Miniserie &#8220;When They See Us&#8221; gewann, neben den Serienmitgliedern Brett Gray (&#8220;On My Block&#8221;), Kara Young (&#8220;The Punisher&#8221;), Allius Barnes (&#8220;Cruel Summer&#8221;), Olivia Washington (&#8220;Breaking&#8221;), Mike Epps (&#8220;The Upshaws&#8221;), Carmen Ejogo (&#8220;True Detective&#8221;) und Walton Goggins (&#8220;The Hateful Eight&#8221;). Die Serie I&#8217;m a Virgo handelt von einem drei Meter gro\u00c3\u0178en Mann namens Cootie (Jerome) aus Oakland, Kalifornien. Er verbringt seine Zeit damit, Fernsehserien und Comics zu lesen. Das liegt vor allem daran, dass er von seinen Eltern immer vor der \u00c3\u2013fffenntlichkeit versteckt wurde. Er war und ist eben viel zu gro\u00c3\u0178. Doch als kein Platz mehr f\u00c3\u00bcr ihn war, musste er dann ausziehen. Dabei weiss er eigentlich nichts \u00c3\u00bcber das Leben da drau\u00c3\u0178en. Als er seinem echten Superhelden, genannt The Hero (Goggins), begegnet, begibt sich Cootie auf eine mythische Reise. Der Teaser-Trailer beginnt mit Cootie, der irritiert L\u00c3\u00b6cher in der Wand \u00c3\u00bcbermalt. Das Tempo beschleunigt sich schnell und gibt den Zuschauern einen kurzen Einblick in die kommenden Verr\u00c3\u00bccktheiten, wenn Cootie den Alltag hinter sich l\u00c3\u00a4sst, um ein actiongeladenes Abenteuer zu erleben &#8211; zum Beispiel eine Spritztour in einem Cabrio mit offenem Verdeck. Mit den Worten\u00e2\u20ac\u017eNun, ich bin Jungfrau, und Jungfrauen lieben Abenteuer&#8221; endet der Trailer. Die Serie wurde von Boots Riley, der vor allem f\u00c3\u00bcr das Drehbuch zu &#8220;Sorry to Bother You&#8221; aus dem Jahr 2018 bekannt ist, entwickelt, geschrieben, inszeniert und produziert. Jerome ist auch als ausf\u00c3\u00bchrender Produzent an dem Projekt beteiligt. Die Amazon Studios und Media Res Studio haben die Serie koproduziert. Alle sieben Episoden von I&#8217;m a Virgo werden im Sommer 2023 auf Amazon Prime Video Premiere feiern. Ein offizielles Ver\u00c3\u00b6ffentlichungsdatum wurde noch nicht bekannt gegeben. Hier ist der erste Trailer zu I\u00e2\u20ac\u2122m a Virgo f\u00c3\u00bcr euch: <iframe loading=\"lazy\" allowfullscreen=\"\" frameborder=\"0\" height=\"315\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/DYfpWY330mM\" width=\"100%\"><\/iframe><\/p><div class=\"newss-content\" id=\"newss-1196771972\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-7733425960004873\" \ndata-ad-slot=\"2582020599\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div class=\"newss-article-1\" id=\"newss-2852103389\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Homepage2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7733425960004873\"\r\n     data-ad-slot=\"2582020599\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Wie lebt es sich, wenn man \u00c3\u00bcber drei Meter gro\u00c3\u0178 ist? Dieser Frage geht die neue Serie von Amazon Prime Video namens I\u00e2\u20ac\u2122m a Virgo&#8230; Mehr auf Newsslash.com!<\/p>\n","protected":false},"author":7,"featured_media":21974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-21030","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Prime Video spendiert ersten Trailer zur Serie I\u00e2\u20ac\u2122m a Vi... - Newsslash<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prime Video spendiert ersten Trailer zur Serie I\u00e2\u20ac\u2122m a Vi... - Newsslash\" \/>\n<meta property=\"og:description\" content=\"Wie lebt es sich, wenn man \u00c3\u00bcber drei Meter gro\u00c3\u0178 ist? Dieser Frage geht die neue Serie von Amazon Prime Video namens I\u00e2\u20ac\u2122m a Virgo... Mehr auf Newsslash.com!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/\" \/>\n<meta property=\"og:site_name\" content=\"Newsslash\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-08T14:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniela H\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniela H\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/\"},\"author\":{\"name\":\"Daniela H\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11\"},\"headline\":\"Prime Video spendiert ersten Trailer zur Serie I\u00e2\u20ac\u2122m a Vi&#8230;\",\"datePublished\":\"2023-03-08T14:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/\"},\"wordCount\":353,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/\",\"url\":\"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/\",\"name\":\"Prime Video spendiert ersten Trailer zur Serie I\u00e2\u20ac\u2122m a Vi... - Newsslash\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"datePublished\":\"2023-03-08T14:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/#primaryimage\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"width\":1280,\"height\":854},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsslash.com\/n\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prime Video spendiert ersten Trailer zur Serie I\u00e2\u20ac\u2122m a Vi&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsslash.com\/n\/#website\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"name\":\"Newsslash\",\"description\":\"Trending News on Movies, Series, OTT, Gaming\",\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsslash.com\/n\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsslash.com\/n\/#organization\",\"name\":\"Newsslash\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"width\":512,\"height\":512,\"caption\":\"Newsslash\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11\",\"name\":\"Daniela H\",\"sameAs\":[\"https:\/\/newsslash.com\"],\"url\":\"https:\/\/newsslash.com\/n\/author\/daniela_h\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prime Video spendiert ersten Trailer zur Serie I\u00e2\u20ac\u2122m a Vi... - Newsslash","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Prime Video spendiert ersten Trailer zur Serie I\u00e2\u20ac\u2122m a Vi... - Newsslash","og_description":"Wie lebt es sich, wenn man \u00c3\u00bcber drei Meter gro\u00c3\u0178 ist? Dieser Frage geht die neue Serie von Amazon Prime Video namens I\u00e2\u20ac\u2122m a Virgo... Mehr auf Newsslash.com!","og_url":"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/","og_site_name":"Newsslash","article_published_time":"2023-03-08T14:30:00+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","type":"image\/jpeg"}],"author":"Daniela H","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Daniela H","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/#article","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/"},"author":{"name":"Daniela H","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11"},"headline":"Prime Video spendiert ersten Trailer zur Serie I\u00e2\u20ac\u2122m a Vi&#8230;","datePublished":"2023-03-08T14:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/"},"wordCount":353,"commentCount":0,"publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"image":{"@id":"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/","url":"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/","name":"Prime Video spendiert ersten Trailer zur Serie I\u00e2\u20ac\u2122m a Vi... - Newsslash","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/#primaryimage"},"image":{"@id":"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","datePublished":"2023-03-08T14:30:00+00:00","breadcrumb":{"@id":"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/#primaryimage","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","width":1280,"height":854},{"@type":"BreadcrumbList","@id":"https:\/\/newsslash.com\/n\/16995-prime-video-spendiert-ersten-trailer-zur-serie-im-a-virgo-von-boots-riley\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsslash.com\/n\/"},{"@type":"ListItem","position":2,"name":"Prime Video spendiert ersten Trailer zur Serie I\u00e2\u20ac\u2122m a Vi&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/newsslash.com\/n\/#website","url":"https:\/\/newsslash.com\/n\/","name":"Newsslash","description":"Trending News on Movies, Series, OTT, Gaming","publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsslash.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/newsslash.com\/n\/#organization","name":"Newsslash","url":"https:\/\/newsslash.com\/n\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","width":512,"height":512,"caption":"Newsslash"},"image":{"@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11","name":"Daniela H","sameAs":["https:\/\/newsslash.com"],"url":"https:\/\/newsslash.com\/n\/author\/daniela_h\/"}]}},"_links":{"self":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/21030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/comments?post=21030"}],"version-history":[{"count":0,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/21030\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media\/21974"}],"wp:attachment":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media?parent=21030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}