{"id":21036,"date":"2023-03-14T19:39:34","date_gmt":"2023-03-14T19:39:34","guid":{"rendered":"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/"},"modified":"2023-03-14T19:39:34","modified_gmt":"2023-03-14T19:39:34","slug":"17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt","status":"publish","type":"post","link":"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/","title":{"rendered":"Nach Im Westen nichts Neues &#8211; Erfolgsregisseur startet n\u00c3&#8230;"},"content":{"rendered":"<p>Beste Kamera, bestes Szenebild, beste Musik und bester internationaler Film \u00e2\u20ac\u201c das ist die Bilanz der Romanverfilmung Im Westen nichts Neues aus Deutschland. Mit diesen vier Oscars gelang Regisseur Edward Berger ein Triumph und sein bisher gr\u00c3\u00b6\u00c3\u0178ter Erfolg. Dass der Regisseur sich darauf nicht ausruhen wird, zeigt ein neues Projekt, welches er schon am Start hat. Edward Berger wird eine Serie f\u00c3\u00bcr Amazon inszenieren. Hellhole soll der achtteilige Mix aus Krimi, Thriller und Drama hei\u00c3\u0178en, und neben Berger weitere gro\u00c3\u0178e und bekannte Akteure aus dem Filmgesch\u00c3\u00a4ft mit sich bringen. Die Amazon Serie Hellhole wird auf der Romanvorlage von Casey Sherman basieren. Mohamad el Masri wird Showrunner und ausf\u00c3\u00bchrender Produzent sein. Einige kenne ihn vielleicht schon als Mitautor bei der Apple-Serie Severance. Mit an Bord ist dar\u00c3\u00bcber hinaus auch Robert Downey Junior mit seiner Produktionsfirma Team Downey. Und auch im Cast wird es hochkar\u00c3\u00a4tig. F\u00c3\u00bcr die Hauptrolle ist Oscar Isaac, der aus dem Marvel-Universum bekannt ist, im Gespr\u00c3\u00a4ch. In Hellhole wird die Geschichte des US-amerikanischen Schriftstellers Kurt Vonnegut erz\u00c3\u00a4hlt. Den kennt man vor allem wegen seiner satirischen Science-Fiction-Romane. Alles beginnt im Jahr 1969 mit einem Mann, der noch nicht richtig in seinem Leben angekommen ist. Noch ist Kurt Autoverk\u00c3\u00a4ufer und versucht so, seine Familie zu ern\u00c3\u00a4hren. Doch als eines Tages die Leichen zweier verschwundener Frauen auftauchen, wird Kurts Leben sich \u00c3\u00a4ndern. Er wird in den Fall hineingezogen. Er will dem vermutlichen Serienkiller auf die Spur kommen, liest alles \u00c3\u00bcber die Verbrechen und baut dabei eine sehr gef\u00c3\u00a4hrliche Beziehung zu dem Hauptverd\u00c3\u00a4chtigen auf. Edward Berger ist kein Neuling im Seriengesch\u00c3\u00a4ft. Vor \u00e2\u20ac\u017eIm Westen nichts Neues\u00e2\u20ac\u0153 drehte er in den USA schon Episoden von Your Honor und The Terror. Auch an der Serie Deutschland 83 war er beteiligt und zeigte sich f\u00c3\u00bcr die Miniserie Patrick Melrose verantwortlich. Man darf gespannt auf die ersten bewegten Bilder und Besetzungslisten von Hellhole sein, die hoffentlich bald zur Verf\u00c3\u00bcgung stehen werden. F\u00c3\u00bcr alle, die den grandiosen Film Im Westen nichts Neues noch nicht gesehen haben, hier der Trailer: <iframe loading=\"lazy\" allowfullscreen=\"\" frameborder=\"0\" height=\"315\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/Ug1bqv3ch1s\" width=\"100%\"><\/iframe><\/p><div class=\"newss-content\" id=\"newss-4187093112\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-7733425960004873\" \ndata-ad-slot=\"2582020599\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div class=\"newss-article-1\" id=\"newss-467362175\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Homepage2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7733425960004873\"\r\n     data-ad-slot=\"2582020599\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mit vier Oscars f\u00c3\u00bcr den Film Im Westen nichts Neues feierte Regisseur Edward Berger den bisher gr\u00c3\u00b6\u00c3\u0178ten Erfolg seines Lebens. Nun&#8230; Mehr auf Newsslash.com!<\/p>\n","protected":false},"author":7,"featured_media":21974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-21036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nach Im Westen nichts Neues - Erfolgsregisseur startet n\u00c3... - Newsslash<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nach Im Westen nichts Neues - Erfolgsregisseur startet n\u00c3... - Newsslash\" \/>\n<meta property=\"og:description\" content=\"Mit vier Oscars f\u00c3\u00bcr den Film Im Westen nichts Neues feierte Regisseur Edward Berger den bisher gr\u00c3\u00b6\u00c3\u0178ten Erfolg seines Lebens. Nun... Mehr auf Newsslash.com!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/\" \/>\n<meta property=\"og:site_name\" content=\"Newsslash\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-14T19:39:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniela H\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniela H\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/\"},\"author\":{\"name\":\"Daniela H\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11\"},\"headline\":\"Nach Im Westen nichts Neues &#8211; Erfolgsregisseur startet n\u00c3&#8230;\",\"datePublished\":\"2023-03-14T19:39:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/\"},\"wordCount\":356,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/\",\"url\":\"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/\",\"name\":\"Nach Im Westen nichts Neues - Erfolgsregisseur startet n\u00c3... - Newsslash\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"datePublished\":\"2023-03-14T19:39:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/#primaryimage\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"width\":1280,\"height\":854},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsslash.com\/n\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nach Im Westen nichts Neues &#8211; Erfolgsregisseur startet n\u00c3&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsslash.com\/n\/#website\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"name\":\"Newsslash\",\"description\":\"Trending News on Movies, Series, OTT, Gaming\",\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsslash.com\/n\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsslash.com\/n\/#organization\",\"name\":\"Newsslash\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"width\":512,\"height\":512,\"caption\":\"Newsslash\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11\",\"name\":\"Daniela H\",\"sameAs\":[\"https:\/\/newsslash.com\"],\"url\":\"https:\/\/newsslash.com\/n\/author\/daniela_h\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nach Im Westen nichts Neues - Erfolgsregisseur startet n\u00c3... - Newsslash","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Nach Im Westen nichts Neues - Erfolgsregisseur startet n\u00c3... - Newsslash","og_description":"Mit vier Oscars f\u00c3\u00bcr den Film Im Westen nichts Neues feierte Regisseur Edward Berger den bisher gr\u00c3\u00b6\u00c3\u0178ten Erfolg seines Lebens. Nun... Mehr auf Newsslash.com!","og_url":"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/","og_site_name":"Newsslash","article_published_time":"2023-03-14T19:39:34+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","type":"image\/jpeg"}],"author":"Daniela H","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Daniela H","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/#article","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/"},"author":{"name":"Daniela H","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11"},"headline":"Nach Im Westen nichts Neues &#8211; Erfolgsregisseur startet n\u00c3&#8230;","datePublished":"2023-03-14T19:39:34+00:00","mainEntityOfPage":{"@id":"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/"},"wordCount":356,"commentCount":0,"publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"image":{"@id":"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/","url":"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/","name":"Nach Im Westen nichts Neues - Erfolgsregisseur startet n\u00c3... - Newsslash","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/#primaryimage"},"image":{"@id":"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","datePublished":"2023-03-14T19:39:34+00:00","breadcrumb":{"@id":"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/#primaryimage","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","width":1280,"height":854},{"@type":"BreadcrumbList","@id":"https:\/\/newsslash.com\/n\/17001-nach-im-westen-nichts-neues-erfolgsregisseur-startet-naechstes-mega-projekt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsslash.com\/n\/"},{"@type":"ListItem","position":2,"name":"Nach Im Westen nichts Neues &#8211; Erfolgsregisseur startet n\u00c3&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/newsslash.com\/n\/#website","url":"https:\/\/newsslash.com\/n\/","name":"Newsslash","description":"Trending News on Movies, Series, OTT, Gaming","publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsslash.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/newsslash.com\/n\/#organization","name":"Newsslash","url":"https:\/\/newsslash.com\/n\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","width":512,"height":512,"caption":"Newsslash"},"image":{"@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/cb1381eb00b5dc4b3071475e9866df11","name":"Daniela H","sameAs":["https:\/\/newsslash.com"],"url":"https:\/\/newsslash.com\/n\/author\/daniela_h\/"}]}},"_links":{"self":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/21036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/comments?post=21036"}],"version-history":[{"count":0,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/21036\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media\/21974"}],"wp:attachment":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media?parent=21036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}