{"id":21219,"date":"2023-08-18T14:49:53","date_gmt":"2023-08-18T14:49:53","guid":{"rendered":"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/"},"modified":"2023-08-18T14:49:53","modified_gmt":"2023-08-18T14:49:53","slug":"17179-rund-um-die-neuigkeiten-in-der-spielwelt","status":"publish","type":"post","link":"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/","title":{"rendered":"Rund um die Neuigkeiten in der Spielwelt"},"content":{"rendered":"<p><span>Grinding Gear Games gab auf der diesj\u00c3\u00a4hrigen ExileCon-Keynote bekannt, dass Path of Exile 2, urspr\u00c3\u00bcnglich als Ersatz f\u00c3\u00bcr den Vorg\u00c3\u00a4nger geplant, nun ein eigenst\u00c3\u00a4ndiges Spiel wird, das auf einem eigenen Client l\u00c3\u00a4uft. Die Entscheidung, die Spiele aufzuteilen, fiel, nachdem PoE2 seit seiner ersten Ank\u00c3\u00bcndigung vor vier Jahren erheblich erweitert wurde, wie vom Magazine PC Gamer berichtet wird. Falls Sie ein Einsteiger sind, k\u00c3\u00b6nnten Sie mit <\/span><a href=\"https:\/\/gg.bet\/de\/esports\"><span>GGBet Wetten<\/span><\/a><span> erste n\u00c3\u00bctzliche Erfahrung sammeln. Informieren Sie sich \u00c3\u00bcber die frischsten Neuigkeiten und fangen Sie an, reale Gewinne live zu erzielen.\u00c2 <\/span> <\/p><div class=\"newss-content\" id=\"newss-2394782171\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-7733425960004873\" \ndata-ad-slot=\"2582020599\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div class=\"newss-article-1\" id=\"newss-158707839\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Homepage2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7733425960004873\"\r\n     data-ad-slot=\"2582020599\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div>\n<h2><span>Die Gr\u00c3\u00bcnde f\u00c3\u00bcr keinen Spielersatz\u00c2 <\/span><\/h2>\n<p> <span>Jonathan Rogers, Mitbegr\u00c3\u00bcnder von Grinding Gear Games, hob die umfangreichen Erg\u00c3\u00a4nzungen zu PoE2 hervor, darunter sechs neue Klassen, 36 Aszendentenklassen, 600 Monster, 100 Bosse, 240 aktive Fertigkeiten und 1.500 passive Fertigkeiten. Bemerkenswert ist, dass die Spieler die Hinzuf\u00c3\u00bcgung eines Ausweichwurfs ohne Abklingzeit begr\u00c3\u00bc\u00c3\u0178t haben.<\/span> <span>Anfangs gab es Bedenken, das beliebte Path of Exile 1 durch die Fortsetzung zu ersetzen (was die Spieler k\u00c3\u00bcrzlich gesehen haben, als Overwatch das erste Spiel ersetzte). Rogers sagte: \u00e2\u20ac\u017eWir haben erkannt, dass unser Plan, PoE1 durch PoE2 zu ersetzen, im Wesentlichen darin bestehen w\u00c3\u00bcrde, ein Spiel loszuwerden, das die Leute ohne wirklichen Grund lieben. Also haben wir eine Entscheidung getroffen: Path of Exile 1 und 2 werden getrennt funktionieren und ihre eigenen Mechaniken haben.\u00e2\u20ac\u0153 , Balance, Endspiele und Ligen.<\/span> <span>Obwohl es sich um separate Spiele handelt, werden PoE1 und PoE2 nicht vollst\u00c3\u00a4ndig voneinander getrennt. In-Game-K\u00c3\u00a4ufe sind in beiden F\u00c3\u00a4llen m\u00c3\u00b6glich, mit Ausnahme von Kompatibilit\u00c3\u00a4tsproblemen. Rogers versicherte den Spielern, dass in einem Spiel gekaufte Gegenst\u00c3\u00a4nde im anderen verwendet werden k\u00c3\u00b6nnen, solange der Inhalt \u00c3\u00bcbereinstimmt. Einige exklusive Inhalte k\u00c3\u00b6nnen jedoch m\u00c3\u00b6glicherweise nicht in beiden verwendet werden.<\/span> <span>Bei der Veranstaltung pr\u00c3\u00a4sentierten die Entwickler einen Teil der Kampagne von PoE2, bekannt als \u00e2\u20ac\u017eDschungeltiefen von Akt 3\u00e2\u20ac\u0153, mit der neuen M\u00c3\u00b6nchsklasse \u00e2\u20ac\u201c einer von sechs, die in der Fortsetzung eingef\u00c3\u00bchrt werden.<\/span> <span>Path of Exile 2 wurde urspr\u00c3\u00bcnglich 2019 als Erweiterung angek\u00c3\u00bcndigt und soll gleichzeitig auf PC und Konsolen ver\u00c3\u00b6ffentlicht werden. Es wird erwartet, dass es bei seiner Ver\u00c3\u00b6ffentlichung eine erhebliche Herausforderung f\u00c3\u00bcr Diablo IV darstellen wird.<\/span> <\/p>\n<h2><span>\u00c3\u0153berrest 2: So entsperren Sie den Archon-Archetyp<\/span><\/h2>\n<p> <span>In Remnant II gibt es in seinen verschiedenen Biomen mehrere supergeheime Archetypen zu entdecken, und die meisten davon erfordern nun eine sorgf\u00c3\u00a4ltige Erkundung. Im Fall des Archon-Archetyps liegen die Dinge jedoch nicht so einfach. Sie ben\u00c3\u00b6tigen viel Geduld, wenn Sie dieses Exemplar zu Ihrer Sammlung hinzuf\u00c3\u00bcgen m\u00c3\u00b6chten. Hier ist die Aufschl\u00c3\u00bcsselung.<\/span> <\/p>\n<h2><span>So erhalten Sie den Archon-Archetyp<\/span><\/h2>\n<p> <span>Um den Archon-Archetyp zu erhalten, m\u00c3\u00bcssen Sie eine Menge Dinge sammeln, bevor Sie eine extrem gut versteckte T\u00c3\u00bcr im Labyrinth aufsuchen. Hier finden Sie alle Gegenst\u00c3\u00a4nde, Archetypen und mehr, was Sie ben\u00c3\u00b6tigen:<\/span> <span>Wenn alles gesammelt und ausger\u00c3\u00bcstet ist, ist es an der Zeit, zu einer Geheimt\u00c3\u00bcr im Labyrinth zu gehen. Beachten Sie, dass die folgenden Anweisungen davon ausgehen, dass Sie das Labyrinth zum ersten Mal abgeschlossen haben.<\/span> <span>Gehen Sie vom Fractured Ingress World Stone die Treppe hinunter und biegen Sie links durch die T\u00c3\u00bcr links vom riesigen Portal ab. Gehen Sie nach rechts eine kleine Treppe hinauf und dann durch die kreuzf\u00c3\u00b6rmige T\u00c3\u00bcr. Hier sehen Sie so ein Portal wie dieses, das alle paar Sekunden wechselt, wohin Sie teleportiert werden. Warten Sie, bis es sich zu einem Ort ver\u00c3\u00a4ndert, der aussieht, als w\u00c3\u00bcrden Sie in den Tod st\u00c3\u00bcrzen, und gehen Sie dann hindurch, um zu fallen. Nach ein paar Augenblicken landen Sie auf einem neu angelegten Steinweg.<\/span> <span>Folgen Sie dem Steinweg und suchen Sie im letzten Bereich auf der rechten Seite nach einem gro\u00c3\u0178en, besch\u00c3\u00a4digten Biomtor. Stellen Sie sicher, dass alle Ihre gesammelten Gegenst\u00c3\u00a4nde ausger\u00c3\u00bcstet sind, verwenden Sie dann den Biome-Portalschl\u00c3\u00bcssel am Tor und gehen Sie hindurch.<\/span> <span>Sie befinden sich jetzt in den Hinterzimmern. Dies ist ein Labyrinth, das Ihnen nur begrenzte Zeit zum Erkunden l\u00c3\u00a4sst, Sie sollten also schnell handeln. Es gibt hier ein paar verschiedene Gegenst\u00c3\u00a4nde, aber Sie sind wegen eines namens \u00e2\u20ac\u017eSeltsame Box\u00e2\u20ac\u0153 hier, das ganz hinten links im Bereich zu finden ist.<\/span> <span>Wenn Sie die sonderbare Kiste gefunden haben, k\u00c3\u00b6nnen Sie jetzt zu Station 13 zur\u00c3\u00bcckkehren und Wallace am Dock besuchen. Geben Sie ihm wie bei anderen Archetypen die seltsame Kiste, um im Gegenzug das Hexaeder zu erhalten, mit dem Sie den Archon-Archetyp ausr\u00c3\u00bcsten k\u00c3\u00b6nnen.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Path of Exile 2 wird das erste Spiel doch nicht ersetzen Auf der ExileCon-Keynote k\u00c3\u00bcndigt Grinding Gear Games eine Spielaufteilung&#8230; Mehr auf Newsslash.com!<\/p>\n","protected":false},"author":2,"featured_media":21974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-21219","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rund um die Neuigkeiten in der Spielwelt - Newsslash<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rund um die Neuigkeiten in der Spielwelt - Newsslash\" \/>\n<meta property=\"og:description\" content=\"Path of Exile 2 wird das erste Spiel doch nicht ersetzen Auf der ExileCon-Keynote k\u00c3\u00bcndigt Grinding Gear Games eine Spielaufteilung... Mehr auf Newsslash.com!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/\" \/>\n<meta property=\"og:site_name\" content=\"Newsslash\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-18T14:49:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viktor Pulz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viktor Pulz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/\"},\"author\":{\"name\":\"Viktor Pulz\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/9710bfacfd5579c2b307825ddaad6c46\"},\"headline\":\"Rund um die Neuigkeiten in der Spielwelt\",\"datePublished\":\"2023-08-18T14:49:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/\"},\"wordCount\":743,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/\",\"url\":\"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/\",\"name\":\"Rund um die Neuigkeiten in der Spielwelt - Newsslash\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"datePublished\":\"2023-08-18T14:49:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/#primaryimage\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"width\":1280,\"height\":854},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsslash.com\/n\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rund um die Neuigkeiten in der Spielwelt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsslash.com\/n\/#website\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"name\":\"Newsslash\",\"description\":\"Trending News on Movies, Series, OTT, Gaming\",\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsslash.com\/n\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsslash.com\/n\/#organization\",\"name\":\"Newsslash\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"width\":512,\"height\":512,\"caption\":\"Newsslash\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/9710bfacfd5579c2b307825ddaad6c46\",\"name\":\"Viktor Pulz\",\"sameAs\":[\"https:\/\/newsslash.com\"],\"url\":\"https:\/\/newsslash.com\/n\/author\/viktor_pulz\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rund um die Neuigkeiten in der Spielwelt - Newsslash","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Rund um die Neuigkeiten in der Spielwelt - Newsslash","og_description":"Path of Exile 2 wird das erste Spiel doch nicht ersetzen Auf der ExileCon-Keynote k\u00c3\u00bcndigt Grinding Gear Games eine Spielaufteilung... Mehr auf Newsslash.com!","og_url":"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/","og_site_name":"Newsslash","article_published_time":"2023-08-18T14:49:53+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","type":"image\/jpeg"}],"author":"Viktor Pulz","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Viktor Pulz","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/#article","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/"},"author":{"name":"Viktor Pulz","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/9710bfacfd5579c2b307825ddaad6c46"},"headline":"Rund um die Neuigkeiten in der Spielwelt","datePublished":"2023-08-18T14:49:53+00:00","mainEntityOfPage":{"@id":"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/"},"wordCount":743,"commentCount":0,"publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"image":{"@id":"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/","url":"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/","name":"Rund um die Neuigkeiten in der Spielwelt - Newsslash","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/#primaryimage"},"image":{"@id":"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","datePublished":"2023-08-18T14:49:53+00:00","breadcrumb":{"@id":"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/#primaryimage","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","width":1280,"height":854},{"@type":"BreadcrumbList","@id":"https:\/\/newsslash.com\/n\/17179-rund-um-die-neuigkeiten-in-der-spielwelt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsslash.com\/n\/"},{"@type":"ListItem","position":2,"name":"Rund um die Neuigkeiten in der Spielwelt"}]},{"@type":"WebSite","@id":"https:\/\/newsslash.com\/n\/#website","url":"https:\/\/newsslash.com\/n\/","name":"Newsslash","description":"Trending News on Movies, Series, OTT, Gaming","publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsslash.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/newsslash.com\/n\/#organization","name":"Newsslash","url":"https:\/\/newsslash.com\/n\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","width":512,"height":512,"caption":"Newsslash"},"image":{"@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/9710bfacfd5579c2b307825ddaad6c46","name":"Viktor Pulz","sameAs":["https:\/\/newsslash.com"],"url":"https:\/\/newsslash.com\/n\/author\/viktor_pulz\/"}]}},"_links":{"self":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/21219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/comments?post=21219"}],"version-history":[{"count":0,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/21219\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media\/21974"}],"wp:attachment":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media?parent=21219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}