{"id":21354,"date":"2023-11-13T13:15:00","date_gmt":"2023-11-13T13:15:00","guid":{"rendered":"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/"},"modified":"2023-11-13T13:15:00","modified_gmt":"2023-11-13T13:15:00","slug":"17290-poker-slots-und-co-in-der-serienwelt","status":"publish","type":"post","link":"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/","title":{"rendered":"Poker, Slots und Co. in der Serienwelt"},"content":{"rendered":"<p><span>In einigen Drehb\u00c3\u00bcchern ist die Casino-Welt sogar das Hauptthema. Die folgenden Beispiele geh\u00c3\u00b6ren diesbez\u00c3\u00bcglich zu den interessantesten Produktionen, die ihre Zuschauer <\/span><a href=\"https:\/\/www.lightsteelblue-llama-768814.hostingersite.comn\/vod-programm\"><span>\u00c3\u00bcber digitale Mediatheken<\/span><\/a><span> in packende Serienwelten katapultieren.\u00c2 \u00c2 <\/span> <\/p><div class=\"newss-content\" id=\"newss-1462851324\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-7733425960004873\" \ndata-ad-slot=\"2582020599\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div class=\"newss-article-1\" id=\"newss-1149063059\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Homepage2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7733425960004873\"\r\n     data-ad-slot=\"2582020599\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div>\n<h3><b>Poker Face<\/b><\/h3>\n<p> <span>Die amerikanische Krimiserie <\/span><i><span>Poker Face<\/span><\/i><span>, die Anfang 2023 ver\u00c3\u00b6ffentlicht wurde, bedient sich bereits beim Titel einer Pokeranspielung. Das \u00e2\u20ac\u0153Pokergesicht\u00e2\u20ac\u009d ist eine wichtige Taktik der Spieler, bei der sie am Spieltisch ein emotionsloses Gesicht vorzeigen. Mit dem Verzicht auf jegliche Mimik verhindern sie R\u00c3\u00bcckschl\u00c3\u00bcsse auf ihre Handkarten. Jenseits der Pokerszene werden Menschen, die <\/span><a href=\"https:\/\/greator.com\/emotionen-kontrollieren\/\"><span>eine starke Emotionskontrolle<\/span><\/a><span> haben, auch mit diesem Begriff beschrieben. In der Serie hat die Hauptdarstellerin Natasha Lyonne alias Charlie Cale allerdings die F\u00c3\u00a4higkeit, jedes Poker Face zu durchschauen. Die Casino-Angestellte auf der Flucht trifft auf ihrer Reise quer durch Amerika auf verschiedenste Menschen und verwickelt sich in mysteri\u00c3\u00b6se Todesf\u00c3\u00a4lle, die von ihr mit Cleverness und Humor gel\u00c3\u00b6st werden. Ihre F\u00c3\u00a4higkeit, L\u00c3\u00bcgner zu entlarven, ist dabei ihre st\u00c3\u00a4rkste Waffe. Die Macher greifen in der Serie immer wieder auf weitere Casino-Elemente zur\u00c3\u00bcck, die den Episodenverlauf reizvoller gestalten.\u00c2 <\/span> <\/p>\n<h3><b>High Card<\/b><\/h3>\n<p> <span>Auch bei der japanischen Mangaserie <\/span><i><span>High Card<\/span><\/i><span> aus dem Jahr 2023 nimmt bereits der Titel einen Bezug auf die Pokerwelt. Der Ausdruck beschreibt im Poker eine Regel hinsichtlich der Rangfolge der Karten. Diese wird wie folgt erkl\u00c3\u00a4rt: Wenn ein Spieler f\u00c3\u00bcnf Karten <\/span><a href=\"https:\/\/www.pokerstars.de\/poker\/learn\/lesson\/poker-rangfolge\/\"><span>mit unterschiedlichen Wertigkeiten<\/span><\/a><span> besitzt, die nicht aufeinander folgend sind oder die gleiche Farbe haben, z\u00c3\u00a4hlt der Wert der h\u00c3\u00b6chsten Karte. Doch die Bez\u00c3\u00bcge auf das Kartenspiel in der Serie sind nicht nur auf den Titel begrenzt. <\/span><i><span>High Card<\/span><\/i><span> ist ein gigantisches Pokerprojekt mit spannenden Fantasy-Elementen. In der Hauptrolle ist ein Dieb namens Finn, der vom K\u00c3\u00b6nig in eine Spezialtruppe aufgenommen wird, damit sie ein geheimes Deck des K\u00c3\u00b6nigshauses mit 52 Karten wiederfinden. Dieses Deck verleiht seinem Besitzer \u00c3\u00bcbermenschliche F\u00c3\u00a4higkeit und darf deshalb nicht in falsche H\u00c3\u00a4nde geraten.\u00c2 <\/span> <img loading=\"lazy\" decoding=\"async\" alt=\"\" height=\"180\" src=\"https:\/\/adherents.com\/wp-content\/uploads\/2023\/11\/night-paris-cityscape-evening-reflection-tower-1054352-pxhere.com_-300x180.jpg\" width=\"300\"\/> <\/p>\n<h3><b>Las Vegas<\/b><\/h3>\n<p> <span>Die amerikanische Serie <\/span><i><span>Las Vegas<\/span><\/i><span>, die zwischen 2003 und 2008 ausgestrahlt wurde, begn\u00c3\u00bcgt sich nicht nur mit Anspielungen, Adaptionen und Referenzen, sondern f\u00c3\u00bchrt die Zuschauer direkt in die spannende Welt des Las Vegas Strips. Hauptthema der Serie ist das Arbeitsumfeld eines Casinos. Im Mittelpunkt steht ein Team, das im fiktiven Hotel und Casino Montecito arbeitet. Im Verlauf der Staffeln erf\u00c3\u00a4hrt das Casino mehrere Besitzerwechsel sowie Positionswechsel unter den Angestellten. Dabei werden die Beziehungen zwischen den Angestellten sowie ihr Privatleben n\u00c3\u00a4her beleuchtet. Treue Zuschauer der Serie werden in einigen <\/span><a href=\"https:\/\/www.moviepilot.de\/news\/die-top-7-der-besten-serien-gastauftritte-116077\"><span>Episoden mit Gastauftritten<\/span><\/a><span> von diversen Gr\u00c3\u00b6\u00c3\u0178en des amerikanischen Showbusiness, wie Jon Bon Jovi, Paris Hilton und Snoop Dogg, \u00c3\u00bcberrascht.<\/span> <\/p>\n<h3><b>Vegas\u00c2 <\/b><\/h3>\n<p> <span>Zwei weitere Serien, die im Herzen von Las Vegas gedreht wurden, befinden sich unter dem Namen <\/span><i><span>Vegas<\/span><\/i><span> auf dem Markt. Die Krimiserie, die zwischen den Jahren 1978 und 1981 ausgestrahlt wurde, handelt von den Abenteuern eines Privatdetektivs. Robert Urich in der Rolle von Dan Tanna arbeitet mit einer Vielzahl von Kunden aus Las Vegas und sucht nach vermissten Personen, kl\u00c3\u00a4rt verschiedene Verbrechen in Casinos auf und jagt Betr\u00c3\u00bcgern hinterher. In dieser Serie sind nicht nur Casinos ein fester Bestandteil des Handlungsstrangs, sondern auch spannende Erfindungen wie <\/span><a href=\"https:\/\/www.bild.de\/auto\/mobilitaet-reisen-motorrad\/mobilitaet-und-mehr\/autotelefon-rueckblick-zum-60-geburtstag-der-kommunikation-im-auto-57600170.bild.html\"><span>das Funkautotelefon <\/span><\/a><span>oder der Anrufbeantworter, die in den sp\u00c3\u00a4ten 1970er-Jahren als Hightech eingestuft wurden.\u00c2 <\/span> <span>Die <\/span><i><span>Vegas<\/span><\/i><span>-Serie aus dem Jahr 2012 kann hingegen als ein Neo-Western eingestuft werden. Die Storyline erstreckt sich \u00c3\u00bcber zwei spannende Staffeln und bezieht sich auf die Aufstiegsjahre von Las Vegas. Die Macher der Serie pr\u00c3\u00a4sentieren eine faszinierende Wechselbeziehung zwischen Gesetz und Kriminalit\u00c3\u00a4t sowie Land- und Stadtleben in der wachsenden W\u00c3\u00bcstenstadt. Unterst\u00c3\u00bctzt wird die Story mit wundersch\u00c3\u00b6nen Bildern aus glitzernden Casinos und kargen Landschaften sowie faszinierenden Nebencharakteren. Im Fokus der Geschichte steht dabei die Rivalit\u00c3\u00a4t zwischen dem Sheriff Ralph Lamb alias Dennis Quaid und dem Casinobetreiber Vincent Savino, verk\u00c3\u00b6rpert von Michael Chiklis.\u00c2 <\/span> <span>Die moderne <\/span><i><span>Vegas<\/span><\/i><span>-Serie im Neo-Western-Format, die <\/span><i><span>Vegas<\/span><\/i><span>-Produktion aus den sp\u00c3\u00a4ten 70ern sowie das Drama <\/span><i><span>Las Vegas<\/span><\/i><span> setzen die amerikanische Casino-Welt ins Zentrum ihrer Drehb\u00c3\u00bccher und pr\u00c3\u00a4sentieren den Zuschauern aus unterschiedlichen Blickwinkeln das Leben in Las Vegas. Dagegen nutzt die nagelneue Ver\u00c3\u00b6ffentlichung <\/span><i><span>Poker Face<\/span><\/i><span> die Casino-Elemente f\u00c3\u00bcr mehr W\u00c3\u00bcrze im Episodenverlauf. Die Mangaserie High Card aus Japan erscheint im Vergleich zu den anderen Beispielen jedoch mit einem innovativen Konzept und bettet Poker in eine packende Fantasy-Geschichte ein. F\u00c3\u00bcr welche Serie man sich auch entscheidet, alle f\u00c3\u00bcnf versprechen packende Momente vor dem Bildschirm.\u00c2 <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rollende Kugeln, gesellige Spieltische und glitzernde Casinos sind in vielen Serien popul\u00c3\u00a4re Elemente der Storyline und Filmkulisse. Mehr auf Newsslash.com!<\/p>\n","protected":false},"author":2,"featured_media":21347,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-21354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Poker, Slots und Co. in der Serienwelt - Newsslash<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Poker, Slots und Co. in der Serienwelt - Newsslash\" \/>\n<meta property=\"og:description\" content=\"Rollende Kugeln, gesellige Spieltische und glitzernde Casinos sind in vielen Serien popul\u00c3\u00a4re Elemente der Storyline und Filmkulisse. Mehr auf Newsslash.com!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/\" \/>\n<meta property=\"og:site_name\" content=\"Newsslash\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-13T13:15:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_17290.png\" \/>\n\t<meta property=\"og:image:width\" content=\"977\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Viktor Pulz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viktor Pulz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/\"},\"author\":{\"name\":\"Viktor Pulz\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/9710bfacfd5579c2b307825ddaad6c46\"},\"headline\":\"Poker, Slots und Co. in der Serienwelt\",\"datePublished\":\"2023-11-13T13:15:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/\"},\"wordCount\":738,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_17290.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/\",\"url\":\"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/\",\"name\":\"Poker, Slots und Co. in der Serienwelt - Newsslash\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_17290.png\",\"datePublished\":\"2023-11-13T13:15:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/#primaryimage\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_17290.png\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_17290.png\",\"width\":977,\"height\":650},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsslash.com\/n\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Poker, Slots und Co. in der Serienwelt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsslash.com\/n\/#website\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"name\":\"Newsslash\",\"description\":\"Trending News on Movies, Series, OTT, Gaming\",\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsslash.com\/n\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsslash.com\/n\/#organization\",\"name\":\"Newsslash\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"width\":512,\"height\":512,\"caption\":\"Newsslash\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/9710bfacfd5579c2b307825ddaad6c46\",\"name\":\"Viktor Pulz\",\"sameAs\":[\"https:\/\/newsslash.com\"],\"url\":\"https:\/\/newsslash.com\/n\/author\/viktor_pulz\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Poker, Slots und Co. in der Serienwelt - Newsslash","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Poker, Slots und Co. in der Serienwelt - Newsslash","og_description":"Rollende Kugeln, gesellige Spieltische und glitzernde Casinos sind in vielen Serien popul\u00c3\u00a4re Elemente der Storyline und Filmkulisse. Mehr auf Newsslash.com!","og_url":"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/","og_site_name":"Newsslash","article_published_time":"2023-11-13T13:15:00+00:00","og_image":[{"width":977,"height":650,"url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_17290.png","type":"image\/png"}],"author":"Viktor Pulz","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Viktor Pulz","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/#article","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/"},"author":{"name":"Viktor Pulz","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/9710bfacfd5579c2b307825ddaad6c46"},"headline":"Poker, Slots und Co. in der Serienwelt","datePublished":"2023-11-13T13:15:00+00:00","mainEntityOfPage":{"@id":"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/"},"wordCount":738,"commentCount":0,"publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"image":{"@id":"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_17290.png","articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/","url":"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/","name":"Poker, Slots und Co. in der Serienwelt - Newsslash","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/#primaryimage"},"image":{"@id":"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_17290.png","datePublished":"2023-11-13T13:15:00+00:00","breadcrumb":{"@id":"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/#primaryimage","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_17290.png","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_17290.png","width":977,"height":650},{"@type":"BreadcrumbList","@id":"https:\/\/newsslash.com\/n\/17290-poker-slots-und-co-in-der-serienwelt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsslash.com\/n\/"},{"@type":"ListItem","position":2,"name":"Poker, Slots und Co. in der Serienwelt"}]},{"@type":"WebSite","@id":"https:\/\/newsslash.com\/n\/#website","url":"https:\/\/newsslash.com\/n\/","name":"Newsslash","description":"Trending News on Movies, Series, OTT, Gaming","publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsslash.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/newsslash.com\/n\/#organization","name":"Newsslash","url":"https:\/\/newsslash.com\/n\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","width":512,"height":512,"caption":"Newsslash"},"image":{"@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/9710bfacfd5579c2b307825ddaad6c46","name":"Viktor Pulz","sameAs":["https:\/\/newsslash.com"],"url":"https:\/\/newsslash.com\/n\/author\/viktor_pulz\/"}]}},"_links":{"self":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/21354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/comments?post=21354"}],"version-history":[{"count":0,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/21354\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media\/21347"}],"wp:attachment":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media?parent=21354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}