{"id":4626,"date":"2014-06-16T16:05:00","date_gmt":"2014-06-16T16:05:00","guid":{"rendered":"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/"},"modified":"2025-04-07T12:04:02","modified_gmt":"2025-04-07T12:04:02","slug":"3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen","status":"publish","type":"post","link":"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/","title":{"rendered":"Die Simpsons Springfield Steinmetze Guide: Heiliges Perga&#8230;"},"content":{"rendered":"<p>Mit dem neuen <a href=\"http:\/\/www.lightsteelblue-llama-768814.hostingersite.comn\/t\/die-simpsons-tapped-out\">Die Simpsons Springfield<\/a> Steinmetze-Update wird Springfield von den Steinmetzen \u00c3\u00bcberrollt. Es ziehen Misstrauen und \u00c3\u0153berwachung in die Reihen der Springfieldianer ein. Sogar euren treuen Freunden und Nachbarn k\u00c3\u00b6nnt ihr nicht mehr trauen und \u00c3\u00bcberwacht diese durch eingeschmuggelte Spionagekameras. Doch Achtung! Denn auch ihr werdet ausspioniert.<\/p><div class=\"newss-content\" id=\"newss-2892175011\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-7733425960004873\" \ndata-ad-slot=\"2582020599\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div class=\"newss-article-1\" id=\"newss-2474335391\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Homepage2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7733425960004873\"\r\n     data-ad-slot=\"2582020599\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div>\n<p>In Simpsons Springfield Steinmetze Event, welches noch einschlie\u00c3\u0178lich bis zum 2. Juli 2014 geht, erwarten euch zahlreiche spannende und interessante Aufgaben. Im neuen Update werdet ihr mit einer neuen W\u00c3\u00a4hrung konfrontiert, n\u00c3\u00a4mlich mit den Emblemen. Diese k\u00c3\u00b6nnt ihr euch auf unterschiedliche Weise verdienen. Wir haben dar\u00c3\u00bcber bereits in: <a href=\"http:\/\/www.lightsteelblue-llama-768814.hostingersite.comn\/n\/3318-die-simpsons-springfield-steinmetze-guide-fuer-mehr-embleme\" target=\"_blank\">Die Simpsons Springfield Steinmetzte Guide f\u00c3\u00bcr mehr Embleme<\/a> berichtet und zahlreiche Tipps hierzu ver\u00c3\u00b6ffentlicht.<\/p>\n<p>Mit dem Erreichen von 1450 Emblemen schaltet sich automatisch \u00e2\u20ac\u017eHeiliges Pergament\u00e2\u20ac\u0153 frei. Errichtet es in eurer Stadt und entdeckt t\u00c3\u00a4glich bis zum 26. Juni 2014 eine neue Aufgabe, die euch zus\u00c3\u00a4tzlich Embleme beschert. Da uns zu den Aufgaben des heiligen Pergaments in den letzten Tagen zahlreiche Fragen erreichten, haben wir hier eine Liste mit allen Aufgaben f\u00c3\u00bcr euch erstellt.<\/p>\n<p>Kennt ihr weiter Aufgaben oder Fragestellungen, dann hinterlasst einfach einen kurzen Kommentar unter diesem Beitrag. Um auch weiterhin alle News zu Simpsons Springfield Steinmetze zu erfahren, schaut einfach t\u00c3\u00a4glich bei uns auf Newsslash vorbei oder liked uns auf Facebook und erhaltet alle Neuigkeiten zu den Simpsons.<\/p>\n<p>Liken auf Facebook: <\/p>\n<div><\/div>\n<p><b>Aufgaben zum heiligen Pergament in Die Simpsons Springfield<\/b><br \/>\n<i>1. Aufgabe vom 3. Juni<\/i><br \/>\nFragestellung: Ein spitzhaariges M\u00c3\u00a4dchen sehnt sich danach, ihr Lieblingsinstrument zu spielen.<br \/>\nAntwort: Lass Lisa Saxophon spielen. Dauer der Aufgabe betr\u00c3\u00a4gt 4 Stunden.<\/p>\n<p><i>2. Aufgabe vom 4. Juni<\/i><br \/>\nFragestellung: Acht hungrige Kinder, gef\u00c3\u00bcttert von einem \u00c3\u00bcberarbeiteten Ladenbesitzer<br \/>\nAntwort: Lass Apu die Achtlinge f\u00c3\u00bcttern. Dauer der Aufgabe betr\u00c3\u00a4gt 60 Minuten.<\/p>\n<p><i>3. Aufgabe vom 5. Juni<\/i><br \/>\nFragestellung: Ein Promi hat einen Affen<br \/>\nAntwort: Lass Krusty Mr. Teeny auff\u00c3\u00bchren. Dauer der Aufgabe betr\u00c3\u00a4gt 12 Stunden.<\/p>\n<p><i>4. Aufgabe vom 6. Juni<\/i><br \/>\nFragestellung: Ein Junge sucht hartn\u00c3\u00a4ckig nach dem, was er liebt.<br \/>\nAntwort: Lass Milhouse Puppy Goo-Goo finden. Dauer der Aufgabe 10 Minuten.<\/p>\n<p><i>5. Aufgabe vom 7. Juni<\/i><br \/>\nFragestellung: Ein Ausflug in die Natur ist eine wundervolle Aufgabe, auch f\u00c3\u00bcr ein Schuloberhaupt.<br \/>\nAntwort: Lass Skinner V\u00c3\u00b6gel beobachten gehen. Dauer der Aufgabe betr\u00c3\u00a4gt 24 Stunden<\/p>\n<p><i>6. Aufgabe vom 8. Juni<\/i><br \/>\nFragestellung: Heiliger Strohsack! Das ist ein Kriegsinstrument!<br \/>\nAntwort: Lass Willie Dudelsack spielen. Dauer der Aufgabe betr\u00c3\u00a4gt 60 Minuten.<\/p>\n<p><i>7. Aufgabe vom 9. Juni<\/i><br \/>\nFragestellung: Das schlimmste Kost\u00c3\u00bcm ist das, das man sich selber macht.<br \/>\nAntwort: Lass den Comicverk\u00c3\u00a4ufer Kost\u00c3\u00bcmspiel betreiben. Dauer der Aufgabe betr\u00c3\u00a4gt 12 Stunden.<\/p>\n<p><i>8. Aufgabe 10. Juni<\/i><br \/>\nFragestellung: Was ist schwarz und wei\u00c3\u0178 und wird \u00c3\u00bcberall mit hingenommen?<br \/>\nAntwort: Lass Moe gef\u00c3\u00a4hrdete Arten schmuggeln. Dauer der Aufgabe betr\u00c3\u00a4gt 8 Stunden.<\/p>\n<p><i>9. Aufgabe 11. Juni<\/i><br \/>\nFragestellung: ein netter Zeitvertreib l\u00c3\u00a4sst deine Vorurteile zur Religion auf Abstellgleis fahren.<br \/>\nAntwort: Lass Reverend Lovejoy Modellbahn fahren. Dauer der Aufgabe betr\u00c3\u00a4gt 6 Stunden.<\/p>\n<p><i>10. Aufgabe 12. Juni<\/i><br \/>\nFragestellung: Zwei R\u00c3\u00a4der transportieren den Sohn eines K\u00c3\u00b6nigs.<br \/>\nAntwort: Lass Martin Fahrrad fahren. Dauer der Aufgabe betr\u00c3\u00a4gt 8 Stunden.<\/p>\n<p><i>11. Aufgabe 13. Juni<\/i><br \/>\nFragestellung: Es w\u00c3\u00a4re ein Verbrechen, diese Kunststunde zu schw\u00c3\u00a4nzen.<br \/>\nAntwort: Lass Marge den Kunstunterricht geben. Dauer der Aufgabe betr\u00c3\u00a4gt 6 Stunden.<\/p>\n<p><i>12. Aufgabe 14 Juni<\/i><br \/>\nFragestellung: Vier R\u00c3\u00a4der transportieren den Sohn  eines griechischen Dichters.<br \/>\nAntwort: Lass Bart Skateboard fahren. Dauer der Aufgabe betr\u00c3\u00a4gt 4 Stunden.<\/p>\n<p><i>13. Aufgabe 15. Juni<\/i><br \/>\nFragestellung: Die Schlange hat eine M\u00c3\u00a4hne, die gepflegt werden muss.<br \/>\nAntwort: Lass Snake krasse Haare k\u00c3\u00a4mmen. Dauer der Aufgabe betr\u00c3\u00a4gt 45 Sekunden.<\/p>\n<p><i>14. Aufgabe 16. Juni<\/i><br \/>\nFragestellung: Daddy braucht ein neus Paar Schuhe in Riesengr\u00c3\u00b6\u00c3\u0178e.<br \/>\nAntwort: Lass Krusty die Strecke besuchen. Dauer der Aufgabe 3 Stunden.<\/p>\n<p><i>15. Aufgabe 17. Juni<\/i><br \/>\nFragestellung: Geheimnisse, die nicht heimlich sind, sind Abfall!<br \/>\nAntwort: Lass Mr. Burns den Atomm\u00c3\u00bcll verstecken. Dauer der Aufgabe betr\u00c3\u00a4gt 8 Stunden.<\/p>\n<p><i>16. Aufgabe 18. Juni<\/i><br \/>\nFragestellung: Ein \\&#8221;Flammender Moe\\&#8221; riecht stark nach Alkohol.<br \/>\nAntwort: Smithers, Whip It! Dauer der Aufgabe betr\u00c3\u00a4gt 8 Stunden.<\/p>\n<p><i>17. Aufgabe 19. Juni<\/i><br \/>\nFragestellung: Pyromanen gehen gerne in die Schuhle!<br \/>\nAntwort: Lass Ralph Dinge verbrennen. Dauer der Aufgabe betr\u00c3\u00a4gt 8 Stunden.<\/p>\n<p><i>18. Aufgabe 20. Juni<\/i><br \/>\nFragestellung: Na, das ist ja mal ein gesalzenes Schifferklavier!<br \/>\nAntwort: Lass Luigi Akkordeon spielen. Dauer der Aufgabe betr\u00c3\u00a4gt 12 Stunden.<\/p>\n<p><i>19. Aufgabe 21. Juni<\/i><br \/>\nFragestellung: Mandela manipuliert eine moderne Mandoline<br \/>\nAntwort: Lass Nelson Gitarre spielen. Dauer der Aufgabe betr\u00c3\u00a4gt 8 Stunden.<\/p>\n<p><i>20. Aufgabe 22. Juni<\/i><br \/>\nFragestellung: Er kommuniziert mit seinen Vorfahren in einer nordischen Sprache.<br \/>\nAntwort: Lass Carl seine isl\u00c3\u00a4ndische Herkunft w\u00c3\u00bcrdigen. Dauer der Aufgabe betr\u00c3\u00a4gt 24 Stunden.<\/p>\n<p><i>21. Aufgabe 23. Juni<\/i><br \/>\nFragestellung: Liebe hat keinen Preis, aber jedes Herz ist k\u00c3\u00a4uflich.<br \/>\nAntwort: Lass Dr. Hibbert Organe auf dem Schwarzmarkt handeln. Dauer der Aufgabe betr\u00c3\u00a4gt 4 Stunden.<\/p>\n<p><i>22. Aufgabe 24. Juni<\/i><br \/>\nFragestellung: Wort f\u00c3\u00bcr eine griesgr\u00c3\u00a4mige, alte Frau mit f\u00c3\u00bcnf Buchstaben. Zweiter Buchstabe: \\&#8221;G\\&#8221;.<br \/>\nAntwort: Lass Agnes Kreuzwortr\u00c3\u00a4tsel l\u00c3\u00b6sen. Dauer der Aufgabe betr\u00c3\u00a4gt 8 Stunden.<\/p>\n<p><i>23. Aufgabe 25. Juni<\/i><br \/>\nFragestellung: Ein musikalisches Angebot, das du nicht ablehnen kannst.<br \/>\nAntwort: Lass Fat Tony Geige spielen. Dauer der Aufgabe 60 Minuten.<\/p>\n<p><i>24. Aufgabe 26. Juni<\/i><br \/>\nFragestellung: Eine fehlende Gliedma\u00c3\u0178e klingt nach schlechten Genen<br \/>\nAntwort: Lass Herman gef\u00c3\u00a4lschte Jeans verkaufen. Dauer der Aufgabe betr\u00c3\u00a4gt 16 Stunden. <\/p>\n<p><b>Holt euch die Antwort von morgen schon heute!<\/b><br \/>\nWir ver\u00c3\u00b6ffentlichen schon immer einen Tag im voraus die L\u00c3\u00b6sung der Heiligen Pergament-Aufgabe von Die Simpsons Springfield. Schaut am besten jeden Tag vorbei und holt euch so immer direkt die passenden L\u00c3\u00b6sungen. Liked auch gerne unsere Facebook-Seite, wenn ihr auch in Zukunft \u00c3\u00bcber das Spiel auf dem Laufenden bleiben m\u00c3\u00b6chtet: <\/p>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Im Smartphone- und Tablet-Game Die Simpsons Springfield l\u00c3\u00a4uft aktuell das Steinmetze-Event. Wir sammeln in diesem Artikel alle&#8230; Mehr auf Newsslash.com!<\/p>\n","protected":false},"author":4,"featured_media":4625,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-4626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Die Simpsons Springfield Steinmetze Guide: Heiliges Perga... - Newsslash<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Simpsons Springfield Steinmetze Guide: Heiliges Perga... - Newsslash\" \/>\n<meta property=\"og:description\" content=\"Im Smartphone- und Tablet-Game Die Simpsons Springfield l\u00c3\u00a4uft aktuell das Steinmetze-Event. Wir sammeln in diesem Artikel alle... Mehr auf Newsslash.com!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/\" \/>\n<meta property=\"og:site_name\" content=\"Newsslash\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-16T16:05:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-07T12:04:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_3340.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"617\" \/>\n\t<meta property=\"og:image:height\" content=\"349\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christina B\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christina B\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/\"},\"author\":{\"name\":\"Christina B\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/d091f5c44e30328c391ba075ee1b88d3\"},\"headline\":\"Die Simpsons Springfield Steinmetze Guide: Heiliges Perga&#8230;\",\"datePublished\":\"2014-06-16T16:05:00+00:00\",\"dateModified\":\"2025-04-07T12:04:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/\"},\"wordCount\":889,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_3340.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/\",\"url\":\"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/\",\"name\":\"Die Simpsons Springfield Steinmetze Guide: Heiliges Perga... - Newsslash\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_3340.jpg\",\"datePublished\":\"2014-06-16T16:05:00+00:00\",\"dateModified\":\"2025-04-07T12:04:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/#primaryimage\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_3340.jpg\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_3340.jpg\",\"width\":617,\"height\":349},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsslash.com\/n\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Simpsons Springfield Steinmetze Guide: Heiliges Perga&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsslash.com\/n\/#website\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"name\":\"Newsslash\",\"description\":\"Trending News on Movies, Series, OTT, Gaming\",\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsslash.com\/n\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsslash.com\/n\/#organization\",\"name\":\"Newsslash\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"width\":512,\"height\":512,\"caption\":\"Newsslash\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/d091f5c44e30328c391ba075ee1b88d3\",\"name\":\"Christina B\",\"sameAs\":[\"https:\/\/newsslash.com\"],\"url\":\"https:\/\/newsslash.com\/n\/author\/christina_b\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Simpsons Springfield Steinmetze Guide: Heiliges Perga... - Newsslash","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Die Simpsons Springfield Steinmetze Guide: Heiliges Perga... - Newsslash","og_description":"Im Smartphone- und Tablet-Game Die Simpsons Springfield l\u00c3\u00a4uft aktuell das Steinmetze-Event. Wir sammeln in diesem Artikel alle... Mehr auf Newsslash.com!","og_url":"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/","og_site_name":"Newsslash","article_published_time":"2014-06-16T16:05:00+00:00","article_modified_time":"2025-04-07T12:04:02+00:00","og_image":[{"width":617,"height":349,"url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_3340.jpg","type":"image\/jpeg"}],"author":"Christina B","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Christina B","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/#article","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/"},"author":{"name":"Christina B","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/d091f5c44e30328c391ba075ee1b88d3"},"headline":"Die Simpsons Springfield Steinmetze Guide: Heiliges Perga&#8230;","datePublished":"2014-06-16T16:05:00+00:00","dateModified":"2025-04-07T12:04:02+00:00","mainEntityOfPage":{"@id":"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/"},"wordCount":889,"commentCount":0,"publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"image":{"@id":"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_3340.jpg","articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/","url":"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/","name":"Die Simpsons Springfield Steinmetze Guide: Heiliges Perga... - Newsslash","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/#primaryimage"},"image":{"@id":"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_3340.jpg","datePublished":"2014-06-16T16:05:00+00:00","dateModified":"2025-04-07T12:04:02+00:00","breadcrumb":{"@id":"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/#primaryimage","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_3340.jpg","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_3340.jpg","width":617,"height":349},{"@type":"BreadcrumbList","@id":"https:\/\/newsslash.com\/n\/3340-die-simpsons-springfield-steinmetze-guide-heiliges-pergament-aufgaben-und-loesungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsslash.com\/n\/"},{"@type":"ListItem","position":2,"name":"Die Simpsons Springfield Steinmetze Guide: Heiliges Perga&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/newsslash.com\/n\/#website","url":"https:\/\/newsslash.com\/n\/","name":"Newsslash","description":"Trending News on Movies, Series, OTT, Gaming","publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsslash.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/newsslash.com\/n\/#organization","name":"Newsslash","url":"https:\/\/newsslash.com\/n\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","width":512,"height":512,"caption":"Newsslash"},"image":{"@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/d091f5c44e30328c391ba075ee1b88d3","name":"Christina B","sameAs":["https:\/\/newsslash.com"],"url":"https:\/\/newsslash.com\/n\/author\/christina_b\/"}]}},"_links":{"self":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/4626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/comments?post=4626"}],"version-history":[{"count":1,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/4626\/revisions"}],"predecessor-version":[{"id":4627,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/4626\/revisions\/4627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media\/4625"}],"wp:attachment":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media?parent=4626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}