{"id":6126,"date":"2014-12-16T23:48:00","date_gmt":"2014-12-16T23:48:00","guid":{"rendered":"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/"},"modified":"2014-12-16T23:48:00","modified_gmt":"2014-12-16T23:48:00","slug":"4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app","status":"publish","type":"post","link":"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/","title":{"rendered":"Instagram Anleitung: Ein Guide mit Tipps und Tricks zur App"},"content":{"rendered":"<p>Ihr habt unz\u00c3\u00a4hlige Fotos und w\u00c3\u00bcrdet diese gerne mit euren Freunden und anderen Personen \u00c3\u00bcber das Internet teilen? Dann wird euch die App Instagram, welche mitterweile auch zu Facebook geh\u00c3\u00b6rt, auf alle F\u00c3\u00a4lle gefallen. Doch daf\u00c3\u00bcr m\u00c3\u00bcsst ihr euch die App als erstes herunterladen. Instagram k\u00c3\u00b6nnt ihr euch sowohl \u00c3\u00bcber den Apple App Store f\u00c3\u00bcr euer iOS iPad oder iPhone als auch \u00c3\u00bcber den Google Play Store f\u00c3\u00bcr euer Android Ger\u00c3\u00a4t downloaden. Aber auch Windows Phone-Nutzer k\u00c3\u00b6nnen sich freuen, denn auch sie k\u00c3\u00b6nnen sich die App f\u00c3\u00bcr ihr Windows-Phone herunterladen. Egal f\u00c3\u00bcr welches Betriebssystem ihr die App downloadet, sie ist immer kostenlos. In den folgenden Abschnitten wollen wir euch erkl\u00c3\u00a4ren, wie ihr die App richtig nutzen k\u00c3\u00b6nnt. Dabei gehen wir zum Beispiel darauf ein, wie man Fotos und Videos macht, sie online stellt und gegebenenfalls auch wieder l\u00c3\u00b6scht. Aber auch andere Features werden in diesem Artikel betrachtet. Instagram Tipps und Tricks sind au\u00c3\u0178erdem mit enthalten. <b>Fotos und Videos auf Instagram machen, hochladen und auf anderen Plattformen teilen<\/b> Nachdem ihr euch die App heruntergeladen und auch ge\u00c3\u00b6ffnet habt, k\u00c3\u00b6nnt ihr sofort loslegen und flei\u00c3\u0178ig eure sch\u00c3\u00b6nsten Fotos und Videos bearbeiten und teilen. Daf\u00c3\u00bcr m\u00c3\u00bcsst ihr einfach den Button in der Mitte unten anklicken. Je nach Betriebssystem sieht der Button wie das Instagram-Logo aus. <\/p><div class=\"newss-content\" id=\"newss-896242918\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-7733425960004873\" \ndata-ad-slot=\"2582020599\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div class=\"newss-article-1\" id=\"newss-1710231474\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Homepage2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7733425960004873\"\r\n     data-ad-slot=\"2582020599\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div>\n<div><span>Bilder auf Instagram ver\u00c3\u00b6ffentlichen &#8211; So funktioniert es!<\/span><\/div>\n<p> Klickt den Button an, und ihr gelangt in die Kamera\u00c3\u00bcbersicht. Jetzt hab ihr zwei M\u00c3\u00b6glichkeiten, wie ihr Bilder und Videos auf Instagram hochladen k\u00c3\u00b6nnt. Zum einen k\u00c3\u00b6nnt ihr sofort ein Bild oder Video erstellen, bearbeiten und uploaden oder ihr sucht euch einfach ein Video oder Bild aus eurer Galerie aus und ladet dieses hoch. Beim n\u00c3\u00a4chsten Schritt ist es egal, ob ihr ein Foto oder Video \u00c3\u00bcber die App geschossen habt oder es \u00c3\u00bcber eure Galerie benutzt. Denn jetzt d\u00c3\u00bcrft ihr euer Kunstwerk durch unterschiedliche Filter versch\u00c3\u00b6nern und nach euren W\u00c3\u00bcnschen anpassen. Bildern k\u00c3\u00b6nnt ihr au\u00c3\u0178erdem nicht nur Filter verpassen sondern auch die Helligkeit und die Sch\u00c3\u00a4rfe nachstellen. Seid ihr fertig mit der Bearbeitung, dann klickt einfach weiter. Nun k\u00c3\u00b6nnt ihr eurem Werk eine \u00c3\u0153berschrift oder einen kurzen Text beif\u00c3\u00bcgen. Aber ihr habt in dieser \u00c3\u0153bersicht auch die Chance, den Ort, an dem das Foto aufgenommen wurde, beizuf\u00c3\u00bcgen. Dieser erscheint dann auf eurer Fotokarte. Seid ihr auf dem Foto oder Video nicht allein zu sehen, so k\u00c3\u00b6nnt ihr falls es sich ebenfalls um einen Instagram-Nutzer handelt, diesen auf dem Bild markieren. Habt ihr alles bearbeitet und beschriftet, k\u00c3\u00b6nnt ihr nun entscheiden, ob ihr euer Bild oder Video f\u00c3\u00bcr alle freischaltet oder nur bestimmte Personen aus eurer Folgen-Liste einen Blick auf dieses Bild werfen d\u00c3\u00bcrfen. Au\u00c3\u0178erdem k\u00c3\u00b6nnt ihr an dieser Stelle auch entscheiden, ob ihr euren Schnappschuss eventuell auch auf Facebook, Tumblr oder Twitter teilen m\u00c3\u00b6chtet. Sind alle Einstellungen erledigt, k\u00c3\u00b6nnt ihr das Video oder Bild durch einen weiteren klick hochladen. Wenn ihr eure Aufnahme \u00c3\u00b6ffentlich gepostet habt, erscheint dieses an oberster Stelle in eurer \u00c3\u0153bersichtsliste mit all den Menschen, denen ihr folgt. Zus\u00c3\u00a4tzlich wird euer Bild dann auch bei anderen Personen angezeigt, welche euch folgen oder nach diesem Bild suchen. <b>Instagram Fotos bearbeiten<\/b> Wie weiter oben bereits beschrieben, k\u00c3\u00b6nnt ihr \u00c3\u00bcber die App Instagram eure Fotos und Bilder durch unz\u00c3\u00a4hlige Filter versch\u00c3\u00b6nern. Daf\u00c3\u00bcr m\u00c3\u00bcsst ihr entweder direkt \u00c3\u00bcber die App euer Wunschmotiv fotografieren oder einfach eins aus eurer Galerie heraussuchen. Habt ihr euch f\u00c3\u00bcr ein Motiv entschieden und ausgew\u00c3\u00a4hlt, so k\u00c3\u00b6nnt ihr es nun bearbeiten. So k\u00c3\u00b6nnt ihr zum Beispiel unterschiedlichste Filter \u00c3\u00bcber euer Bild legen. Hierbei k\u00c3\u00b6nnt ihr unter anderem zwischen Amaro, Mayfair und mehr w\u00c3\u00a4hlen. Probiert einfach mal aus, welchen Filter ihr am besten findet. Aber nat\u00c3\u00bcrlich, k\u00c3\u00b6nnt ihr euer Foto auch ganz einfach ohne jeglichen Filter einstellen. Habt ihr einen passenden Filter gefunden oder wollt ihr einfach nur zum Beispiel die Helligkeit eures Fotos etwas anheben, so k\u00c3\u00b6nnt ihr das \u00c3\u00bcber Instagram ebenfalls tun. Klickt daf\u00c3\u00bcr im Bearbeitungsmodus auf den Schraubenschl\u00c3\u00bcsse. Habt ihr das getan, so findet ihr dort Optionen wie Helligkeit, Kontrast usw. Ist das Foto fertig bearbeitet, dann klickt auf weiter. Jetzt m\u00c3\u00bcsst ihr nur noch eine Beschreibung hinzuf\u00c3\u00bcgen und best\u00c3\u00a4tigen, schon erscheint euer Pic in eurer \u00c3\u0153bersichtsleiste. <b>Instagram Videos aufnehmen und bearbeiten<\/b> Wie beim Foto, so k\u00c3\u00b6nnt ihr auch bei einem Video einfach direkt \u00c3\u00bcber Instagram eins aufnehmen oder ihr ladet einfach eins aus eurer Galerie hoch. Entscheidet ihr euch f\u00c3\u00bcr die Variante, selbst ein Video aufzunehmen, dann dr\u00c3\u00bcckt wie gewohnt auf den Aufnahmebutton und gelang in die Aufnahme\u00c3\u00bcbersicht. Dort findet ihr ein Kamera-Symbol. Klickt dieses an und wechselt somit vom Foto- in den Aufnahmemodus. Dr\u00c3\u00bcckt auf den roten Button in der Mitte und haltet ihn gedr\u00c3\u00bcckt, solange ihr aufnehmt. Beachtet dabei aber, dass euer Video mindestens 3 und h\u00c3\u00b6chsten 15 Sekunden lang sein darf. <\/p>\n<div><span>Auch Instagram Videos k\u00c3\u00b6nnen bearbeitet werden!<\/span><\/div>\n<p> Wollt ihr eines eure bestehenden Videos verwenden, dann w\u00c3\u00a4hlt es aus der Galerie aus. Ist das Video l\u00c3\u00a4nger als 15 Sekunden, dann m\u00c3\u00bcsst ihr es auf die richtige L\u00c3\u00a4nge schneiden. Dabei k\u00c3\u00b6nnt ihr entweder die ersten 15 Sekunden des Videos nehmen oder ihr schiebt den Video-Regler so lange weiter, bis ihr genau die Stelle habt, die ihr haben wollt. Aber auch hier hei\u00c3\u0178t es wieder, dass Video muss mindestens 3 Sekunden lang sein, sonst k\u00c3\u00b6nnt ihr es nicht nehmen. Habt ihr euer Wunschvideo, dann habt ihr ebenfalls die M\u00c3\u00b6glichkeit, dieses etwas zu bearbeiten. Allerdings stehen euch daf\u00c3\u00bcr nur die Filter zur Auswahl, welche bereits bei den Fotos beschrieben wurden. Helligkeit und Kontrast k\u00c3\u00b6nnt ihr in Instagram-Videos nicht bearbeiten. Jetzt habt ihr noch die M\u00c3\u00b6glichkeit, eurem Videoe ein Titelbild zu verpassen. Dieses sucht ihr ganz einfach aus eurem Video aus. Klickt im Bearbeitungsmen\u00c3\u00bc einfach auf den Button Titelbild w\u00c3\u00a4hlen. Seid ihr im passenden Men\u00c3\u00bc, so seht ihr verschiedene Bildschnippsel aus eurem Video. Sucht einfach ein Bild aus den ganzen aus und macht es zu eurem Titelbild. Habt ihr euer Video fertig bearbeitet, dann klickt auf weiter und f\u00c3\u00bcgt eurem Video eine Beschreibung wie bei den Bildern bei. Jetzt nur noch auf ver\u00c3\u00b6ffentlichen klicken und voil\u00c3 , schon erscheint euer Video in eurer Haupt\u00c3\u00bcbersicht an erster Stelle. <b>Beitr\u00c3\u00a4ge und Bilder auf Instagram l\u00c3\u00b6schen<\/b> Hab ihr ein Video oder Foto auf Instagram ver\u00c3\u00b6ffentlicht, welches ihr gerne l\u00c3\u00b6schen m\u00c3\u00b6chtet? Dann funktioniert dies wie folgt! Ihr m\u00c3\u00bcsst hierf\u00c3\u00bcr einfach den Home-Button anklicken. Dieser befindet sich sowohl bei Android als auch bei iOS Ger\u00c3\u00a4ten ganz rechts. Seid ihr nun in eurem Profil, so seht ihr als aller erstes links oben euer Profilbild und darunter eine kurze Beschreibung \u00c3\u00bcber euch, falls ihr eine eingef\u00c3\u00bcgt habt. Rechts seht ihr die Anzahl eurer Beitr\u00c3\u00a4ge, wie viele Leute eure Seite abonniert habe und wie viele Nutzer ihr abonniert habt. <\/p>\n<div><span>Instagram Bilder und Beitr\u00c3\u00a4ge wieder l\u00c3\u00b6schen<\/span><\/div>\n<p> Unter euren Angaben ist eine Leiste, wo ihr einstellen k\u00c3\u00b6nnt, ob die Bilder als Kacheln angezeigt werden sollen oder untereinander. Dann ist dort noch ein Symbol f\u00c3\u00bcr die Fotokarte, dort wird angezeigt, wo ihr die Bilder aufgenommen habt, voraussichtlich ihr habt diese Funktion gew\u00c3\u00a4hlt. Zu guter Letzt habt ihr in dieser Leiste noch die Angabe, auf welchen Fotos ihr markiert wurdet. Unter der Leiste seht ihr dann eure ganzen Fotos und Videos. Sucht nun das Foto oder Video, welches ihr l\u00c3\u00b6schen wollt und klickt es an. Dieses wird nun komplett mit allen Likes und Kommentaren ge\u00c3\u00b6ffnet. Damit ihr das Video oder Foto nun l\u00c3\u00b6schen k\u00c3\u00b6nnt, m\u00c3\u00bcsst ihr solange runterscrollen, bis ihr drei kleine Punkte seht. Klickt diesen Button an. Sogleich \u00c3\u00b6ffnet sich eine \u00c3\u0153bersicht, in der ihr die ausgew\u00c3\u00a4hlte Aufnahme l\u00c3\u00b6schen, teilen oder als URL kopieren k\u00c3\u00b6nnt. W\u00c3\u00a4hlt l\u00c3\u00b6schen aus und l\u00c3\u00b6scht dadurch ganz einfach das gew\u00c3\u00bcnschte Objekt. <b>Aufnahmen auf Instagram liken und kommentieren<\/b> Der Spa\u00c3\u0178 an Instagram liegt nicht nur daran, eine Aufnahmen zu machen und diese zu teilen, sondern auch daran, Freunden und anderen Instagram-Nutzern zu folgen und zu sehen, was sie auf Instagram hochladen. In der \u00c3\u0153bersichtsliste, die bei jedem \u00c3\u2013ffnen der App als erstes erscheint, findet ihr die neuesten Eintr\u00c3\u00a4ge der Leute denen ihr folgt. Scrollt euch einfach durch und erkundet was eure Freunde und Nutzer denen ihr folgt, neues zu zeigen haben. Habt ihr ein besonders sch\u00c3\u00b6nes Exemplar eines Video oder eines Foto gefunden, so k\u00c3\u00b6nnt ihr es durch ein Herzchen liken oder auch einen Kommentar unter dem Foto hinterlassen. Achtet beim kommentieren darauf, dass ihr den Namen einer Person mit einem vorgestellten @ schreiben m\u00c3\u00bcsst, damit diese Person auch korrekt verlinkt wird. Setzt ihr n\u00c3\u00a4mlich ein @ vor dem Namen der angeschriebenen Person, so erh\u00c3\u00a4lt diese eine Benachrichtigung \u00c3\u00bcber ihre Erw\u00c3\u00a4hnung in einem Kommentar. Doch aufgepasst! Hier ist es wichtig, dass zwischen dem @ und dem Namen kein Leerzeichen ist. Rutscht n\u00c3\u00a4mlich ein Leerzeichen zwischen Name und @, so verliert das @ seine Wirkung und die Person, die ihr ansprechen wollt, bekommt keine Benachrichtigung und erf\u00c3\u00a4hrt niemals, dass ihr sie angeschrieben hat; au\u00c3\u0178er der Beitrag den ihr Kommentiert kommt genau von dieser Person. <b>Was ist der Instagram Hashtag?<\/b> Zu Beginn ist einmal wichtig zu wissen, dass der Hashtag durch das Rautezeichen \u00e2\u20ac\u017e#\u00e2\u20ac\u0153 dargestellt wird. \u00c3\u201ehnlich wie das @-Zeichen, so setzt man das #-Zeichen vor ein Wort, welches man herausheben m\u00c3\u00b6chte. Wird durch das @-Zeichen eine bestimmte Person angesprochen, so hebt der Hashtag ein bestimmtes Wort heraus. Hierbei ist es ebenfalls wie bei dem @-Zeichen wichtig, dass wischen dem #-Zeichen und dem Text kein Leerzeichen steht. Wollt ihr mehrere W\u00c3\u00b6rter durch einen Hashtag markieren, dann m\u00c3\u00bcsst ihr diese hintereinander schreiben, ohne ein Leerzeichen zu setzten oder einwach mehrere W\u00c3\u00b6rter mit einem eigenen Rautezeichen versehen. <\/p>\n<div><span>Welchen Nutzern haben Instagram Hashtags und wie funktionieren diese?<\/span><\/div>\n<p> Beschreibt man eines seiner eigenen Fotos oder Videos, oder kommentiert man ein Video oder Bild eines anderen Nutzers und m\u00c3\u00b6chte ein bestimmtes Wort herausheben, so setzt man wie oben bereits beschrieben, einen Hashtag vor das Wort. Suchen nun andere Nutzer genau nach diesem Wort, welches ihr durch ein #-Zeichen markiert habt, so wird diesen auch euer Hashtag und das damit verbundene Video oder Bild in der Suchfunktion angezeigt. Habt ihr zum Beispiel ein Foto von eurer Katze gemacht, so k\u00c3\u00b6nnte die Beschreibung unter eurem Foto lauten: \u00e2\u20ac\u017eDies ist meine s\u00c3\u00bc\u00c3\u0178e #Katze Lulu\u00e2\u20ac\u0153. Das Wort Katze wurde durch einen Hashtag markiert. Suchen nun andere nach dem Wort Katze, so wir auch euer Bild unter dem Suchbegriff Katze erscheinen. Dadurch habt ihr eine h\u00c3\u00b6here Wahrscheinlichkeit von anderen Nutzern entdeckt zu werden und somit schneller eine gr\u00c3\u00b6\u00c3\u0178ere Fan-Gemeinde zu erreichen. <b>Instagram Freunde finden und ihnen folgen<\/b> Einfach Bilder oder Videos auf Instagram reinzustellen und diese mit keine Teilen zu k\u00c3\u00b6nnen, w\u00c3\u00a4re fad. Daher hat die App die Funktion, dass man Freunde suchen und ihnen folgen kann. Dadurch erfahrt ihr immer, was diese tun und welche Fotos und Videos sie auf Instagram teilen. Eure Freunde k\u00c3\u00b6nnen euch nat\u00c3\u00bcrlich ebenfalls folgen um zu erfahren, was ihr so erlebt und welche Fotos und Videos ihr auf Instagram stellt. Damit ihr eure Freunde finden k\u00c3\u00b6nnt, m\u00c3\u00bcsst ihr als aller erstes auf euer Profil in der App klicken. Wenn ihr euch auf eurem Profil befindet, so m\u00c3\u00bcsst ihr rechts oben auf die Punkte oder das Zahnrad klicken. Habt ihr das getan, so gelangt ihr zu den Optionen. Dort k\u00c3\u00b6nnt ihr zum Beispiel euer Profilbild \u00c3\u00a4ndern, euch ausloggen oder andere Einstellungen \u00c3\u00a4ndern. Aber ihr findet dort auch die Option Freunde finden. Jetzt m\u00c3\u00bcsst ihr nur noch auf Freunde finden klicken und gelangt ins \u00e2\u20ac\u017eFreunde finden\u00e2\u20ac\u0153-Men\u00c3\u00bc. Um Freunde zu finden, m\u00c3\u00bcsst ihr entweder deren Instagram-Nicknamen kennen, oder ihr verbindet Instagram einfach zum Beispiel mit eurem Facebook-Account. Durch das Verbinden mit Facebook, werden euch alle eure Freunde angezeigt, die ebenfalls einen Instagram-Account besitzen und diesen mit ihrem Facebook-Account verbunden haben. Jetzt m\u00c3\u00bcsst ihr nur noch entscheiden, welchen eurer Facebook-Freunde ihr auch auf Instagram folgen wollt. Klickt nun den Button Folgen an und schon folgt ihr euren Freunden. Wobei hier noch kurz unterschieden werden muss, dass manche eurer Freunde ihr Profil vielleicht auf Privat gestellt haben. Diese m\u00c3\u00bcssen eure Folgen-Anfrage erst best\u00c3\u00a4tigen, bevor ihr ihnen auch wirklich folgen und sehen k\u00c3\u00b6nnt, was diese auf Instagram ver\u00c3\u00b6ffentlichen. Folgt ihr einem eurer Freunde, so hei\u00c3\u0178t es aber noch lange nicht, dass dieser euch ebenfalls folgt. <b>Anderen Instagram-Nutzern folgen<\/b> Zahlreiche bekannte Pers\u00c3\u00b6nlichkeiten wie Heidi Klum, Miley Cyrus, Kim Kardashian oder Justin Bieber sind ebenfalls sehr aktiv auf Instagram dabei. W\u00c3\u00bcrdet ihr also gerne wissen, was sie so mit der Instagram-Community teilen, dann k\u00c3\u00b6nnt ihr auch diesen jederzeit folgen. Daf\u00c3\u00bcr m\u00c3\u00bcsst auf der Leiste ganz unten den zweiten Button von links anklicken. In diesem Men\u00c3\u00bc werden euch zahlreiche Bilder anderer Nutzer angezeigt. Findet ihr ein besonders sch\u00c3\u00b6nes Exemplar, k\u00c3\u00b6nnt ihr dieses anklicken und es entweder kommentieren oder es mit einem like-Herz versehen. Wollt ihr nun wissen, welche Bilder der Nutzer sonst noch gemacht hat, dann m\u00c3\u00bcsst ihr ganz einfach den Namen des Nutzers den ihr \u00c3\u00bcber dem Bild oder Video findet, anklicken. So gelangt ihr auf die Profilseite dieser Person. Die Profilseite dieses Nutzers ist dabei genauso aufgebaut wie eure und ihr k\u00c3\u00b6nnt dort ebenfalls alle Bilder und Videos erkennen, aber auch sehen, welchen Personen der Nutzer folgt und welche ihm folgen. So k\u00c3\u00b6nnt ihr euch ganz einfach durch die Leute klicken und denen folgen, die ihr interessant findet. Kommen wir aber zur\u00c3\u00bcck dazu, wie ihr eine bestimmte Person finden k\u00c3\u00b6nnt. Wenn ihr euch im Such-Men\u00c3\u00bc befindet, so k\u00c3\u00b6nnt ihr oben in der Suchleiste einfach den Namen der gesuchten Person eingeben und auf suchen klicken. Sogleich werden euch alle Personen mit dem Namen, den ihr eingegeben habt, angezeigt. Sucht euch jetzt einfach nur die Seite eures Lieblingsstars heraus und folgt diesem. \u00c3\u0153ber die Suchfunktion k\u00c3\u00b6nnt ihr aber auch nach einem bestimmten Hashtag suchen. Daf\u00c3\u00bcr gebt ihr in die Suchleiste einfach den gew\u00c3\u00bcnschten Begriff ein und schaltet von Person auf Hashtag um. Jetzt seht ihr alle Hashtags die mit eurem Begriff zu tun haben. Klick einen an und sofort seht ihr alle Bilder und Videos, die mit diesem Hashtag versehen wurden. <b>Instagram Account l\u00c3\u00b6schen \/ deaktivieren<\/b> Wollt ihr nicht mehr auf Instagram aktiv sein und w\u00c3\u00bcrdet gerne euren Account auf Instagram komplett l\u00c3\u00b6schen, so ist dies nat\u00c3\u00bcrlich auch m\u00c3\u00b6glich. Allerdings k\u00c3\u00b6nnt ihr dies leider nicht direkt \u00c3\u00bcber die App machen. Um euren Account zu l\u00c3\u00b6schen, m\u00c3\u00bcsst ihr euch an eurem Rechner \u00c3\u00bcber den Browser auf Instagram einloggen. Klickt nun oben rechts den Button mit eurem Profilbild und Nicknamen an. Habt ihr das getan, m\u00c3\u00bcsst ihr auf Profil bearbeiten gehen. Im Profil bearbeiten seht ihr rechst unten \u00e2\u20ac\u017eIch m\u00c3\u00b6chte mein Konto l\u00c3\u00b6schen\u00e2\u20ac\u0153. Klickt dort drauf. Nun m\u00c3\u00bcsst ihr unter \u00e2\u20ac\u017eBitte teile uns mit, warum du uns verl\u00c3\u00a4sst\u00e2\u20ac\u0153 einen Grund ausw\u00c3\u00a4hlen, wieso ihr euren Instagram-Account l\u00c3\u00b6schen wollt. Habt ihr das getan, so m\u00c3\u00bcsst ihr nur noch euer Passwort ins entsprechende Fenster eintragen und auf den roten Button \u00e2\u20ac\u017eMein Konto dauerhaft deaktivieren klicken\u00e2\u20ac\u0153. Jetzt wurde euer Account deaktiviert.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Instagram z\u00c3\u00a4hlt zu den beliebtesten Anwendungen, um Fotos und Videos \u00c3\u00bcber das eigene Smartphone zu teilen. Wir erkl\u00c3\u00a4ren euch in&#8230; Mehr auf Newsslash.com!<\/p>\n","protected":false},"author":4,"featured_media":21974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-6126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Instagram Anleitung: Ein Guide mit Tipps und Tricks zur App - Newsslash<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Instagram Anleitung: Ein Guide mit Tipps und Tricks zur App - Newsslash\" \/>\n<meta property=\"og:description\" content=\"Instagram z\u00c3\u00a4hlt zu den beliebtesten Anwendungen, um Fotos und Videos \u00c3\u00bcber das eigene Smartphone zu teilen. Wir erkl\u00c3\u00a4ren euch in... Mehr auf Newsslash.com!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/\" \/>\n<meta property=\"og:site_name\" content=\"Newsslash\" \/>\n<meta property=\"article:published_time\" content=\"2014-12-16T23:48:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christina B\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christina B\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/\"},\"author\":{\"name\":\"Christina B\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/d091f5c44e30328c391ba075ee1b88d3\"},\"headline\":\"Instagram Anleitung: Ein Guide mit Tipps und Tricks zur App\",\"datePublished\":\"2014-12-16T23:48:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/\"},\"wordCount\":2610,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/\",\"url\":\"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/\",\"name\":\"Instagram Anleitung: Ein Guide mit Tipps und Tricks zur App - Newsslash\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"datePublished\":\"2014-12-16T23:48:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/#primaryimage\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg\",\"width\":1280,\"height\":854},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsslash.com\/n\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Instagram Anleitung: Ein Guide mit Tipps und Tricks zur App\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsslash.com\/n\/#website\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"name\":\"Newsslash\",\"description\":\"Trending News on Movies, Series, OTT, Gaming\",\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsslash.com\/n\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsslash.com\/n\/#organization\",\"name\":\"Newsslash\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"width\":512,\"height\":512,\"caption\":\"Newsslash\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/d091f5c44e30328c391ba075ee1b88d3\",\"name\":\"Christina B\",\"sameAs\":[\"https:\/\/newsslash.com\"],\"url\":\"https:\/\/newsslash.com\/n\/author\/christina_b\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Instagram Anleitung: Ein Guide mit Tipps und Tricks zur App - Newsslash","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Instagram Anleitung: Ein Guide mit Tipps und Tricks zur App - Newsslash","og_description":"Instagram z\u00c3\u00a4hlt zu den beliebtesten Anwendungen, um Fotos und Videos \u00c3\u00bcber das eigene Smartphone zu teilen. Wir erkl\u00c3\u00a4ren euch in... Mehr auf Newsslash.com!","og_url":"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/","og_site_name":"Newsslash","article_published_time":"2014-12-16T23:48:00+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","type":"image\/jpeg"}],"author":"Christina B","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Christina B","Est. reading time":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/#article","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/"},"author":{"name":"Christina B","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/d091f5c44e30328c391ba075ee1b88d3"},"headline":"Instagram Anleitung: Ein Guide mit Tipps und Tricks zur App","datePublished":"2014-12-16T23:48:00+00:00","mainEntityOfPage":{"@id":"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/"},"wordCount":2610,"commentCount":0,"publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"image":{"@id":"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/","url":"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/","name":"Instagram Anleitung: Ein Guide mit Tipps und Tricks zur App - Newsslash","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/#primaryimage"},"image":{"@id":"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","datePublished":"2014-12-16T23:48:00+00:00","breadcrumb":{"@id":"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/#primaryimage","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/NewsSlash-Featured-Image.jpg","width":1280,"height":854},{"@type":"BreadcrumbList","@id":"https:\/\/newsslash.com\/n\/4556-instagram-anleitung-ein-guide-mit-tipps-und-tricks-zur-app\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsslash.com\/n\/"},{"@type":"ListItem","position":2,"name":"Instagram Anleitung: Ein Guide mit Tipps und Tricks zur App"}]},{"@type":"WebSite","@id":"https:\/\/newsslash.com\/n\/#website","url":"https:\/\/newsslash.com\/n\/","name":"Newsslash","description":"Trending News on Movies, Series, OTT, Gaming","publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsslash.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/newsslash.com\/n\/#organization","name":"Newsslash","url":"https:\/\/newsslash.com\/n\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","width":512,"height":512,"caption":"Newsslash"},"image":{"@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/d091f5c44e30328c391ba075ee1b88d3","name":"Christina B","sameAs":["https:\/\/newsslash.com"],"url":"https:\/\/newsslash.com\/n\/author\/christina_b\/"}]}},"_links":{"self":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/6126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/comments?post=6126"}],"version-history":[{"count":0,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/6126\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media\/21974"}],"wp:attachment":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media?parent=6126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}