{"id":6897,"date":"2015-03-30T21:08:00","date_gmt":"2015-03-30T21:08:00","guid":{"rendered":"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/"},"modified":"2015-03-30T21:08:00","modified_gmt":"2015-03-30T21:08:00","slug":"5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen","status":"publish","type":"post","link":"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/","title":{"rendered":"DuckTales: Remastered k\u00c3\u00b6nnte f\u00c3\u00bcr das iPhone erscheinen"},"content":{"rendered":"<p>Schon im Jahr 2013 ver\u00c3\u00b6ffentlichte Disney in Kooperation mit Capcom und WayForward einen DuckTales: Remastered Titel f\u00c3\u00bcr die Konsole und den Computer. Das Spiel rund um den gleichnamigen Cartoon DuckTales, der in den 90ern erschienen ist, bekam von den Spielern durchwegs positive Bewertungen. Jetzt soll der Titel m\u00c3\u00b6glicherweise auch als iPhone-Version erscheinen. Vor einigen Tagen hat Disney \u00c3\u00bcber den Disney Interactive Twitter-Account ein Bild ver\u00c3\u00b6ffentlicht, auf dem zu sehen ist, wie der DuckTales: Remastered-Titel auf einem iPhone gespielt wird. Betitelt wurde das Foto mit den Worten aus dem englischen Intro-Song des Cartoons \u00e2\u20ac\u017eMight solve a mystery, or rewrite history!\u00e2\u20ac\u0153 und zugleich mit dem Hashtag #sneakpeek versehen. DuckTales: Remastered w\u00c3\u00a4re allerdings nicht der erste Titel, der f\u00c3\u00bcr mobile Endger\u00c3\u00a4te erscheint. Bereits 2013 erschien unter dem Namen DuckTales: Scrooge\u00e2\u20ac\u2122s Loot ein Free-2-Play Titel f\u00c3\u00bcr Android und iOS-Ger\u00c3\u00a4te. Wann DuckTales: Remastered f\u00c3\u00bcr mobile Endger\u00c3\u00a4te erscheint, ist noch nicht bekannt.<\/p><div class=\"newss-content\" id=\"newss-185369823\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-7733425960004873\" \ndata-ad-slot=\"2582020599\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div class=\"newss-article-1\" id=\"newss-2573660969\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7733425960004873\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Homepage2 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7733425960004873\"\r\n     data-ad-slot=\"2582020599\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Disney gab einen kurzen Einblick auf einen m\u00c3\u00b6glichen DuckTales: Remastered Titel f\u00c3\u00bcr das iPhone. Bereits das 2013 ver\u00c3\u00b6ffentlichte&#8230; Mehr auf Newsslash.com!<\/p>\n","protected":false},"author":4,"featured_media":6883,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-6897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>DuckTales: Remastered k\u00c3\u00b6nnte f\u00c3\u00bcr das iPhone erscheinen - Newsslash<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DuckTales: Remastered k\u00c3\u00b6nnte f\u00c3\u00bcr das iPhone erscheinen - Newsslash\" \/>\n<meta property=\"og:description\" content=\"Disney gab einen kurzen Einblick auf einen m\u00c3\u00b6glichen DuckTales: Remastered Titel f\u00c3\u00bcr das iPhone. Bereits das 2013 ver\u00c3\u00b6ffentlichte... Mehr auf Newsslash.com!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/\" \/>\n<meta property=\"og:site_name\" content=\"Newsslash\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-30T21:08:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_5137.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"617\" \/>\n\t<meta property=\"og:image:height\" content=\"349\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christina B\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christina B\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/\"},\"author\":{\"name\":\"Christina B\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/d091f5c44e30328c391ba075ee1b88d3\"},\"headline\":\"DuckTales: Remastered k\u00c3\u00b6nnte f\u00c3\u00bcr das iPhone erscheinen\",\"datePublished\":\"2015-03-30T21:08:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/\"},\"wordCount\":166,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_5137.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/\",\"url\":\"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/\",\"name\":\"DuckTales: Remastered k\u00c3\u00b6nnte f\u00c3\u00bcr das iPhone erscheinen - Newsslash\",\"isPartOf\":{\"@id\":\"https:\/\/newsslash.com\/n\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_5137.jpg\",\"datePublished\":\"2015-03-30T21:08:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/#primaryimage\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_5137.jpg\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_5137.jpg\",\"width\":617,\"height\":349},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsslash.com\/n\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DuckTales: Remastered k\u00c3\u00b6nnte f\u00c3\u00bcr das iPhone erscheinen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsslash.com\/n\/#website\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"name\":\"Newsslash\",\"description\":\"Trending News on Movies, Series, OTT, Gaming\",\"publisher\":{\"@id\":\"https:\/\/newsslash.com\/n\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsslash.com\/n\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsslash.com\/n\/#organization\",\"name\":\"Newsslash\",\"url\":\"https:\/\/newsslash.com\/n\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"contentUrl\":\"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png\",\"width\":512,\"height\":512,\"caption\":\"Newsslash\"},\"image\":{\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/newsslash.com\/n\/#\/schema\/person\/d091f5c44e30328c391ba075ee1b88d3\",\"name\":\"Christina B\",\"sameAs\":[\"https:\/\/newsslash.com\"],\"url\":\"https:\/\/newsslash.com\/n\/author\/christina_b\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DuckTales: Remastered k\u00c3\u00b6nnte f\u00c3\u00bcr das iPhone erscheinen - Newsslash","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"DuckTales: Remastered k\u00c3\u00b6nnte f\u00c3\u00bcr das iPhone erscheinen - Newsslash","og_description":"Disney gab einen kurzen Einblick auf einen m\u00c3\u00b6glichen DuckTales: Remastered Titel f\u00c3\u00bcr das iPhone. Bereits das 2013 ver\u00c3\u00b6ffentlichte... Mehr auf Newsslash.com!","og_url":"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/","og_site_name":"Newsslash","article_published_time":"2015-03-30T21:08:00+00:00","og_image":[{"width":617,"height":349,"url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_5137.jpg","type":"image\/jpeg"}],"author":"Christina B","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Christina B","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/#article","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/"},"author":{"name":"Christina B","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/d091f5c44e30328c391ba075ee1b88d3"},"headline":"DuckTales: Remastered k\u00c3\u00b6nnte f\u00c3\u00bcr das iPhone erscheinen","datePublished":"2015-03-30T21:08:00+00:00","mainEntityOfPage":{"@id":"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/"},"wordCount":166,"commentCount":0,"publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"image":{"@id":"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_5137.jpg","articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/","url":"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/","name":"DuckTales: Remastered k\u00c3\u00b6nnte f\u00c3\u00bcr das iPhone erscheinen - Newsslash","isPartOf":{"@id":"https:\/\/newsslash.com\/n\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/#primaryimage"},"image":{"@id":"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/#primaryimage"},"thumbnailUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_5137.jpg","datePublished":"2015-03-30T21:08:00+00:00","breadcrumb":{"@id":"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/#primaryimage","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_5137.jpg","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/teaser_img_5137.jpg","width":617,"height":349},{"@type":"BreadcrumbList","@id":"https:\/\/newsslash.com\/n\/5137-ducktales-remastered-koennte-fuer-das-iphone-erscheinen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsslash.com\/n\/"},{"@type":"ListItem","position":2,"name":"DuckTales: Remastered k\u00c3\u00b6nnte f\u00c3\u00bcr das iPhone erscheinen"}]},{"@type":"WebSite","@id":"https:\/\/newsslash.com\/n\/#website","url":"https:\/\/newsslash.com\/n\/","name":"Newsslash","description":"Trending News on Movies, Series, OTT, Gaming","publisher":{"@id":"https:\/\/newsslash.com\/n\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsslash.com\/n\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/newsslash.com\/n\/#organization","name":"Newsslash","url":"https:\/\/newsslash.com\/n\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/","url":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","contentUrl":"https:\/\/newsslash.com\/n\/wp-content\/uploads\/2025\/04\/cropped-Newsslash-logo-Fevicon.png","width":512,"height":512,"caption":"Newsslash"},"image":{"@id":"https:\/\/newsslash.com\/n\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/newsslash.com\/n\/#\/schema\/person\/d091f5c44e30328c391ba075ee1b88d3","name":"Christina B","sameAs":["https:\/\/newsslash.com"],"url":"https:\/\/newsslash.com\/n\/author\/christina_b\/"}]}},"_links":{"self":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/6897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/comments?post=6897"}],"version-history":[{"count":0,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/posts\/6897\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media\/6883"}],"wp:attachment":[{"href":"https:\/\/newsslash.com\/n\/wp-json\/wp\/v2\/media?parent=6897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}